{"id":7302,"date":"2026-05-28T13:57:55","date_gmt":"2026-05-28T19:57:55","guid":{"rendered":"https:\/\/grupohoymexico.com\/tlaxcala\/uncategorized\/enrique-inzunza-pide-licencia-tras-un-mes-de-ser-acusado-como-narcopolitico\/"},"modified":"2026-05-28T13:57:55","modified_gmt":"2026-05-28T19:57:55","slug":"enrique-inzunza-pide-licencia-tras-un-mes-de-ser-acusado-como-narcopolitico","status":"publish","type":"post","link":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/enrique-inzunza-pide-licencia-tras-un-mes-de-ser-acusado-como-narcopolitico\/","title":{"rendered":"Enrique Inzunza pide licencia tras un mes de ser acusado como &#8216;narcopol\u00edtico&#8217;"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Enrique Inzunza C\u00e1zarez<\/strong> solicit\u00f3 licencia a su cargo en el <strong>Senado de la Rep\u00fablica<\/strong>. El movimiento surgi\u00f3 a un mes de que autoridades de Estados Unidos lo se\u00f1alaran por presuntos v\u00ednculos con integrantes del <strong>C\u00e1rtel de Sinaloa.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La decisi\u00f3n ocurri\u00f3 en medio de cuestionamientos por sus ausencias p\u00fablicas y legislativas desde que se difundieron las acusaciones el pasado 29 de abril de 2026. Durante ese periodo, el morenista dej\u00f3 de acudir a su oficina y redujo su actividad p\u00fablica a mensajes en redes sociales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>TAMBI\u00c9N LEE<\/strong>. <a href=\"https:\/\/grupohoymexico.com\/2026\/05\/28\/clara-brugada-ha-dado-mas-de-250-mdp-a-la-empresa-que-pinta-de-morado-la-cdmx\/\" target=\"_blank\" rel=\"noreferrer noopener\">Clara Brugada ha dado m\u00e1s de 250 mdp a la empresa que pinta de morado la CDMX<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El senador de Morena confirm\u00f3 su separaci\u00f3n temporal del cargo mediante un posicionamiento difundido desde la CDMX, donde acudi\u00f3 a la sesi\u00f3n extraordinaria convocada en el Senado para este jueves y viernes. Sin embargo, el legislador decidi\u00f3 no permanecer en la discusi\u00f3n parlamentaria y dej\u00f3 su lugar al <strong>suplente Omar Alejandro L\u00f3pez Campos<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-enrique-inzunza-pide-licencia-tras-un-mes-de-ser-acusado-como-narcopolitico\">Enrique Inzunza pide licencia tras un mes de ser acusado como &#8216;narcopol\u00edtico&#8217;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El senador asegur\u00f3 que la licencia no respondi\u00f3 a las acusaciones en su contra, sino a lo que calific\u00f3 como una \u201cembestida medi\u00e1tica\u201d impulsada por \u201cpersoneros y medios de la derecha\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSeguir\u00e9 las reuniones de comisiones y la del Pleno, apoyando a mi grupo parlamentario, Morena, con opiniones y argumentos a favor de los dict\u00e1menes que son materia de la deliberaci\u00f3n\u201d, escribi\u00f3 en redes sociales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las acusaciones contra el morenista generaron tensi\u00f3n dentro de la bancada oficialista. Legisladores como Ad\u00e1n Augusto L\u00f3pez Hern\u00e1ndez y Gerardo Fern\u00e1ndez Noro\u00f1a evitaron pronunciarse p\u00fablicamente sobre el caso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>TAMBI\u00c9N LEE<\/strong>. <a href=\"https:\/\/grupohoymexico.com\/2026\/05\/28\/aprueban-reforma-que-permite-a-la-4t-anular-elecciones-por-intervencion-extranjera\/\" target=\"_blank\" rel=\"noreferrer noopener\">Aprueban reforma que permite a la 4T anular elecciones por \u2018intervenci\u00f3n extranjera\u2019<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde que se revelaron los se\u00f1alamientos, Inzunza permaneci\u00f3 alejado de la actividad p\u00fablica. Uno de los pocos encuentros que trascendieron fue una reuni\u00f3n con el exgobernador de Chihuahua, Javier Corral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con la salida temporal de Enrique Inzunza, el Senado qued\u00f3 en manos de su suplente, Omar Alejandro L\u00f3pez Campos, quien actualmente se desempe\u00f1aba como secretario de Bienestar y Desarrollo Sustentable del gobierno de Sinaloa.<\/p>\n","protected":false},"excerpt":{"rendered":"Enrique Inzunza C\u00e1zarez solicit\u00f3 licencia a su cargo en el Senado de la Rep\u00fablica. El movimiento surgi\u00f3 a&hellip;","protected":false},"author":15,"featured_media":7303,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[175],"tags":[3006,3193,1112],"class_list":["post-7302","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacional","tag-enrique-inzunza","tag-narcopolitico","tag-ruben-rocha-moya","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Enrique Inzunza pide licencia tras un mes de ser acusado como &#039;narcopol\u00edtico&#039; - Tlaxcala Hoy<\/title>\n<meta name=\"description\" content=\"Enrique Inzunza solicit\u00f3 licencia a su cargo en el Senado de la Rep\u00fablica a un mes de que EEUU lo se\u00f1alaran como &#039;narcopol\u00edtico&#039;.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/enrique-inzunza-pide-licencia-tras-un-mes-de-ser-acusado-como-narcopolitico\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Enrique Inzunza pide licencia tras un mes de ser acusado como &#039;narcopol\u00edtico&#039;\" \/>\n<meta property=\"og:description\" content=\"Enrique Inzunza solicit\u00f3 licencia a su cargo en el Senado de la Rep\u00fablica a un mes de que EEUU lo se\u00f1alaran como &#039;narcopol\u00edtico&#039;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/enrique-inzunza-pide-licencia-tras-un-mes-de-ser-acusado-como-narcopolitico\/\" \/>\n<meta property=\"og:site_name\" content=\"Tlaxcala Hoy\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-28T19:57:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2026\/05\/enrique_inzunza_pide_licencia_senado_acusaciones_nexos_narco_cartel_de_sonaloa.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"638\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"nestor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"nestor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/enrique-inzunza-pide-licencia-tras-un-mes-de-ser-acusado-como-narcopolitico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/enrique-inzunza-pide-licencia-tras-un-mes-de-ser-acusado-como-narcopolitico\\\/\"},\"author\":{\"name\":\"nestor\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#\\\/schema\\\/person\\\/8201f3fa49669f346d08e15801e0ebc2\"},\"headline\":\"Enrique Inzunza pide licencia tras un mes de ser acusado como &#8216;narcopol\u00edtico&#8217;\",\"datePublished\":\"2026-05-28T19:57:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/enrique-inzunza-pide-licencia-tras-un-mes-de-ser-acusado-como-narcopolitico\\\/\"},\"wordCount\":381,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/enrique-inzunza-pide-licencia-tras-un-mes-de-ser-acusado-como-narcopolitico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/05\\\/enrique_inzunza_pide_licencia_senado_acusaciones_nexos_narco_cartel_de_sonaloa.png\",\"keywords\":[\"Enrique Inzunza\",\"Narcopol\u00edtico\",\"Rub\u00e9n Rocha Moya\"],\"articleSection\":[\"Nacional\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/enrique-inzunza-pide-licencia-tras-un-mes-de-ser-acusado-como-narcopolitico\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/enrique-inzunza-pide-licencia-tras-un-mes-de-ser-acusado-como-narcopolitico\\\/\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/enrique-inzunza-pide-licencia-tras-un-mes-de-ser-acusado-como-narcopolitico\\\/\",\"name\":\"Enrique Inzunza pide licencia tras un mes de ser acusado como 'narcopol\u00edtico' - Tlaxcala Hoy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/enrique-inzunza-pide-licencia-tras-un-mes-de-ser-acusado-como-narcopolitico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/enrique-inzunza-pide-licencia-tras-un-mes-de-ser-acusado-como-narcopolitico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/05\\\/enrique_inzunza_pide_licencia_senado_acusaciones_nexos_narco_cartel_de_sonaloa.png\",\"datePublished\":\"2026-05-28T19:57:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#\\\/schema\\\/person\\\/8201f3fa49669f346d08e15801e0ebc2\"},\"description\":\"Enrique Inzunza solicit\u00f3 licencia a su cargo en el Senado de la Rep\u00fablica a un mes de que EEUU lo se\u00f1alaran como 'narcopol\u00edtico'.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/enrique-inzunza-pide-licencia-tras-un-mes-de-ser-acusado-como-narcopolitico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/enrique-inzunza-pide-licencia-tras-un-mes-de-ser-acusado-como-narcopolitico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/enrique-inzunza-pide-licencia-tras-un-mes-de-ser-acusado-como-narcopolitico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/05\\\/enrique_inzunza_pide_licencia_senado_acusaciones_nexos_narco_cartel_de_sonaloa.png\",\"contentUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/05\\\/enrique_inzunza_pide_licencia_senado_acusaciones_nexos_narco_cartel_de_sonaloa.png\",\"width\":1200,\"height\":638},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/enrique-inzunza-pide-licencia-tras-un-mes-de-ser-acusado-como-narcopolitico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Enrique Inzunza pide licencia tras un mes de ser acusado como &#8216;narcopol\u00edtico&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#website\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/\",\"name\":\"Tlaxcala Hoy\",\"description\":\"El alma de la naci\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#\\\/schema\\\/person\\\/8201f3fa49669f346d08e15801e0ebc2\",\"name\":\"nestor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g\",\"caption\":\"nestor\"},\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/author\\\/nestor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Enrique Inzunza pide licencia tras un mes de ser acusado como 'narcopol\u00edtico' - Tlaxcala Hoy","description":"Enrique Inzunza solicit\u00f3 licencia a su cargo en el Senado de la Rep\u00fablica a un mes de que EEUU lo se\u00f1alaran como 'narcopol\u00edtico'.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/enrique-inzunza-pide-licencia-tras-un-mes-de-ser-acusado-como-narcopolitico\/","og_locale":"es_MX","og_type":"article","og_title":"Enrique Inzunza pide licencia tras un mes de ser acusado como 'narcopol\u00edtico'","og_description":"Enrique Inzunza solicit\u00f3 licencia a su cargo en el Senado de la Rep\u00fablica a un mes de que EEUU lo se\u00f1alaran como 'narcopol\u00edtico'.","og_url":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/enrique-inzunza-pide-licencia-tras-un-mes-de-ser-acusado-como-narcopolitico\/","og_site_name":"Tlaxcala Hoy","article_published_time":"2026-05-28T19:57:55+00:00","og_image":[{"width":1200,"height":638,"url":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2026\/05\/enrique_inzunza_pide_licencia_senado_acusaciones_nexos_narco_cartel_de_sonaloa.png","type":"image\/png"}],"author":"nestor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"nestor","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/enrique-inzunza-pide-licencia-tras-un-mes-de-ser-acusado-como-narcopolitico\/#article","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/enrique-inzunza-pide-licencia-tras-un-mes-de-ser-acusado-como-narcopolitico\/"},"author":{"name":"nestor","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#\/schema\/person\/8201f3fa49669f346d08e15801e0ebc2"},"headline":"Enrique Inzunza pide licencia tras un mes de ser acusado como &#8216;narcopol\u00edtico&#8217;","datePublished":"2026-05-28T19:57:55+00:00","mainEntityOfPage":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/enrique-inzunza-pide-licencia-tras-un-mes-de-ser-acusado-como-narcopolitico\/"},"wordCount":381,"commentCount":0,"image":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/enrique-inzunza-pide-licencia-tras-un-mes-de-ser-acusado-como-narcopolitico\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2026\/05\/enrique_inzunza_pide_licencia_senado_acusaciones_nexos_narco_cartel_de_sonaloa.png","keywords":["Enrique Inzunza","Narcopol\u00edtico","Rub\u00e9n Rocha Moya"],"articleSection":["Nacional"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/enrique-inzunza-pide-licencia-tras-un-mes-de-ser-acusado-como-narcopolitico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/enrique-inzunza-pide-licencia-tras-un-mes-de-ser-acusado-como-narcopolitico\/","url":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/enrique-inzunza-pide-licencia-tras-un-mes-de-ser-acusado-como-narcopolitico\/","name":"Enrique Inzunza pide licencia tras un mes de ser acusado como 'narcopol\u00edtico' - Tlaxcala Hoy","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#website"},"primaryImageOfPage":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/enrique-inzunza-pide-licencia-tras-un-mes-de-ser-acusado-como-narcopolitico\/#primaryimage"},"image":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/enrique-inzunza-pide-licencia-tras-un-mes-de-ser-acusado-como-narcopolitico\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2026\/05\/enrique_inzunza_pide_licencia_senado_acusaciones_nexos_narco_cartel_de_sonaloa.png","datePublished":"2026-05-28T19:57:55+00:00","author":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#\/schema\/person\/8201f3fa49669f346d08e15801e0ebc2"},"description":"Enrique Inzunza solicit\u00f3 licencia a su cargo en el Senado de la Rep\u00fablica a un mes de que EEUU lo se\u00f1alaran como 'narcopol\u00edtico'.","breadcrumb":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/enrique-inzunza-pide-licencia-tras-un-mes-de-ser-acusado-como-narcopolitico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/enrique-inzunza-pide-licencia-tras-un-mes-de-ser-acusado-como-narcopolitico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/enrique-inzunza-pide-licencia-tras-un-mes-de-ser-acusado-como-narcopolitico\/#primaryimage","url":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2026\/05\/enrique_inzunza_pide_licencia_senado_acusaciones_nexos_narco_cartel_de_sonaloa.png","contentUrl":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2026\/05\/enrique_inzunza_pide_licencia_senado_acusaciones_nexos_narco_cartel_de_sonaloa.png","width":1200,"height":638},{"@type":"BreadcrumbList","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/enrique-inzunza-pide-licencia-tras-un-mes-de-ser-acusado-como-narcopolitico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/grupohoymexico.com\/tlaxcala\/"},{"@type":"ListItem","position":2,"name":"Enrique Inzunza pide licencia tras un mes de ser acusado como &#8216;narcopol\u00edtico&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#website","url":"https:\/\/grupohoymexico.com\/tlaxcala\/","name":"Tlaxcala Hoy","description":"El alma de la naci\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/grupohoymexico.com\/tlaxcala\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#\/schema\/person\/8201f3fa49669f346d08e15801e0ebc2","name":"nestor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g","caption":"nestor"},"url":"https:\/\/grupohoymexico.com\/tlaxcala\/author\/nestor\/"}]}},"_links":{"self":[{"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/posts\/7302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/comments?post=7302"}],"version-history":[{"count":0,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/posts\/7302\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/media\/7303"}],"wp:attachment":[{"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/media?parent=7302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/categories?post=7302"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/tags?post=7302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}