{"id":7143,"date":"2026-05-12T13:13:55","date_gmt":"2026-05-12T19:13:55","guid":{"rendered":"https:\/\/grupohoymexico.com\/tlaxcala\/uncategorized\/ariadna-montiel-convoca-a-megamarcha-contra-maru-campos-mientras-morena-desaparece-a-rocha-moya\/"},"modified":"2026-05-12T13:13:57","modified_gmt":"2026-05-12T19:13:57","slug":"ariadna-montiel-convoca-a-megamarcha-contra-maru-campos-mientras-morena-desaparece-a-rocha-moya","status":"publish","type":"post","link":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/ariadna-montiel-convoca-a-megamarcha-contra-maru-campos-mientras-morena-desaparece-a-rocha-moya\/","title":{"rendered":"Ariadna Montiel convoca a megamarcha contra Maru Campos mientras Morena desaparece a Rocha Moya"},"content":{"rendered":"\n<p><strong>Ariadna Montiel <\/strong>convoc\u00f3 a simpatizantes de <strong>Morena<\/strong> a una megamarcha contra <strong>Maru Campos<\/strong>, mientras que el partido y el gobierno federal <strong>protege y desaparece a Rub\u00e9n Rocha Moya<\/strong>. Fue en un encuentro con militantes del partido pol\u00edtico donde pidi\u00f3 que asistan a la protesta en contra de la <strong>gobernadora del PAN<\/strong>.<\/p>\n\n\n\n<p>Se trata de una nueva estrategia del partido oficial contra la gobernadora, luego que permiti\u00f3 el ingreso de agentes de la CIA para el desmantelamiento de un narcolaboratorio en la entidad. Debido a esta acci\u00f3n es que la mandataria estatal es v\u00edctima de acoso pol\u00edtico tanto por Movimiento Regeneraci\u00f3n Nacional como por la misma presidenta Claudia Sheinbaum.<\/p>\n\n\n\n<p><strong>TAMBI\u00c9N LEE:<\/strong> <a href=\"https:\/\/grupohoymexico.com\/2026\/05\/12\/violencia-en-guerrero-localizan-10-cuerpos-en-chilapa-y-olinala-atribuidas-al-grupo-criminal-de-los-ardillos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Violencia en Guerrero: localizan 10 cuerpos en Chilapa y Olinal\u00e1 atribuidas al grupo criminal de Los Ardillos<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-ariadna-montiel-convoca-a-megamarcha-contra-maru-campos-mientras-morena-desaparece-a-rocha-moya\">Ariadna Montiel convoca a megamarcha contra Maru Campos mientras Morena desaparece a Rocha Moya<\/h2>\n\n\n\n<p>La dirigente nacional del partido oficial convoc\u00f3 a la ciudadan\u00eda a que asista a la <strong>Glorieta Pancho Villa en Chihuahua el pr\u00f3ximo s\u00e1bado 16 de mayo a las 16:00 horas<\/strong>. La intenci\u00f3n es promover el desafuero de la gobernadora de la oposici\u00f3n.<\/p>\n\n\n\n<p>La megamarcha a la que convoc\u00f3 <strong>Ariadna Montiel<\/strong> no es el primer ataque que realiza <strong>Morena<\/strong> contra <strong>Maru Campos<\/strong>, cuyo caso qued\u00f3 opacado por los se\u00f1alamientos contra <strong>Rub\u00e9n Rocha Moya<\/strong> por presuntos v\u00ednculos con el <strong>C\u00e1rtel de Sinaloa<\/strong>.<\/p>\n\n\n\n<p><strong>TAMBI\u00c9N LEE:<\/strong> <a href=\"https:\/\/grupohoymexico.com\/2026\/05\/12\/trump-iran-bloqueo-naval-ormuz\/\" target=\"_blank\" rel=\"noreferrer noopener\">Trump endurece postura con Ir\u00e1n por bloqueo naval en Ormuz<\/a><\/p>\n\n\n\n<p>El partido oficial recibe acusaciones en su contra porque utiliza el caso de Chihuahua como un distractor de los se\u00f1alamientos contra Rocha Moya, de quien insisten en su inocencia pese a la carencia de pruebas. Adem\u00e1s que apuestan por su protecci\u00f3n en medio de una intenci\u00f3n por su extradici\u00f3n a EEUU. Por eso mismo es que se le asignaron elementos de la Marina, Guardia Nacional y polic\u00eda estatal para su protecci\u00f3n.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"Ariadna Montiel convoc\u00f3 a simpatizantes de Morena a una megamarcha contra Maru Campos, mientras que el partido y&hellip;","protected":false},"author":15,"featured_media":7144,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[175,2162],"tags":[3093,3002,348,1112],"class_list":{"0":"post-7143","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nacional","8":"category-politica","9":"tag-ariadna-montiel","10":"tag-maru-campos","11":"tag-morena","12":"tag-ruben-rocha-moya","13":"cs-entry","14":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.7 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ariadna Montiel convoca a megamarcha contra Maru Campos mientras Morena desaparece a Rocha Moya - Tlaxcala Hoy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/grupohoymexico.com\/tlaxcala\/uncategorized\/ariadna-montiel-convoca-a-megamarcha-contra-maru-campos-mientras-morena-desaparece-a-rocha-moya\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ariadna Montiel convoca a megamarcha contra Maru Campos mientras Morena desaparece a Rocha Moya\" \/>\n<meta property=\"og:description\" content=\"Ariadna Montiel convoc\u00f3 a simpatizantes de Morena a una megamarcha contra Maru Campos, mientras que el partido y&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/grupohoymexico.com\/tlaxcala\/uncategorized\/ariadna-montiel-convoca-a-megamarcha-contra-maru-campos-mientras-morena-desaparece-a-rocha-moya\/\" \/>\n<meta property=\"og:site_name\" content=\"Tlaxcala Hoy\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-12T19:13:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T19:13:57+00:00\" \/>\n<meta name=\"author\" content=\"nestor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"nestor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/uncategorized\\\/ariadna-montiel-convoca-a-megamarcha-contra-maru-campos-mientras-morena-desaparece-a-rocha-moya\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/uncategorized\\\/ariadna-montiel-convoca-a-megamarcha-contra-maru-campos-mientras-morena-desaparece-a-rocha-moya\\\/\"},\"author\":{\"name\":\"nestor\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#\\\/schema\\\/person\\\/8201f3fa49669f346d08e15801e0ebc2\"},\"headline\":\"Ariadna Montiel convoca a megamarcha contra Maru Campos mientras Morena desaparece a Rocha Moya\",\"datePublished\":\"2026-05-12T19:13:55+00:00\",\"dateModified\":\"2026-05-12T19:13:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/uncategorized\\\/ariadna-montiel-convoca-a-megamarcha-contra-maru-campos-mientras-morena-desaparece-a-rocha-moya\\\/\"},\"wordCount\":340,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/uncategorized\\\/ariadna-montiel-convoca-a-megamarcha-contra-maru-campos-mientras-morena-desaparece-a-rocha-moya\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/05\\\/ariadna_montiel_megamarcha_maru_campos_chihuahua_morena_ruben_rocha_moya.png\",\"keywords\":[\"Ariadna Montiel\",\"Maru Campos\",\"Morena\",\"Rub\u00e9n Rocha Moya\"],\"articleSection\":[\"Nacional\",\"Pol\u00edtica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/uncategorized\\\/ariadna-montiel-convoca-a-megamarcha-contra-maru-campos-mientras-morena-desaparece-a-rocha-moya\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/uncategorized\\\/ariadna-montiel-convoca-a-megamarcha-contra-maru-campos-mientras-morena-desaparece-a-rocha-moya\\\/\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/uncategorized\\\/ariadna-montiel-convoca-a-megamarcha-contra-maru-campos-mientras-morena-desaparece-a-rocha-moya\\\/\",\"name\":\"Ariadna Montiel convoca a megamarcha contra Maru Campos mientras Morena desaparece a Rocha Moya - Tlaxcala Hoy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/uncategorized\\\/ariadna-montiel-convoca-a-megamarcha-contra-maru-campos-mientras-morena-desaparece-a-rocha-moya\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/uncategorized\\\/ariadna-montiel-convoca-a-megamarcha-contra-maru-campos-mientras-morena-desaparece-a-rocha-moya\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/05\\\/ariadna_montiel_megamarcha_maru_campos_chihuahua_morena_ruben_rocha_moya.png\",\"datePublished\":\"2026-05-12T19:13:55+00:00\",\"dateModified\":\"2026-05-12T19:13:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#\\\/schema\\\/person\\\/8201f3fa49669f346d08e15801e0ebc2\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/uncategorized\\\/ariadna-montiel-convoca-a-megamarcha-contra-maru-campos-mientras-morena-desaparece-a-rocha-moya\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/uncategorized\\\/ariadna-montiel-convoca-a-megamarcha-contra-maru-campos-mientras-morena-desaparece-a-rocha-moya\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/uncategorized\\\/ariadna-montiel-convoca-a-megamarcha-contra-maru-campos-mientras-morena-desaparece-a-rocha-moya\\\/#primaryimage\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/05\\\/ariadna_montiel_megamarcha_maru_campos_chihuahua_morena_ruben_rocha_moya.png\",\"contentUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/05\\\/ariadna_montiel_megamarcha_maru_campos_chihuahua_morena_ruben_rocha_moya.png\",\"width\":1200,\"height\":638},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/uncategorized\\\/ariadna-montiel-convoca-a-megamarcha-contra-maru-campos-mientras-morena-desaparece-a-rocha-moya\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ariadna Montiel convoca a megamarcha contra Maru Campos mientras Morena desaparece a Rocha Moya\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#website\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/\",\"name\":\"Tlaxcala Hoy\",\"description\":\"El alma de la naci\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#\\\/schema\\\/person\\\/8201f3fa49669f346d08e15801e0ebc2\",\"name\":\"nestor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g\",\"caption\":\"nestor\"},\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/author\\\/nestor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ariadna Montiel convoca a megamarcha contra Maru Campos mientras Morena desaparece a Rocha Moya - Tlaxcala Hoy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/grupohoymexico.com\/tlaxcala\/uncategorized\/ariadna-montiel-convoca-a-megamarcha-contra-maru-campos-mientras-morena-desaparece-a-rocha-moya\/","og_locale":"es_MX","og_type":"article","og_title":"Ariadna Montiel convoca a megamarcha contra Maru Campos mientras Morena desaparece a Rocha Moya","og_description":"Ariadna Montiel convoc\u00f3 a simpatizantes de Morena a una megamarcha contra Maru Campos, mientras que el partido y&hellip;","og_url":"https:\/\/grupohoymexico.com\/tlaxcala\/uncategorized\/ariadna-montiel-convoca-a-megamarcha-contra-maru-campos-mientras-morena-desaparece-a-rocha-moya\/","og_site_name":"Tlaxcala Hoy","article_published_time":"2026-05-12T19:13:55+00:00","article_modified_time":"2026-05-12T19:13:57+00:00","author":"nestor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"nestor","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/uncategorized\/ariadna-montiel-convoca-a-megamarcha-contra-maru-campos-mientras-morena-desaparece-a-rocha-moya\/#article","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/uncategorized\/ariadna-montiel-convoca-a-megamarcha-contra-maru-campos-mientras-morena-desaparece-a-rocha-moya\/"},"author":{"name":"nestor","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#\/schema\/person\/8201f3fa49669f346d08e15801e0ebc2"},"headline":"Ariadna Montiel convoca a megamarcha contra Maru Campos mientras Morena desaparece a Rocha Moya","datePublished":"2026-05-12T19:13:55+00:00","dateModified":"2026-05-12T19:13:57+00:00","mainEntityOfPage":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/uncategorized\/ariadna-montiel-convoca-a-megamarcha-contra-maru-campos-mientras-morena-desaparece-a-rocha-moya\/"},"wordCount":340,"commentCount":0,"image":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/uncategorized\/ariadna-montiel-convoca-a-megamarcha-contra-maru-campos-mientras-morena-desaparece-a-rocha-moya\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2026\/05\/ariadna_montiel_megamarcha_maru_campos_chihuahua_morena_ruben_rocha_moya.png","keywords":["Ariadna Montiel","Maru Campos","Morena","Rub\u00e9n Rocha Moya"],"articleSection":["Nacional","Pol\u00edtica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/grupohoymexico.com\/tlaxcala\/uncategorized\/ariadna-montiel-convoca-a-megamarcha-contra-maru-campos-mientras-morena-desaparece-a-rocha-moya\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/uncategorized\/ariadna-montiel-convoca-a-megamarcha-contra-maru-campos-mientras-morena-desaparece-a-rocha-moya\/","url":"https:\/\/grupohoymexico.com\/tlaxcala\/uncategorized\/ariadna-montiel-convoca-a-megamarcha-contra-maru-campos-mientras-morena-desaparece-a-rocha-moya\/","name":"Ariadna Montiel convoca a megamarcha contra Maru Campos mientras Morena desaparece a Rocha Moya - Tlaxcala Hoy","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#website"},"primaryImageOfPage":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/uncategorized\/ariadna-montiel-convoca-a-megamarcha-contra-maru-campos-mientras-morena-desaparece-a-rocha-moya\/#primaryimage"},"image":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/uncategorized\/ariadna-montiel-convoca-a-megamarcha-contra-maru-campos-mientras-morena-desaparece-a-rocha-moya\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2026\/05\/ariadna_montiel_megamarcha_maru_campos_chihuahua_morena_ruben_rocha_moya.png","datePublished":"2026-05-12T19:13:55+00:00","dateModified":"2026-05-12T19:13:57+00:00","author":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#\/schema\/person\/8201f3fa49669f346d08e15801e0ebc2"},"breadcrumb":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/uncategorized\/ariadna-montiel-convoca-a-megamarcha-contra-maru-campos-mientras-morena-desaparece-a-rocha-moya\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/grupohoymexico.com\/tlaxcala\/uncategorized\/ariadna-montiel-convoca-a-megamarcha-contra-maru-campos-mientras-morena-desaparece-a-rocha-moya\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/uncategorized\/ariadna-montiel-convoca-a-megamarcha-contra-maru-campos-mientras-morena-desaparece-a-rocha-moya\/#primaryimage","url":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2026\/05\/ariadna_montiel_megamarcha_maru_campos_chihuahua_morena_ruben_rocha_moya.png","contentUrl":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2026\/05\/ariadna_montiel_megamarcha_maru_campos_chihuahua_morena_ruben_rocha_moya.png","width":1200,"height":638},{"@type":"BreadcrumbList","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/uncategorized\/ariadna-montiel-convoca-a-megamarcha-contra-maru-campos-mientras-morena-desaparece-a-rocha-moya\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/grupohoymexico.com\/tlaxcala\/"},{"@type":"ListItem","position":2,"name":"Ariadna Montiel convoca a megamarcha contra Maru Campos mientras Morena desaparece a Rocha Moya"}]},{"@type":"WebSite","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#website","url":"https:\/\/grupohoymexico.com\/tlaxcala\/","name":"Tlaxcala Hoy","description":"El alma de la naci\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/grupohoymexico.com\/tlaxcala\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#\/schema\/person\/8201f3fa49669f346d08e15801e0ebc2","name":"nestor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g","caption":"nestor"},"url":"https:\/\/grupohoymexico.com\/tlaxcala\/author\/nestor\/"}]}},"_links":{"self":[{"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/posts\/7143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/comments?post=7143"}],"version-history":[{"count":0,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/posts\/7143\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/media\/7144"}],"wp:attachment":[{"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/media?parent=7143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/categories?post=7143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/tags?post=7143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}