{"id":7103,"date":"2026-05-11T09:56:50","date_gmt":"2026-05-11T15:56:50","guid":{"rendered":"https:\/\/grupohoymexico.com\/tlaxcala\/uncategorized\/madres-buscadoras-protestan-en-7-estados-este-10-de-mayo-para-exigir-justicia-y-localizar-a-desaparecidos\/"},"modified":"2026-05-11T09:56:52","modified_gmt":"2026-05-11T15:56:52","slug":"madres-buscadoras-protestan-en-7-estados-este-10-de-mayo-para-exigir-justicia-y-localizar-a-desaparecidos","status":"publish","type":"post","link":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/madres-buscadoras-protestan-en-7-estados-este-10-de-mayo-para-exigir-justicia-y-localizar-a-desaparecidos\/","title":{"rendered":"Madres Buscadoras protestan en 7 estados este 10 de mayo para exigir justicia y localizar a desaparecidos"},"content":{"rendered":"\n<p><strong>Miles de familiares de personas desaparecidas<\/strong> volvieron a salir a las calles en distintos estados del pa\u00eds durante el <strong>D\u00eda de las Madres<\/strong> para exigir <strong>justicia, b\u00fasqueda efectiva y localizaci\u00f3n de sus seres queridos<\/strong>.<\/p>\n\n\n\n<p>Bajo consignas como <strong><em>&#8220;10 de mayo no es fiesta, es lucha y protesta&#8221;<\/em><\/strong>, madres buscadoras realizaron movilizaciones en <strong>Jalisco, Guerrero, Baja California, Morelos, Michoac\u00e1n, Nayarit y Tamaulipas<\/strong> para recordar que, mientras miles de familias sigan buscando desaparecidos, no hay nada que celebrar.<\/p>\n\n\n\n<p>Una de las voces que m\u00e1s impact\u00f3 durante las protestas fue la de la madre de <strong>H\u00e9ctor Adri\u00e1n \u00c1guila Corona<\/strong>, joven desaparecido el 21 de julio de 2023 en el municipio de San Pedro Tlaquepaque, quien asegur\u00f3:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><strong>&#8220;Tengo miedo, porque ser madre buscadora es buscar la muerte&#8221;.<\/strong><\/p>\n<\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-sigue-nuestras-cuentas-en-facebook-e-instagram-para-mantenerte-informado-con-las-noticias-mas-relevantes\"><strong>Sigue nuestras cuentas en Facebook e Instagram para mantenerte informado con las noticias m\u00e1s relevantes.<\/strong><\/h3>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-madres-buscadoras-denuncian-desgaste-emocional-y-abandono-institucional\"><strong>Madres buscadoras denuncian desgaste emocional y abandono institucional<\/strong><\/h2>\n\n\n\n<p>Durante la <strong>marcha en Guadalajara<\/strong>, familiares de personas desaparecidas se\u00f1alaron que la participaci\u00f3n fue menor que en otros a\u00f1os debido al <strong>desgaste f\u00edsico y emocional<\/strong> provocado por a\u00f1os de b\u00fasqueda.<\/p>\n\n\n\n<p>Madres buscadoras denunciaron sufrir:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Estr\u00e9s.<\/li>\n\n\n\n<li>Depresi\u00f3n.<\/li>\n\n\n\n<li>Ansiedad.<\/li>\n\n\n\n<li>Miedo constante.<\/li>\n\n\n\n<li>Revictimizaci\u00f3n institucional.<\/li>\n<\/ul>\n\n\n\n<p>Muchas aseguraron sentirse abandonadas por las autoridades y obligadas a realizar labores de b\u00fasqueda por cuenta propia.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><strong><em>&#8220;\u00bfQu\u00e9 m\u00e1s podemos perder si ya nos mataron en vida?&#8221;<\/em><\/strong>, expres\u00f3 una madre durante la protesta.<\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-acapulco-madres-piden-apoyo-internacional-para-atender-desapariciones\"><strong>Acapulco: madres piden apoyo internacional para atender desapariciones<\/strong><\/h2>\n\n\n\n<p>En <strong>Acapulco<\/strong>, colectivos de b\u00fasqueda realizaron una caminata y encendido de veladoras en el <strong>antimonumento a la Esperanza<\/strong>, ubicado en <strong>playa Tamarindos<\/strong>.<\/p>\n\n\n\n<p>La movilizaci\u00f3n fue convocada por la <strong>Asociaci\u00f3n de Familias de Acapulco<\/strong> en busca de sus desaparecidos, acompa\u00f1ada por el <strong>Colectivo de Madres Igualtecas<\/strong>.<\/p>\n\n\n\n<p>Las participantes pidieron al gobierno federal aplicar est\u00e1ndares internacionales contemplados en la <strong>Convenci\u00f3n contra la Desaparici\u00f3n Forzada<\/strong> y solicitar asistencia t\u00e9cnica especializada para enfrentar la crisis de desapariciones en M\u00e9xico.<\/p>\n\n\n\n<p>Adem\u00e1s, hicieron un llamado directo a <strong>Claudia Sheinbaum Pardo<\/strong> para comprometerse con las madres buscadoras y fortalecer las investigaciones.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-leer-mas-scjn-avala-que-estudiantes-de-educacion-basica-no-reprueben-aunque-deban-hasta-4-materias\"><strong><em>Leer m\u00e1s: <a href=\"https:\/\/grupohoymexico.com\/2026\/05\/09\/scjn-avala-que-estudiantes-de-educacion-basica-no-reprueben-aunque-deban-hasta-4-materias\/\">SCJN avala que estudiantes de educaci\u00f3n b\u00e1sica no reprueben aunque deban hasta 4 materias<\/a><\/em><\/strong><\/h3>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-tijuana-10-de-mayo-no-es-fiesta-es-protesta\"><strong>Tijuana: &#8220;10 de mayo no es fiesta, es protesta&#8221;<\/strong><\/h2>\n\n\n\n<p>En <strong>Tijuana<\/strong>, madres rastreadoras marcharon hacia las instalaciones de la <strong><a href=\"https:\/\/www.fgebc.gob.mx\/\">Fiscal\u00eda General del Estado<\/a><\/strong> para exigir justicia y localizaci\u00f3n de desaparecidos.<\/p>\n\n\n\n<p>La protesta reuni\u00f3 a colectivos como:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Una Naci\u00f3n Buscando T.<\/li>\n\n\n\n<li>Ponte en Nuestras Botas.<\/li>\n\n\n\n<li>Frente Popular Revolucionario.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-colectivos-denuncian-crisis-forense-y-desaparicion-administrativa\"><strong>Colectivos denuncian crisis forense y &#8220;desaparici\u00f3n administrativa&#8221;<\/strong><\/h2>\n\n\n\n<p><strong>Jocelyn P\u00e9rez Valladares<\/strong>, <strong>fundadora del colectivo Ponte en Nuestras Botas<\/strong>, denunci\u00f3 que existe un grave rezago en investigaciones relacionadas con desapariciones en M\u00e9xico.<\/p>\n\n\n\n<p>La activista se\u00f1al\u00f3 la falta de:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Antrop\u00f3logos forenses.<\/li>\n\n\n\n<li>Especialistas en identificaci\u00f3n humana.<\/li>\n\n\n\n<li>Seguimiento institucional.<\/li>\n\n\n\n<li>Recursos para fiscal\u00edas.<\/li>\n<\/ul>\n\n\n\n<p>Tambi\u00e9n acus\u00f3 la existencia de una <strong>&#8220;desaparici\u00f3n administrativa&#8221;<\/strong>, donde cuerpos recuperados no son correctamente identificados ni entregados a sus familias.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><strong><em>&#8220;El Estado los vuelve a desaparecer&#8221;<\/em><\/strong>, reclam\u00f3.<\/p>\n<\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-leer-mas-marina-desmantela-narcolaboratorio-ligado-a-el-mayito-flaco-en-culiacan\"><strong><em>Leer m\u00e1s: <a href=\"https:\/\/grupohoymexico.com\/2026\/05\/09\/marina-desmantela-narcolaboratorio-ligado-a-el-mayito-flaco-en-culiacan\/\">Marina desmantela narcolaboratorio ligado a &#8220;El Mayito Flaco&#8221; en Culiac\u00e1n<\/a><\/em><\/strong><\/h3>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-madres-migrantes-tambien-alzaron-la-voz-en-la-frontera\"><strong>Madres migrantes tambi\u00e9n alzaron la voz en la frontera<\/strong><\/h2>\n\n\n\n<p>En <strong>Tijuana<\/strong>, madres migrantes participaron en una <strong>misa celebrada en Playas de Tijuana<\/strong>, en la <strong>frontera entre M\u00e9xico y Estados Unidos.<\/strong><\/p>\n\n\n\n<p>El acto religioso sirvi\u00f3 para recordar a hijos desaparecidos durante procesos migratorios y exigir mayor atenci\u00f3n a los casos de personas no localizadas en rutas migrantes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-crisis-de-desapariciones-en-mexico-sigue-creciendo\"><strong>Crisis de desapariciones en M\u00e9xico sigue creciendo<\/strong><\/h2>\n\n\n\n<p>La crisis de personas desaparecidas en M\u00e9xico contin\u00faa siendo una de las principales problem\u00e1ticas de derechos humanos del pa\u00eds.<\/p>\n\n\n\n<p>Colectivos y organizaciones civiles se\u00f1alan que miles de familias enfrentan:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Lentitud en investigaciones.<\/li>\n\n\n\n<li>Falta de recursos.<\/li>\n\n\n\n<li>Impunidad.<\/li>\n\n\n\n<li>Ausencia de identificaci\u00f3n forense.<\/li>\n\n\n\n<li>Riesgos durante b\u00fasquedas.<\/li>\n<\/ul>\n\n\n\n<p>Las madres buscadoras reiteraron que seguir\u00e1n marchando y buscando hasta encontrar a sus hijos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-no-hay-nada-que-celebrar-madres-convierten-el-10-de-mayo-en-jornada-de-protesta\"><strong>&#8220;No hay nada que celebrar&#8221;: madres convierten el 10 de mayo en jornada de protesta<\/strong><\/h2>\n\n\n\n<p>Mientras gran parte del pa\u00eds celebraba el <strong>D\u00eda de las Madres<\/strong>, cientos de mujeres transformaron la fecha en una jornada nacional de memoria, lucha y exigencia de justicia.<\/p>\n\n\n\n<p>En estados como <strong>Morelos, Michoac\u00e1n, Nayarit y Tamaulipas<\/strong>, madres buscadoras tambi\u00e9n realizaron marchas y protestas para exigir a autoridades federales, estatales y municipales localizar a sus seres queridos desaparecidos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-unete-a-nuestro-canal-de-whatsapp\"><strong><a href=\"https:\/\/whatsapp.com\/channel\/0029Vaylt1XG3R3gm4Nsgp2m\">\u00danete a nuestro canal de WhatsApp<\/a><\/strong><\/h2>\n","protected":false},"excerpt":{"rendered":"Miles de familiares de personas desaparecidas volvieron a salir a las calles en distintos estados del pa\u00eds durante&hellip;","protected":false},"author":5,"featured_media":7104,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[175],"tags":[2422,3081,1698,1058,2752,2747,871,2993,3082,2991],"class_list":{"0":"post-7103","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nacional","8":"tag-baja-california","9":"tag-dia-de-las-madres","10":"tag-guerrero","11":"tag-jalisco","12":"tag-madres-buscadoras","13":"tag-michoacan","14":"tag-morelos","15":"tag-nayarit","16":"tag-personas-desaparecidas","17":"tag-tamaulipas","18":"cs-entry","19":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.7 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Madres Buscadoras protestan en 7 estados este 10 de mayo para exigir justicia y localizar a desaparecidos - Tlaxcala Hoy<\/title>\n<meta name=\"description\" content=\"Este 2026, madres buscadoras convirtieron el D\u00eda de las Madres en protesta nacional por las personas desaparecidas en M\u00e9xico.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/madres-buscadoras-protestan-en-7-estados-este-10-de-mayo-para-exigir-justicia-y-localizar-a-desaparecidos\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Madres Buscadoras protestan en 7 estados este 10 de mayo para exigir justicia y localizar a desaparecidos\" \/>\n<meta property=\"og:description\" content=\"Este 2026, madres buscadoras convirtieron el D\u00eda de las Madres en protesta nacional por las personas desaparecidas en M\u00e9xico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/madres-buscadoras-protestan-en-7-estados-este-10-de-mayo-para-exigir-justicia-y-localizar-a-desaparecidos\/\" \/>\n<meta property=\"og:site_name\" content=\"Tlaxcala Hoy\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-11T15:56:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T15:56:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2026\/05\/Madres-buscadoras.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"638\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jair\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"jair\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/madres-buscadoras-protestan-en-7-estados-este-10-de-mayo-para-exigir-justicia-y-localizar-a-desaparecidos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/madres-buscadoras-protestan-en-7-estados-este-10-de-mayo-para-exigir-justicia-y-localizar-a-desaparecidos\\\/\"},\"author\":{\"name\":\"jair\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#\\\/schema\\\/person\\\/98e2425fe99fbbdf486895b69dab3c3d\"},\"headline\":\"Madres Buscadoras protestan en 7 estados este 10 de mayo para exigir justicia y localizar a desaparecidos\",\"datePublished\":\"2026-05-11T15:56:50+00:00\",\"dateModified\":\"2026-05-11T15:56:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/madres-buscadoras-protestan-en-7-estados-este-10-de-mayo-para-exigir-justicia-y-localizar-a-desaparecidos\\\/\"},\"wordCount\":741,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/madres-buscadoras-protestan-en-7-estados-este-10-de-mayo-para-exigir-justicia-y-localizar-a-desaparecidos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/05\\\/Madres-buscadoras.jpg\",\"keywords\":[\"Baja California\",\"D\u00eda de las madres\",\"Guerrero\",\"Jalisco\",\"Madres buscadoras\",\"Michoac\u00e1n\",\"Morelos\",\"Nayarit\",\"Personas desaparecidas\",\"Tamaulipas\"],\"articleSection\":[\"Nacional\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/madres-buscadoras-protestan-en-7-estados-este-10-de-mayo-para-exigir-justicia-y-localizar-a-desaparecidos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/madres-buscadoras-protestan-en-7-estados-este-10-de-mayo-para-exigir-justicia-y-localizar-a-desaparecidos\\\/\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/madres-buscadoras-protestan-en-7-estados-este-10-de-mayo-para-exigir-justicia-y-localizar-a-desaparecidos\\\/\",\"name\":\"Madres Buscadoras protestan en 7 estados este 10 de mayo para exigir justicia y localizar a desaparecidos - Tlaxcala Hoy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/madres-buscadoras-protestan-en-7-estados-este-10-de-mayo-para-exigir-justicia-y-localizar-a-desaparecidos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/madres-buscadoras-protestan-en-7-estados-este-10-de-mayo-para-exigir-justicia-y-localizar-a-desaparecidos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/05\\\/Madres-buscadoras.jpg\",\"datePublished\":\"2026-05-11T15:56:50+00:00\",\"dateModified\":\"2026-05-11T15:56:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#\\\/schema\\\/person\\\/98e2425fe99fbbdf486895b69dab3c3d\"},\"description\":\"Este 2026, madres buscadoras convirtieron el D\u00eda de las Madres en protesta nacional por las personas desaparecidas en M\u00e9xico.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/madres-buscadoras-protestan-en-7-estados-este-10-de-mayo-para-exigir-justicia-y-localizar-a-desaparecidos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/madres-buscadoras-protestan-en-7-estados-este-10-de-mayo-para-exigir-justicia-y-localizar-a-desaparecidos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/madres-buscadoras-protestan-en-7-estados-este-10-de-mayo-para-exigir-justicia-y-localizar-a-desaparecidos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/05\\\/Madres-buscadoras.jpg\",\"contentUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/05\\\/Madres-buscadoras.jpg\",\"width\":1200,\"height\":638,\"caption\":\"Foto: Redes Sociales\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/madres-buscadoras-protestan-en-7-estados-este-10-de-mayo-para-exigir-justicia-y-localizar-a-desaparecidos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Madres Buscadoras protestan en 7 estados este 10 de mayo para exigir justicia y localizar a desaparecidos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#website\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/\",\"name\":\"Tlaxcala Hoy\",\"description\":\"El alma de la naci\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#\\\/schema\\\/person\\\/98e2425fe99fbbdf486895b69dab3c3d\",\"name\":\"jair\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ec205dfb8733a1ce1601942dddb04fc9294fb780c832e3c1ec58faa8e4e64e9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ec205dfb8733a1ce1601942dddb04fc9294fb780c832e3c1ec58faa8e4e64e9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ec205dfb8733a1ce1601942dddb04fc9294fb780c832e3c1ec58faa8e4e64e9b?s=96&d=mm&r=g\",\"caption\":\"jair\"},\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/author\\\/jair\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Madres Buscadoras protestan en 7 estados este 10 de mayo para exigir justicia y localizar a desaparecidos - Tlaxcala Hoy","description":"Este 2026, madres buscadoras convirtieron el D\u00eda de las Madres en protesta nacional por las personas desaparecidas en M\u00e9xico.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/madres-buscadoras-protestan-en-7-estados-este-10-de-mayo-para-exigir-justicia-y-localizar-a-desaparecidos\/","og_locale":"es_MX","og_type":"article","og_title":"Madres Buscadoras protestan en 7 estados este 10 de mayo para exigir justicia y localizar a desaparecidos","og_description":"Este 2026, madres buscadoras convirtieron el D\u00eda de las Madres en protesta nacional por las personas desaparecidas en M\u00e9xico.","og_url":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/madres-buscadoras-protestan-en-7-estados-este-10-de-mayo-para-exigir-justicia-y-localizar-a-desaparecidos\/","og_site_name":"Tlaxcala Hoy","article_published_time":"2026-05-11T15:56:50+00:00","article_modified_time":"2026-05-11T15:56:52+00:00","og_image":[{"width":1200,"height":638,"url":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2026\/05\/Madres-buscadoras.jpg","type":"image\/jpeg"}],"author":"jair","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"jair","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/madres-buscadoras-protestan-en-7-estados-este-10-de-mayo-para-exigir-justicia-y-localizar-a-desaparecidos\/#article","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/madres-buscadoras-protestan-en-7-estados-este-10-de-mayo-para-exigir-justicia-y-localizar-a-desaparecidos\/"},"author":{"name":"jair","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#\/schema\/person\/98e2425fe99fbbdf486895b69dab3c3d"},"headline":"Madres Buscadoras protestan en 7 estados este 10 de mayo para exigir justicia y localizar a desaparecidos","datePublished":"2026-05-11T15:56:50+00:00","dateModified":"2026-05-11T15:56:52+00:00","mainEntityOfPage":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/madres-buscadoras-protestan-en-7-estados-este-10-de-mayo-para-exigir-justicia-y-localizar-a-desaparecidos\/"},"wordCount":741,"commentCount":0,"image":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/madres-buscadoras-protestan-en-7-estados-este-10-de-mayo-para-exigir-justicia-y-localizar-a-desaparecidos\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2026\/05\/Madres-buscadoras.jpg","keywords":["Baja California","D\u00eda de las madres","Guerrero","Jalisco","Madres buscadoras","Michoac\u00e1n","Morelos","Nayarit","Personas desaparecidas","Tamaulipas"],"articleSection":["Nacional"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/madres-buscadoras-protestan-en-7-estados-este-10-de-mayo-para-exigir-justicia-y-localizar-a-desaparecidos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/madres-buscadoras-protestan-en-7-estados-este-10-de-mayo-para-exigir-justicia-y-localizar-a-desaparecidos\/","url":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/madres-buscadoras-protestan-en-7-estados-este-10-de-mayo-para-exigir-justicia-y-localizar-a-desaparecidos\/","name":"Madres Buscadoras protestan en 7 estados este 10 de mayo para exigir justicia y localizar a desaparecidos - Tlaxcala Hoy","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#website"},"primaryImageOfPage":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/madres-buscadoras-protestan-en-7-estados-este-10-de-mayo-para-exigir-justicia-y-localizar-a-desaparecidos\/#primaryimage"},"image":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/madres-buscadoras-protestan-en-7-estados-este-10-de-mayo-para-exigir-justicia-y-localizar-a-desaparecidos\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2026\/05\/Madres-buscadoras.jpg","datePublished":"2026-05-11T15:56:50+00:00","dateModified":"2026-05-11T15:56:52+00:00","author":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#\/schema\/person\/98e2425fe99fbbdf486895b69dab3c3d"},"description":"Este 2026, madres buscadoras convirtieron el D\u00eda de las Madres en protesta nacional por las personas desaparecidas en M\u00e9xico.","breadcrumb":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/madres-buscadoras-protestan-en-7-estados-este-10-de-mayo-para-exigir-justicia-y-localizar-a-desaparecidos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/madres-buscadoras-protestan-en-7-estados-este-10-de-mayo-para-exigir-justicia-y-localizar-a-desaparecidos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/madres-buscadoras-protestan-en-7-estados-este-10-de-mayo-para-exigir-justicia-y-localizar-a-desaparecidos\/#primaryimage","url":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2026\/05\/Madres-buscadoras.jpg","contentUrl":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2026\/05\/Madres-buscadoras.jpg","width":1200,"height":638,"caption":"Foto: Redes Sociales"},{"@type":"BreadcrumbList","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/madres-buscadoras-protestan-en-7-estados-este-10-de-mayo-para-exigir-justicia-y-localizar-a-desaparecidos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/grupohoymexico.com\/tlaxcala\/"},{"@type":"ListItem","position":2,"name":"Madres Buscadoras protestan en 7 estados este 10 de mayo para exigir justicia y localizar a desaparecidos"}]},{"@type":"WebSite","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#website","url":"https:\/\/grupohoymexico.com\/tlaxcala\/","name":"Tlaxcala Hoy","description":"El alma de la naci\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/grupohoymexico.com\/tlaxcala\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#\/schema\/person\/98e2425fe99fbbdf486895b69dab3c3d","name":"jair","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ec205dfb8733a1ce1601942dddb04fc9294fb780c832e3c1ec58faa8e4e64e9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ec205dfb8733a1ce1601942dddb04fc9294fb780c832e3c1ec58faa8e4e64e9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ec205dfb8733a1ce1601942dddb04fc9294fb780c832e3c1ec58faa8e4e64e9b?s=96&d=mm&r=g","caption":"jair"},"url":"https:\/\/grupohoymexico.com\/tlaxcala\/author\/jair\/"}]}},"_links":{"self":[{"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/posts\/7103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/comments?post=7103"}],"version-history":[{"count":0,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/posts\/7103\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/media\/7104"}],"wp:attachment":[{"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/media?parent=7103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/categories?post=7103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/tags?post=7103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}