{"id":6993,"date":"2026-05-07T10:35:42","date_gmt":"2026-05-07T16:35:42","guid":{"rendered":"https:\/\/grupohoymexico.com\/tlaxcala\/uncategorized\/claudia-sheinbaum-interfiere-en-las-elecciones-de-eeuu-a-traves-de-consulados-peter-schweizer\/"},"modified":"2026-05-07T10:35:43","modified_gmt":"2026-05-07T16:35:43","slug":"claudia-sheinbaum-interfiere-en-las-elecciones-de-eeuu-a-traves-de-consulados-peter-schweizer","status":"publish","type":"post","link":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/claudia-sheinbaum-interfiere-en-las-elecciones-de-eeuu-a-traves-de-consulados-peter-schweizer\/","title":{"rendered":"Claudia Sheinbaum interfiere en las elecciones de EEUU a trav\u00e9s de consulados: Peter Schweizer"},"content":{"rendered":"\n<p><strong>Peter Schweizer<\/strong> denunci\u00f3 que <strong>Claudia Sheinbaum<\/strong>, a trav\u00e9s de las embajadas de M\u00e9xico, interfiere en las <strong>elecciones de EEUU<\/strong>. Fue a trav\u00e9s de redes sociales donde realiz\u00f3 su acusaci\u00f3n  contra <strong>el Gobierno Federal<\/strong> y <strong>Morena<\/strong>.<\/p>\n\n\n\n<p>El comentario del escritor y consultor pol\u00edtico, autor de <em>The Invisible Coup<\/em>, uno de cinco #1 de los libros m\u00e1s vendidos en la lista del <em>New York Times<\/em>, gener\u00f3 reacciones en nuestro pa\u00eds. Principalmente desde el lado oficialista, pues personas afines a la 4T dijeron: &#8220;recuperaremos nuestro territorio robado por ustedes, malditos criminales&#8221;. <\/p>\n\n\n\n<p><strong>TAMBI\u00c9N LEE:<\/strong> <a href=\"https:\/\/grupohoymexico.com\/2026\/05\/07\/difunden-video-sexual-grabado-por-enrique-inzunza-para-acosar-a-jueza\/\" target=\"_blank\" rel=\"noreferrer noopener\">Difunden video sexual grabado por Enrique Inzunza para acosar a jueza<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-claudia-sheinbaum-interfiere-en-las-elecciones-de-eeuu-a-traves-de-embajadas-peter-schweizer\">Claudia Sheinbaum interfiere en las elecciones de EEUU a trav\u00e9s de embajadas: Peter Schweizer<\/h2>\n\n\n\n<p>El tambi\u00e9n <strong>presidente del Instituto de Responsabilidad Gubernamental <\/strong>dijo que a trav\u00e9s de los m\u00e1s de 50 consulados que tiene nuestro pa\u00eds en <strong>Estados Unidos<\/strong> es que se llevan a cabo trabajos mediante los cuales se ejecuta una injerencia en la democracia estadounidense.<\/p>\n\n\n\n<p>Su se\u00f1alamiento comenz\u00f3 a partir de una frase que dijo la sucesora de <strong>Andr\u00e9s Manuel L\u00f3pez Obrador<\/strong> en medio de las pol\u00e9micas por el narcotr\u00e1fico. &#8220;La historia nos dice que el pueblo de M\u00e9xico no se equivoca cuando se trata de defender la soberan\u00eda nacional&#8221;, record\u00f3 que dijo la presidenta. <\/p>\n\n\n\n<p><strong>TAMBI\u00c9N LEE:<\/strong> <a href=\"https:\/\/grupohoymexico.com\/2026\/05\/07\/balacera-en-veracruz-deja-4-muertos-tras-enfrentamiento-entre-policias-y-presuntos-secuestradores\/\" target=\"_blank\" rel=\"noreferrer noopener\">Balacera en Veracruz deja 4 muertos tras enfrentamiento entre polic\u00edas y presuntos secuestradores<\/a><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>&#8220;Palabras ricas de una l\u00edder que est\u00e1 interfiriendo en las elecciones estadounidenses a trav\u00e9s de sus m\u00e1s de 50 consulados en EE.UU. y funcionarios del Partido Morena que viven aqu\u00ed&#8221;, agreg\u00f3 sobre una presunta intervenci\u00f3n del gobierno de Sheinbaum en las elecciones de EEUU. <\/p>\n<\/blockquote>\n\n\n\n<p>Las acusaciones de Peter Schweizer cobran eco en medio de la tensi\u00f3n diplom\u00e1tica que hay en la relaci\u00f3n entre los dos pa\u00edses. Esto luego que a consideraci\u00f3n de Donald Trump, el gobierno de M\u00e9xico no enfrenta de forma eficaz a los <strong>c\u00e1rteles de la droga<\/strong>. De acuerdo con su informaci\u00f3n, esto se debe a que varios funcionarios de la 4T tiene v\u00ednculos con organizaciones criminales como el C\u00e1rtel de Sinaloa.<\/p>\n\n\n\n<p>Ante la pol\u00e9mica, la Embajada de M\u00e9xico en EEUU sostuvo que los consulados mexicanos en el extranjero trabajan todos los d\u00edas para asistir a las personas mexicanas en una amplia gama de asuntos. Asegur\u00f3 que las instituciones aseguran que la documentaci\u00f3n tenga todas las actualizaciones y reciban apoyo en caso de ser v\u00edctimas de un delito.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>&#8220;No hay nada pol\u00edtico en el trabajo consular, solo el compromiso de asegurar que los derechos de las personas sean respetados&#8221;, agreg\u00f3.<\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"Peter Schweizer denunci\u00f3 que Claudia Sheinbaum, a trav\u00e9s de las embajadas de M\u00e9xico, interfiere en las elecciones de&hellip;","protected":false},"author":15,"featured_media":6994,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[175],"tags":[234,3052,3053],"class_list":{"0":"post-6993","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nacional","8":"tag-claudia-sheinbaum","9":"tag-elecciones-en-eeuu","10":"tag-peter-schweizer","11":"cs-entry","12":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.7 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Claudia Sheinbaum interfiere en las elecciones de EEUU a trav\u00e9s de consulados: Peter Schweizer - Tlaxcala Hoy<\/title>\n<meta name=\"description\" content=\"El escritor Peter Schweizer acus\u00f3 que el gobierno de Claudia Sheinbaum interviene, a trav\u00e9s de los consulados, las elecciones en EEUU.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/claudia-sheinbaum-interfiere-en-las-elecciones-de-eeuu-a-traves-de-consulados-peter-schweizer\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Claudia Sheinbaum interfiere en las elecciones de EEUU a trav\u00e9s de consulados: Peter Schweizer\" \/>\n<meta property=\"og:description\" content=\"El escritor Peter Schweizer acus\u00f3 que el gobierno de Claudia Sheinbaum interviene, a trav\u00e9s de los consulados, las elecciones en EEUU.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/claudia-sheinbaum-interfiere-en-las-elecciones-de-eeuu-a-traves-de-consulados-peter-schweizer\/\" \/>\n<meta property=\"og:site_name\" content=\"Tlaxcala Hoy\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-07T16:35:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-07T16:35:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2026\/05\/claudia_sheinbaum_interfiere_elecciones_eeuu_embajadas_peter_schweizer.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"638\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"nestor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"nestor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/claudia-sheinbaum-interfiere-en-las-elecciones-de-eeuu-a-traves-de-consulados-peter-schweizer\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/claudia-sheinbaum-interfiere-en-las-elecciones-de-eeuu-a-traves-de-consulados-peter-schweizer\\\/\"},\"author\":{\"name\":\"nestor\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#\\\/schema\\\/person\\\/8201f3fa49669f346d08e15801e0ebc2\"},\"headline\":\"Claudia Sheinbaum interfiere en las elecciones de EEUU a trav\u00e9s de consulados: Peter Schweizer\",\"datePublished\":\"2026-05-07T16:35:42+00:00\",\"dateModified\":\"2026-05-07T16:35:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/claudia-sheinbaum-interfiere-en-las-elecciones-de-eeuu-a-traves-de-consulados-peter-schweizer\\\/\"},\"wordCount\":469,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/claudia-sheinbaum-interfiere-en-las-elecciones-de-eeuu-a-traves-de-consulados-peter-schweizer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/05\\\/claudia_sheinbaum_interfiere_elecciones_eeuu_embajadas_peter_schweizer.png\",\"keywords\":[\"Claudia Sheinbaum\",\"Elecciones en EEUU\",\"Peter Schweizer\"],\"articleSection\":[\"Nacional\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/claudia-sheinbaum-interfiere-en-las-elecciones-de-eeuu-a-traves-de-consulados-peter-schweizer\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/claudia-sheinbaum-interfiere-en-las-elecciones-de-eeuu-a-traves-de-consulados-peter-schweizer\\\/\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/claudia-sheinbaum-interfiere-en-las-elecciones-de-eeuu-a-traves-de-consulados-peter-schweizer\\\/\",\"name\":\"Claudia Sheinbaum interfiere en las elecciones de EEUU a trav\u00e9s de consulados: Peter Schweizer - Tlaxcala Hoy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/claudia-sheinbaum-interfiere-en-las-elecciones-de-eeuu-a-traves-de-consulados-peter-schweizer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/claudia-sheinbaum-interfiere-en-las-elecciones-de-eeuu-a-traves-de-consulados-peter-schweizer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/05\\\/claudia_sheinbaum_interfiere_elecciones_eeuu_embajadas_peter_schweizer.png\",\"datePublished\":\"2026-05-07T16:35:42+00:00\",\"dateModified\":\"2026-05-07T16:35:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#\\\/schema\\\/person\\\/8201f3fa49669f346d08e15801e0ebc2\"},\"description\":\"El escritor Peter Schweizer acus\u00f3 que el gobierno de Claudia Sheinbaum interviene, a trav\u00e9s de los consulados, las elecciones en EEUU.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/claudia-sheinbaum-interfiere-en-las-elecciones-de-eeuu-a-traves-de-consulados-peter-schweizer\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/claudia-sheinbaum-interfiere-en-las-elecciones-de-eeuu-a-traves-de-consulados-peter-schweizer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/claudia-sheinbaum-interfiere-en-las-elecciones-de-eeuu-a-traves-de-consulados-peter-schweizer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/05\\\/claudia_sheinbaum_interfiere_elecciones_eeuu_embajadas_peter_schweizer.png\",\"contentUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/05\\\/claudia_sheinbaum_interfiere_elecciones_eeuu_embajadas_peter_schweizer.png\",\"width\":1200,\"height\":638},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/claudia-sheinbaum-interfiere-en-las-elecciones-de-eeuu-a-traves-de-consulados-peter-schweizer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Claudia Sheinbaum interfiere en las elecciones de EEUU a trav\u00e9s de consulados: Peter Schweizer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#website\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/\",\"name\":\"Tlaxcala Hoy\",\"description\":\"El alma de la naci\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#\\\/schema\\\/person\\\/8201f3fa49669f346d08e15801e0ebc2\",\"name\":\"nestor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g\",\"caption\":\"nestor\"},\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/author\\\/nestor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Claudia Sheinbaum interfiere en las elecciones de EEUU a trav\u00e9s de consulados: Peter Schweizer - Tlaxcala Hoy","description":"El escritor Peter Schweizer acus\u00f3 que el gobierno de Claudia Sheinbaum interviene, a trav\u00e9s de los consulados, las elecciones en EEUU.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/claudia-sheinbaum-interfiere-en-las-elecciones-de-eeuu-a-traves-de-consulados-peter-schweizer\/","og_locale":"es_MX","og_type":"article","og_title":"Claudia Sheinbaum interfiere en las elecciones de EEUU a trav\u00e9s de consulados: Peter Schweizer","og_description":"El escritor Peter Schweizer acus\u00f3 que el gobierno de Claudia Sheinbaum interviene, a trav\u00e9s de los consulados, las elecciones en EEUU.","og_url":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/claudia-sheinbaum-interfiere-en-las-elecciones-de-eeuu-a-traves-de-consulados-peter-schweizer\/","og_site_name":"Tlaxcala Hoy","article_published_time":"2026-05-07T16:35:42+00:00","article_modified_time":"2026-05-07T16:35:43+00:00","og_image":[{"width":1200,"height":638,"url":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2026\/05\/claudia_sheinbaum_interfiere_elecciones_eeuu_embajadas_peter_schweizer.png","type":"image\/png"}],"author":"nestor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"nestor","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/claudia-sheinbaum-interfiere-en-las-elecciones-de-eeuu-a-traves-de-consulados-peter-schweizer\/#article","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/claudia-sheinbaum-interfiere-en-las-elecciones-de-eeuu-a-traves-de-consulados-peter-schweizer\/"},"author":{"name":"nestor","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#\/schema\/person\/8201f3fa49669f346d08e15801e0ebc2"},"headline":"Claudia Sheinbaum interfiere en las elecciones de EEUU a trav\u00e9s de consulados: Peter Schweizer","datePublished":"2026-05-07T16:35:42+00:00","dateModified":"2026-05-07T16:35:43+00:00","mainEntityOfPage":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/claudia-sheinbaum-interfiere-en-las-elecciones-de-eeuu-a-traves-de-consulados-peter-schweizer\/"},"wordCount":469,"commentCount":0,"image":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/claudia-sheinbaum-interfiere-en-las-elecciones-de-eeuu-a-traves-de-consulados-peter-schweizer\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2026\/05\/claudia_sheinbaum_interfiere_elecciones_eeuu_embajadas_peter_schweizer.png","keywords":["Claudia Sheinbaum","Elecciones en EEUU","Peter Schweizer"],"articleSection":["Nacional"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/claudia-sheinbaum-interfiere-en-las-elecciones-de-eeuu-a-traves-de-consulados-peter-schweizer\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/claudia-sheinbaum-interfiere-en-las-elecciones-de-eeuu-a-traves-de-consulados-peter-schweizer\/","url":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/claudia-sheinbaum-interfiere-en-las-elecciones-de-eeuu-a-traves-de-consulados-peter-schweizer\/","name":"Claudia Sheinbaum interfiere en las elecciones de EEUU a trav\u00e9s de consulados: Peter Schweizer - Tlaxcala Hoy","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#website"},"primaryImageOfPage":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/claudia-sheinbaum-interfiere-en-las-elecciones-de-eeuu-a-traves-de-consulados-peter-schweizer\/#primaryimage"},"image":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/claudia-sheinbaum-interfiere-en-las-elecciones-de-eeuu-a-traves-de-consulados-peter-schweizer\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2026\/05\/claudia_sheinbaum_interfiere_elecciones_eeuu_embajadas_peter_schweizer.png","datePublished":"2026-05-07T16:35:42+00:00","dateModified":"2026-05-07T16:35:43+00:00","author":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#\/schema\/person\/8201f3fa49669f346d08e15801e0ebc2"},"description":"El escritor Peter Schweizer acus\u00f3 que el gobierno de Claudia Sheinbaum interviene, a trav\u00e9s de los consulados, las elecciones en EEUU.","breadcrumb":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/claudia-sheinbaum-interfiere-en-las-elecciones-de-eeuu-a-traves-de-consulados-peter-schweizer\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/claudia-sheinbaum-interfiere-en-las-elecciones-de-eeuu-a-traves-de-consulados-peter-schweizer\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/claudia-sheinbaum-interfiere-en-las-elecciones-de-eeuu-a-traves-de-consulados-peter-schweizer\/#primaryimage","url":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2026\/05\/claudia_sheinbaum_interfiere_elecciones_eeuu_embajadas_peter_schweizer.png","contentUrl":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2026\/05\/claudia_sheinbaum_interfiere_elecciones_eeuu_embajadas_peter_schweizer.png","width":1200,"height":638},{"@type":"BreadcrumbList","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/claudia-sheinbaum-interfiere-en-las-elecciones-de-eeuu-a-traves-de-consulados-peter-schweizer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/grupohoymexico.com\/tlaxcala\/"},{"@type":"ListItem","position":2,"name":"Claudia Sheinbaum interfiere en las elecciones de EEUU a trav\u00e9s de consulados: Peter Schweizer"}]},{"@type":"WebSite","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#website","url":"https:\/\/grupohoymexico.com\/tlaxcala\/","name":"Tlaxcala Hoy","description":"El alma de la naci\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/grupohoymexico.com\/tlaxcala\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#\/schema\/person\/8201f3fa49669f346d08e15801e0ebc2","name":"nestor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g","caption":"nestor"},"url":"https:\/\/grupohoymexico.com\/tlaxcala\/author\/nestor\/"}]}},"_links":{"self":[{"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/posts\/6993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/comments?post=6993"}],"version-history":[{"count":0,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/posts\/6993\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/media\/6994"}],"wp:attachment":[{"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/media?parent=6993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/categories?post=6993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/tags?post=6993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}