{"id":6914,"date":"2026-05-05T12:37:47","date_gmt":"2026-05-05T18:37:47","guid":{"rendered":"https:\/\/grupohoymexico.com\/tlaxcala\/uncategorized\/ataques-armados-en-acapulco-mujer-asesinada-y-tres-heridas-en-zona-turistica-de-la-costa-azul\/"},"modified":"2026-05-05T12:37:47","modified_gmt":"2026-05-05T18:37:47","slug":"ataques-armados-en-acapulco-mujer-asesinada-y-tres-heridas-en-zona-turistica-de-la-costa-azul","status":"publish","type":"post","link":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/ataques-armados-en-acapulco-mujer-asesinada-y-tres-heridas-en-zona-turistica-de-la-costa-azul\/","title":{"rendered":"Ataques armados en Acapulco: mujer asesinada y tres heridas en zona tur\u00edstica de la Costa Azul"},"content":{"rendered":"\n<p>Una serie de <strong>ataques armados en Acapulco este lunes 4 de mayo<\/strong> encendi\u00f3 las alertas de seguridad en el principal <strong>destino tur\u00edstico de Guerrero<\/strong>. La violencia registrada este lunes en la zona de <strong>Costa Azul, Acapulco<\/strong>, dej\u00f3 como saldo una mujer muerta y tres m\u00e1s heridas, en hechos ocurridos a escasos metros de la <strong>Costera Miguel Alem\u00e1n<\/strong>, uno de los corredores tur\u00edsticos m\u00e1s importantes del puerto.<\/p>\n\n\n\n<p>Las agresiones ocurrieron en plena tarde, provocando una fuerte movilizaci\u00f3n de fuerzas federales, estatales y municipales, adem\u00e1s de generar preocupaci\u00f3n entre turistas, comerciantes y empresarios del sector hotelero.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-sigue-nuestras-cuentas-en-facebook-e-instagram-para-mantenerte-informado-con-las-noticias-mas-relevantes\"><strong>Sigue nuestras cuentas en Facebook e Instagram para mantenerte informado con las noticias m\u00e1s relevantes.<\/strong><\/h3>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-ataque-armado-en-costa-azul-deja-una-mujer-muerta\"><strong>Ataque armado en Costa Azul deja una mujer muerta<\/strong><\/h2>\n\n\n\n<p>El primer ataque se registr\u00f3 alrededor de las <strong>14:00 horas<\/strong> en una <strong>boutique ubicada sobre la calzada Pie de la Cuesta<\/strong>, muy cerca de la <strong>Costera Miguel Alem\u00e1n<\/strong> y a menos de 200 metros de la coordinaci\u00f3n de la <strong><a href=\"https:\/\/fiscaliaguerrero.gob.mx\/\">Fiscal\u00eda General del Estado<\/a><\/strong>.<\/p>\n\n\n\n<p>Sujetos armados abrieron fuego contra el establecimiento, provocando la muerte de una mujer en el lugar. Hasta el momento, la identidad de la v\u00edctima no ha sido revelada.<\/p>\n\n\n\n<p>Tras el ataque, autoridades implementaron un <strong>operativo de seguridad en Acapulco<\/strong>, acordonaron la zona y comenzaron la b\u00fasqueda de los responsables.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-segundo-ataque-en-acapulco-tres-mujeres-resultan-heridas\"><strong>Segundo ataque en Acapulco: tres mujeres resultan heridas<\/strong><\/h2>\n\n\n\n<p>Minutos despu\u00e9s, un segundo hecho violento ocurri\u00f3 frente a la <strong>glorieta del CICI<\/strong>, tambi\u00e9n en <strong>Costa Azul<\/strong>, sobre la <strong>calle Crist\u00f3bal Col\u00f3n<\/strong>.<\/p>\n\n\n\n<p>En este punto, hombres armados dispararon contra un sitio de taxis, dejando al menos tres mujeres heridas por arma de fuego. Entre las v\u00edctimas se encuentran:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Una vendedora semifija de comida.<\/li>\n\n\n\n<li>La \u201cchecadora\u201d del sitio de taxis.<\/li>\n\n\n\n<li>Una tercera mujer que se refugi\u00f3 en un restaurante cercano.<\/li>\n<\/ul>\n\n\n\n<p>Las lesionadas fueron atendidas por param\u00e9dicos del <strong>Centro de Urgencias M\u00e9dicas de Acapulco<\/strong> y trasladadas a un hospital, donde permanecen bajo resguardo policiaco.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-leer-mas-ataque-armado-en-patzcuaro-hallan-camioneta-calcinada-con-cinco-cuerpos-tras-emboscada\"><strong><em>Leer m\u00e1s: <a href=\"https:\/\/grupohoymexico.com\/2026\/05\/05\/ataque-armado-en-patzcuaro-michoacan-hallan-camioneta-calcinada-con-cinco-cuerpos-tras-emboscada\/\">Ataque armado en P\u00e1tzcuaro: hallan camioneta calcinada con cinco cuerpos tras emboscada<\/a><\/em><\/strong><\/h3>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-detienen-a-presunto-responsable-tras-operativo-en-acapulco\"><strong>Detienen a presunto responsable tras operativo en Acapulco<\/strong><\/h2>\n\n\n\n<p>Durante el despliegue de seguridad, elementos de la <strong>Guardia Nacional<\/strong> y polic\u00edas lograron la detenci\u00f3n de un presunto agresor en la <strong>esquina de Piloto Ant\u00f3n de Alaminos y la Costera Miguel Alem\u00e1n<\/strong>.<\/p>\n\n\n\n<p>De acuerdo con reportes preliminares, el detenido habr\u00eda disparado desde una motocicleta en movimiento, lo que le permiti\u00f3 huir inicialmente. Sin embargo, fue localizado y arrestado minutos despu\u00e9s.<\/p>\n\n\n\n<p>Las autoridades investigan su posible relaci\u00f3n directa con ambos <strong>ataques armados en Acapulco<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-zona-turistica-de-acapulco-bajo-presion-por-violencia\"><strong>Zona tur\u00edstica de Acapulco bajo presi\u00f3n por violencia<\/strong><\/h2>\n\n\n\n<p>Los hechos ocurrieron en el coraz\u00f3n de la actividad tur\u00edstica del puerto. La <strong>Costera Miguel Alem\u00e1n<\/strong> concentra hoteles, restaurantes, transporte p\u00fablico y comercios, siendo una de las zonas m\u00e1s transitadas por visitantes nacionales y extranjeros.<\/p>\n\n\n\n<p>La cercan\u00eda de los ataques con m\u00f3dulos de la <strong>Polic\u00eda Tur\u00edstica<\/strong> y la <strong>Guardia Nacional<\/strong> ha incrementado la preocupaci\u00f3n sobre la <strong>seguridad en Acapulco<\/strong>, especialmente en \u00e1reas consideradas prioritarias para el turismo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-leer-mas-golpe-al-crimen-organizado-detienen-a-el-chuky-en-manzanillo-presunto-jefe-de-plaza-de-cjng\"><strong><em>Leer m\u00e1s: <a href=\"https:\/\/grupohoymexico.com\/2026\/05\/04\/golpe-al-crimen-organizado-detienen-a-el-chuky-en-manzanillo-presunto-jefe-de-plaza-de-cjng\/\">\u00a1Golpe al crimen organizado! Detienen a &#8220;El Chuky&#8221; en Manzanillo, presunto jefe de plaza de CJNG<\/a><\/em><\/strong><\/h3>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-impacto-economico-inseguridad-golpea-al-turismo-en-acapulco\"><strong>Impacto econ\u00f3mico: inseguridad golpea al turismo en Acapulco<\/strong><\/h2>\n\n\n\n<p>Empresarios y hoteleros han advertido que la <strong>violencia en Acapulco 2026<\/strong> est\u00e1 afectando directamente la actividad econ\u00f3mica del puerto.<\/p>\n\n\n\n<p>Durante la actual temporada baja, los recientes hechos delictivos han provocado:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Disminuci\u00f3n en la ocupaci\u00f3n hotelera.<\/li>\n\n\n\n<li>Cancelaci\u00f3n de reservaciones.<\/li>\n\n\n\n<li>P\u00e9rdida de ingresos en comercios locales.<\/li>\n<\/ul>\n\n\n\n<p>C\u00e1maras empresariales han solicitado al gobierno estatal reforzar la seguridad en zonas tur\u00edsticas para recuperar la confianza de los visitantes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-refuerzan-seguridad-en-acapulco-tras-jornada-violenta\"><strong>Refuerzan seguridad en Acapulco tras jornada violenta<\/strong><\/h2>\n\n\n\n<p>Ante la gravedad de los hechos, autoridades locales y estatales han intensificado los operativos de vigilancia en <strong>Acapulco<\/strong>, especialmente en <strong>Costa Azul<\/strong> y avenidas principales.<\/p>\n\n\n\n<p>Las acciones incluyen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mayor presencia de Guardia Nacional.<\/li>\n\n\n\n<li>Instalaci\u00f3n de puntos de revisi\u00f3n.<\/li>\n\n\n\n<li>Patrullajes constantes en zonas tur\u00edsticas.<\/li>\n\n\n\n<li>Vigilancia en hospitales donde permanecen las v\u00edctimas.<\/li>\n<\/ul>\n\n\n\n<p>Las investigaciones contin\u00faan para esclarecer los hechos y determinar si existe relaci\u00f3n con otros episodios de violencia en municipios cercanos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-unete-a-nuestro-canal-de-whatsapp\"><strong><a href=\"https:\/\/whatsapp.com\/channel\/0029Vaylt1XG3R3gm4Nsgp2m\">\u00danete a nuestro canal de WhatsApp<\/a><\/strong><\/h2>\n","protected":false},"excerpt":{"rendered":"Una serie de ataques armados en Acapulco este lunes 4 de mayo encendi\u00f3 las alertas de seguridad en&hellip;","protected":false},"author":5,"featured_media":6915,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[175],"tags":[2994,2753,3036,1698,425],"class_list":{"0":"post-6914","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nacional","8":"tag-acapulco","9":"tag-ataque-armado","10":"tag-costa-azul","11":"tag-guerrero","12":"tag-seguridad","13":"cs-entry","14":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.7 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ataques armados en Acapulco: mujer asesinada y tres heridas en zona tur\u00edstica de la Costa Azul - Tlaxcala Hoy<\/title>\n<meta name=\"description\" content=\"Ataques armados en Acapulco el lunes 04 de mayo de 2026: mujer muerta y 3 heridas en Costa Azul, cerca Costera Miguel Alem\u00e1n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/ataques-armados-en-acapulco-mujer-asesinada-y-tres-heridas-en-zona-turistica-de-la-costa-azul\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ataques armados en Acapulco: mujer asesinada y tres heridas en zona tur\u00edstica de la Costa Azul\" \/>\n<meta property=\"og:description\" content=\"Ataques armados en Acapulco el lunes 04 de mayo de 2026: mujer muerta y 3 heridas en Costa Azul, cerca Costera Miguel Alem\u00e1n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/ataques-armados-en-acapulco-mujer-asesinada-y-tres-heridas-en-zona-turistica-de-la-costa-azul\/\" \/>\n<meta property=\"og:site_name\" content=\"Tlaxcala Hoy\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-05T18:37:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2026\/05\/ataques-armados-Acapulco.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"638\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jair\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"jair\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/ataques-armados-en-acapulco-mujer-asesinada-y-tres-heridas-en-zona-turistica-de-la-costa-azul\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/ataques-armados-en-acapulco-mujer-asesinada-y-tres-heridas-en-zona-turistica-de-la-costa-azul\\\/\"},\"author\":{\"name\":\"jair\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#\\\/schema\\\/person\\\/98e2425fe99fbbdf486895b69dab3c3d\"},\"headline\":\"Ataques armados en Acapulco: mujer asesinada y tres heridas en zona tur\u00edstica de la Costa Azul\",\"datePublished\":\"2026-05-05T18:37:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/ataques-armados-en-acapulco-mujer-asesinada-y-tres-heridas-en-zona-turistica-de-la-costa-azul\\\/\"},\"wordCount\":723,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/ataques-armados-en-acapulco-mujer-asesinada-y-tres-heridas-en-zona-turistica-de-la-costa-azul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/05\\\/ataques-armados-Acapulco.jpg\",\"keywords\":[\"Acapulco\",\"Ataque armado\",\"Costa Azul\",\"Guerrero\",\"Seguridad\"],\"articleSection\":[\"Nacional\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/ataques-armados-en-acapulco-mujer-asesinada-y-tres-heridas-en-zona-turistica-de-la-costa-azul\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/ataques-armados-en-acapulco-mujer-asesinada-y-tres-heridas-en-zona-turistica-de-la-costa-azul\\\/\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/ataques-armados-en-acapulco-mujer-asesinada-y-tres-heridas-en-zona-turistica-de-la-costa-azul\\\/\",\"name\":\"Ataques armados en Acapulco: mujer asesinada y tres heridas en zona tur\u00edstica de la Costa Azul - Tlaxcala Hoy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/ataques-armados-en-acapulco-mujer-asesinada-y-tres-heridas-en-zona-turistica-de-la-costa-azul\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/ataques-armados-en-acapulco-mujer-asesinada-y-tres-heridas-en-zona-turistica-de-la-costa-azul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/05\\\/ataques-armados-Acapulco.jpg\",\"datePublished\":\"2026-05-05T18:37:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#\\\/schema\\\/person\\\/98e2425fe99fbbdf486895b69dab3c3d\"},\"description\":\"Ataques armados en Acapulco el lunes 04 de mayo de 2026: mujer muerta y 3 heridas en Costa Azul, cerca Costera Miguel Alem\u00e1n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/ataques-armados-en-acapulco-mujer-asesinada-y-tres-heridas-en-zona-turistica-de-la-costa-azul\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/ataques-armados-en-acapulco-mujer-asesinada-y-tres-heridas-en-zona-turistica-de-la-costa-azul\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/ataques-armados-en-acapulco-mujer-asesinada-y-tres-heridas-en-zona-turistica-de-la-costa-azul\\\/#primaryimage\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/05\\\/ataques-armados-Acapulco.jpg\",\"contentUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/05\\\/ataques-armados-Acapulco.jpg\",\"width\":1200,\"height\":638,\"caption\":\"Foto: Polic\u00eda de Guerrero\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/nacional\\\/ataques-armados-en-acapulco-mujer-asesinada-y-tres-heridas-en-zona-turistica-de-la-costa-azul\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ataques armados en Acapulco: mujer asesinada y tres heridas en zona tur\u00edstica de la Costa Azul\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#website\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/\",\"name\":\"Tlaxcala Hoy\",\"description\":\"El alma de la naci\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#\\\/schema\\\/person\\\/98e2425fe99fbbdf486895b69dab3c3d\",\"name\":\"jair\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ec205dfb8733a1ce1601942dddb04fc9294fb780c832e3c1ec58faa8e4e64e9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ec205dfb8733a1ce1601942dddb04fc9294fb780c832e3c1ec58faa8e4e64e9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ec205dfb8733a1ce1601942dddb04fc9294fb780c832e3c1ec58faa8e4e64e9b?s=96&d=mm&r=g\",\"caption\":\"jair\"},\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/author\\\/jair\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ataques armados en Acapulco: mujer asesinada y tres heridas en zona tur\u00edstica de la Costa Azul - Tlaxcala Hoy","description":"Ataques armados en Acapulco el lunes 04 de mayo de 2026: mujer muerta y 3 heridas en Costa Azul, cerca Costera Miguel Alem\u00e1n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/ataques-armados-en-acapulco-mujer-asesinada-y-tres-heridas-en-zona-turistica-de-la-costa-azul\/","og_locale":"es_MX","og_type":"article","og_title":"Ataques armados en Acapulco: mujer asesinada y tres heridas en zona tur\u00edstica de la Costa Azul","og_description":"Ataques armados en Acapulco el lunes 04 de mayo de 2026: mujer muerta y 3 heridas en Costa Azul, cerca Costera Miguel Alem\u00e1n.","og_url":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/ataques-armados-en-acapulco-mujer-asesinada-y-tres-heridas-en-zona-turistica-de-la-costa-azul\/","og_site_name":"Tlaxcala Hoy","article_published_time":"2026-05-05T18:37:47+00:00","og_image":[{"width":1200,"height":638,"url":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2026\/05\/ataques-armados-Acapulco.jpg","type":"image\/jpeg"}],"author":"jair","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"jair","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/ataques-armados-en-acapulco-mujer-asesinada-y-tres-heridas-en-zona-turistica-de-la-costa-azul\/#article","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/ataques-armados-en-acapulco-mujer-asesinada-y-tres-heridas-en-zona-turistica-de-la-costa-azul\/"},"author":{"name":"jair","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#\/schema\/person\/98e2425fe99fbbdf486895b69dab3c3d"},"headline":"Ataques armados en Acapulco: mujer asesinada y tres heridas en zona tur\u00edstica de la Costa Azul","datePublished":"2026-05-05T18:37:47+00:00","mainEntityOfPage":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/ataques-armados-en-acapulco-mujer-asesinada-y-tres-heridas-en-zona-turistica-de-la-costa-azul\/"},"wordCount":723,"commentCount":0,"image":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/ataques-armados-en-acapulco-mujer-asesinada-y-tres-heridas-en-zona-turistica-de-la-costa-azul\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2026\/05\/ataques-armados-Acapulco.jpg","keywords":["Acapulco","Ataque armado","Costa Azul","Guerrero","Seguridad"],"articleSection":["Nacional"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/ataques-armados-en-acapulco-mujer-asesinada-y-tres-heridas-en-zona-turistica-de-la-costa-azul\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/ataques-armados-en-acapulco-mujer-asesinada-y-tres-heridas-en-zona-turistica-de-la-costa-azul\/","url":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/ataques-armados-en-acapulco-mujer-asesinada-y-tres-heridas-en-zona-turistica-de-la-costa-azul\/","name":"Ataques armados en Acapulco: mujer asesinada y tres heridas en zona tur\u00edstica de la Costa Azul - Tlaxcala Hoy","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#website"},"primaryImageOfPage":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/ataques-armados-en-acapulco-mujer-asesinada-y-tres-heridas-en-zona-turistica-de-la-costa-azul\/#primaryimage"},"image":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/ataques-armados-en-acapulco-mujer-asesinada-y-tres-heridas-en-zona-turistica-de-la-costa-azul\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2026\/05\/ataques-armados-Acapulco.jpg","datePublished":"2026-05-05T18:37:47+00:00","author":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#\/schema\/person\/98e2425fe99fbbdf486895b69dab3c3d"},"description":"Ataques armados en Acapulco el lunes 04 de mayo de 2026: mujer muerta y 3 heridas en Costa Azul, cerca Costera Miguel Alem\u00e1n.","breadcrumb":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/ataques-armados-en-acapulco-mujer-asesinada-y-tres-heridas-en-zona-turistica-de-la-costa-azul\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/ataques-armados-en-acapulco-mujer-asesinada-y-tres-heridas-en-zona-turistica-de-la-costa-azul\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/ataques-armados-en-acapulco-mujer-asesinada-y-tres-heridas-en-zona-turistica-de-la-costa-azul\/#primaryimage","url":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2026\/05\/ataques-armados-Acapulco.jpg","contentUrl":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2026\/05\/ataques-armados-Acapulco.jpg","width":1200,"height":638,"caption":"Foto: Polic\u00eda de Guerrero"},{"@type":"BreadcrumbList","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/ataques-armados-en-acapulco-mujer-asesinada-y-tres-heridas-en-zona-turistica-de-la-costa-azul\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/grupohoymexico.com\/tlaxcala\/"},{"@type":"ListItem","position":2,"name":"Ataques armados en Acapulco: mujer asesinada y tres heridas en zona tur\u00edstica de la Costa Azul"}]},{"@type":"WebSite","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#website","url":"https:\/\/grupohoymexico.com\/tlaxcala\/","name":"Tlaxcala Hoy","description":"El alma de la naci\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/grupohoymexico.com\/tlaxcala\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#\/schema\/person\/98e2425fe99fbbdf486895b69dab3c3d","name":"jair","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ec205dfb8733a1ce1601942dddb04fc9294fb780c832e3c1ec58faa8e4e64e9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ec205dfb8733a1ce1601942dddb04fc9294fb780c832e3c1ec58faa8e4e64e9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ec205dfb8733a1ce1601942dddb04fc9294fb780c832e3c1ec58faa8e4e64e9b?s=96&d=mm&r=g","caption":"jair"},"url":"https:\/\/grupohoymexico.com\/tlaxcala\/author\/jair\/"}]}},"_links":{"self":[{"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/posts\/6914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/comments?post=6914"}],"version-history":[{"count":0,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/posts\/6914\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/media\/6915"}],"wp:attachment":[{"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/media?parent=6914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/categories?post=6914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/tags?post=6914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}