{"id":3217,"date":"2025-06-07T19:16:58","date_gmt":"2025-06-07T19:16:58","guid":{"rendered":"https:\/\/grupohoymexico.com\/tlaxcala\/?p=3217"},"modified":"2025-06-07T19:36:29","modified_gmt":"2025-06-07T19:36:29","slug":"autoridades-de-tlaxcala-han-detenido-a-mas-de-500-personas-que-ha-cometido-un-delito","status":"publish","type":"post","link":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/estatal\/autoridades-de-tlaxcala-han-detenido-a-mas-de-500-personas-que-ha-cometido-un-delito\/","title":{"rendered":"Autoridades de Tlaxcala han detenido a m\u00e1s de 500 personas que ha cometido un delito"},"content":{"rendered":"<p>La seguridad se convirti\u00f3 en un tema serio en la entidad gobernada por Lorena Cu\u00e9llar. La Secretar\u00eda de Seguridad Ciudadana (SSC) local detuvo a m\u00e1s de 500 personas que han cometido alg\u00fan <strong>delito en Tlaxcala<\/strong>.<\/p>\n<p><strong>Alberto Mart\u00edn Perea Marrufo<\/strong>, titular de la SSC, comparti\u00f3 ante medios de comunicaci\u00f3n que se detuvieron a <a href=\"https:\/\/grupohoymexico.com\/tlaxcala\/deportes\/wwe-listo-para-celebrar-dos-eventos-imperdibles-worlds-collide-y-money-in-the-bank\/\">cientos de personas<\/a>. Mientras tanto est\u00e1n a la espera de recibir una sentencia por parte del <strong>Poder Judicial<\/strong>.<\/p>\n<blockquote><p>&#8220;A la fecha m\u00e1s de 500 personas que han infringido la ley han sido detenidas en el estado y seguimos trabajando para ello&#8221;, coment\u00f3.<\/p><\/blockquote>\n<p>Perrea Marrufo asegur\u00f3 que las acciones del estado y la federaci\u00f3n \u201chan sido contundentes\u201d en contra de las bandas delincuenciales. Sostuvo que el trabajo colaborativo entre Estado y Federaci\u00f3n funciona para aportar indicios para lograr la <a href=\"https:\/\/grupohoymexico.com\/tlaxcala\/columnas\/garganta-no-tan-profunda-6-de-junio\/\" target=\"_blank\" rel=\"noopener\">detenci\u00f3n<\/a> de quienes cometen delito en todo Tlaxcala.<\/p>\n<p>El Secretario de Seguridad sostuvo que la mayor\u00eda de presuntos delincuentes cometieron los siguientes actos il\u00edcitos:<\/p>\n<ul>\n<li>Robo contra el patrimonio<\/li>\n<li>\u201cHuachicol\u201d<\/li>\n<li>\u201cHuachigas\u201d<\/li>\n<li>Tala clandestina de \u00e1rboles<\/li>\n<\/ul>\n<p>Respecto al futuro de los delincuentes detenidos en Tlaxcala, sostuvo que depender\u00e1 de la decisi\u00f3n del <a href=\"https:\/\/ssc.tlaxcala.gob.mx\/\" target=\"_blank\" rel=\"noopener\">Poder Judicial<\/a> y las sentencias que tengan en su contra. Destac\u00f3 que es su responsabilidad &#8220;evitar que esta gente salga del proceso que llevan o de las sentencias a las que sean acreedores&#8221;.<\/p>\n<p><span class=\"relative -mx-px my-[-0.2rem] rounded px-px py-[0.2rem] transition-colors duration-100 ease-in-out\">Tlaxcala se mantiene entre los estados con <strong data-start=\"43\" data-end=\"99\">las tasas de incidencia delictiva m\u00e1s bajas del pa\u00eds<\/strong>. Seg\u00fan datos oficiales del Secretariado Ejecutivo del Sistema Nacional de Seguridad P\u00fablica correspondientes a abril de 2025, el estado presenta una baja en delitos del fuero com\u00fan.\u00a0<\/span><\/p>\n<p>En enero de 2025, la entidad registr\u00f3 una ca\u00edda del 15.8\u202f% en la tasa de delitos respecto al mismo mes del a\u00f1o anterior. Esto que refleja avances en prevenci\u00f3n y control delictivo.<\/p>\n<p>A pesar del panorama general, existen zonas como <strong data-start=\"49\" data-end=\"60\">Apizaco<\/strong>, que enfrentan retos espec\u00edficos en seguridad, incluyendo un incremento en asaltos a negocios nocturnos y agresiones a comerciantes, lo cual exige medidas focalizadas por parte de las autoridades locales.<\/p>\n","protected":false},"excerpt":{"rendered":"La seguridad se convirti\u00f3 en un tema serio en la entidad gobernada por Lorena Cu\u00e9llar. La Secretar\u00eda de&hellip;","protected":false},"author":15,"featured_media":3222,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[172],"tags":[1637,1636,1634,1635,654,405,229],"class_list":{"0":"post-3217","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-estatal","8":"tag-aprehension-de-delincuentes","9":"tag-delito","10":"tag-devolucion-de-impuestos","11":"tag-estatus-de-devolucion-de-impuestos","12":"tag-sat","13":"tag-seguridad-en-tlaxcala","14":"tag-tlaxcala","15":"cs-entry","16":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.7 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tlaxcala detiene a m\u00e1s de 500 personas que ha cometido un delito- Tlaxcala Hoy<\/title>\n<meta name=\"description\" content=\"La SSC de Tlaxcala revel\u00f3 que m\u00e1s de 500 personas que han cometido alg\u00fan delito en la entidad han sido detenidas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/autoridades-de-tlaxcala-han-detenido-a-mas-de-500-personas-que-ha-cometido-un-delito\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Autoridades de Tlaxcala han detenido a m\u00e1s de 500 personas que ha cometido un delito\" \/>\n<meta property=\"og:description\" content=\"La SSC de Tlaxcala revel\u00f3 que m\u00e1s de 500 personas que han cometido alg\u00fan delito en la entidad han sido detenidas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/autoridades-de-tlaxcala-han-detenido-a-mas-de-500-personas-que-ha-cometido-un-delito\/\" \/>\n<meta property=\"og:site_name\" content=\"Tlaxcala Hoy\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-07T19:16:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-07T19:36:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2025\/06\/tlaxcala_500_personas_cometido_delito_detenidas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"nestor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"nestor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/autoridades-de-tlaxcala-han-detenido-a-mas-de-500-personas-que-ha-cometido-un-delito\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/autoridades-de-tlaxcala-han-detenido-a-mas-de-500-personas-que-ha-cometido-un-delito\\\/\"},\"author\":{\"name\":\"nestor\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#\\\/schema\\\/person\\\/8201f3fa49669f346d08e15801e0ebc2\"},\"headline\":\"Autoridades de Tlaxcala han detenido a m\u00e1s de 500 personas que ha cometido un delito\",\"datePublished\":\"2025-06-07T19:16:58+00:00\",\"dateModified\":\"2025-06-07T19:36:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/autoridades-de-tlaxcala-han-detenido-a-mas-de-500-personas-que-ha-cometido-un-delito\\\/\"},\"wordCount\":359,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/autoridades-de-tlaxcala-han-detenido-a-mas-de-500-personas-que-ha-cometido-un-delito\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/06\\\/tlaxcala_500_personas_cometido_delito_detenidas.jpg\",\"keywords\":[\"aprehensi\u00f3n de delincuentes\",\"delito\",\"devoluci\u00f3n de impuestos\",\"Estatus de devoluci\u00f3n de impuestos\",\"SAT\",\"Seguridad en Tlaxcala\",\"Tlaxcala\"],\"articleSection\":[\"Estados\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/autoridades-de-tlaxcala-han-detenido-a-mas-de-500-personas-que-ha-cometido-un-delito\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/autoridades-de-tlaxcala-han-detenido-a-mas-de-500-personas-que-ha-cometido-un-delito\\\/\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/autoridades-de-tlaxcala-han-detenido-a-mas-de-500-personas-que-ha-cometido-un-delito\\\/\",\"name\":\"Tlaxcala detiene a m\u00e1s de 500 personas que ha cometido un delito- Tlaxcala Hoy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/autoridades-de-tlaxcala-han-detenido-a-mas-de-500-personas-que-ha-cometido-un-delito\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/autoridades-de-tlaxcala-han-detenido-a-mas-de-500-personas-que-ha-cometido-un-delito\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/06\\\/tlaxcala_500_personas_cometido_delito_detenidas.jpg\",\"datePublished\":\"2025-06-07T19:16:58+00:00\",\"dateModified\":\"2025-06-07T19:36:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#\\\/schema\\\/person\\\/8201f3fa49669f346d08e15801e0ebc2\"},\"description\":\"La SSC de Tlaxcala revel\u00f3 que m\u00e1s de 500 personas que han cometido alg\u00fan delito en la entidad han sido detenidas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/autoridades-de-tlaxcala-han-detenido-a-mas-de-500-personas-que-ha-cometido-un-delito\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/autoridades-de-tlaxcala-han-detenido-a-mas-de-500-personas-que-ha-cometido-un-delito\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/autoridades-de-tlaxcala-han-detenido-a-mas-de-500-personas-que-ha-cometido-un-delito\\\/#primaryimage\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/06\\\/tlaxcala_500_personas_cometido_delito_detenidas.jpg\",\"contentUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/06\\\/tlaxcala_500_personas_cometido_delito_detenidas.jpg\",\"width\":1280,\"height\":680,\"caption\":\"La seguridad en Tlaxcala sigue siendo una prioridad, como lo es la detenci\u00f3n de m\u00e1s de 500 personas que ha cometido un delito. Foto: Freepik\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/autoridades-de-tlaxcala-han-detenido-a-mas-de-500-personas-que-ha-cometido-un-delito\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Autoridades de Tlaxcala han detenido a m\u00e1s de 500 personas que ha cometido un delito\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#website\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/\",\"name\":\"Tlaxcala Hoy\",\"description\":\"El alma de la naci\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#\\\/schema\\\/person\\\/8201f3fa49669f346d08e15801e0ebc2\",\"name\":\"nestor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g\",\"caption\":\"nestor\"},\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/author\\\/nestor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tlaxcala detiene a m\u00e1s de 500 personas que ha cometido un delito- Tlaxcala Hoy","description":"La SSC de Tlaxcala revel\u00f3 que m\u00e1s de 500 personas que han cometido alg\u00fan delito en la entidad han sido detenidas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/autoridades-de-tlaxcala-han-detenido-a-mas-de-500-personas-que-ha-cometido-un-delito\/","og_locale":"es_MX","og_type":"article","og_title":"Autoridades de Tlaxcala han detenido a m\u00e1s de 500 personas que ha cometido un delito","og_description":"La SSC de Tlaxcala revel\u00f3 que m\u00e1s de 500 personas que han cometido alg\u00fan delito en la entidad han sido detenidas.","og_url":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/autoridades-de-tlaxcala-han-detenido-a-mas-de-500-personas-que-ha-cometido-un-delito\/","og_site_name":"Tlaxcala Hoy","article_published_time":"2025-06-07T19:16:58+00:00","article_modified_time":"2025-06-07T19:36:29+00:00","og_image":[{"width":1280,"height":680,"url":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2025\/06\/tlaxcala_500_personas_cometido_delito_detenidas.jpg","type":"image\/jpeg"}],"author":"nestor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"nestor","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/autoridades-de-tlaxcala-han-detenido-a-mas-de-500-personas-que-ha-cometido-un-delito\/#article","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/autoridades-de-tlaxcala-han-detenido-a-mas-de-500-personas-que-ha-cometido-un-delito\/"},"author":{"name":"nestor","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#\/schema\/person\/8201f3fa49669f346d08e15801e0ebc2"},"headline":"Autoridades de Tlaxcala han detenido a m\u00e1s de 500 personas que ha cometido un delito","datePublished":"2025-06-07T19:16:58+00:00","dateModified":"2025-06-07T19:36:29+00:00","mainEntityOfPage":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/autoridades-de-tlaxcala-han-detenido-a-mas-de-500-personas-que-ha-cometido-un-delito\/"},"wordCount":359,"commentCount":0,"image":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/autoridades-de-tlaxcala-han-detenido-a-mas-de-500-personas-que-ha-cometido-un-delito\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2025\/06\/tlaxcala_500_personas_cometido_delito_detenidas.jpg","keywords":["aprehensi\u00f3n de delincuentes","delito","devoluci\u00f3n de impuestos","Estatus de devoluci\u00f3n de impuestos","SAT","Seguridad en Tlaxcala","Tlaxcala"],"articleSection":["Estados"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/autoridades-de-tlaxcala-han-detenido-a-mas-de-500-personas-que-ha-cometido-un-delito\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/autoridades-de-tlaxcala-han-detenido-a-mas-de-500-personas-que-ha-cometido-un-delito\/","url":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/autoridades-de-tlaxcala-han-detenido-a-mas-de-500-personas-que-ha-cometido-un-delito\/","name":"Tlaxcala detiene a m\u00e1s de 500 personas que ha cometido un delito- Tlaxcala Hoy","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#website"},"primaryImageOfPage":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/autoridades-de-tlaxcala-han-detenido-a-mas-de-500-personas-que-ha-cometido-un-delito\/#primaryimage"},"image":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/autoridades-de-tlaxcala-han-detenido-a-mas-de-500-personas-que-ha-cometido-un-delito\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2025\/06\/tlaxcala_500_personas_cometido_delito_detenidas.jpg","datePublished":"2025-06-07T19:16:58+00:00","dateModified":"2025-06-07T19:36:29+00:00","author":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#\/schema\/person\/8201f3fa49669f346d08e15801e0ebc2"},"description":"La SSC de Tlaxcala revel\u00f3 que m\u00e1s de 500 personas que han cometido alg\u00fan delito en la entidad han sido detenidas.","breadcrumb":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/autoridades-de-tlaxcala-han-detenido-a-mas-de-500-personas-que-ha-cometido-un-delito\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/autoridades-de-tlaxcala-han-detenido-a-mas-de-500-personas-que-ha-cometido-un-delito\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/autoridades-de-tlaxcala-han-detenido-a-mas-de-500-personas-que-ha-cometido-un-delito\/#primaryimage","url":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2025\/06\/tlaxcala_500_personas_cometido_delito_detenidas.jpg","contentUrl":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2025\/06\/tlaxcala_500_personas_cometido_delito_detenidas.jpg","width":1280,"height":680,"caption":"La seguridad en Tlaxcala sigue siendo una prioridad, como lo es la detenci\u00f3n de m\u00e1s de 500 personas que ha cometido un delito. Foto: Freepik"},{"@type":"BreadcrumbList","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/autoridades-de-tlaxcala-han-detenido-a-mas-de-500-personas-que-ha-cometido-un-delito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/grupohoymexico.com\/tlaxcala\/"},{"@type":"ListItem","position":2,"name":"Autoridades de Tlaxcala han detenido a m\u00e1s de 500 personas que ha cometido un delito"}]},{"@type":"WebSite","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#website","url":"https:\/\/grupohoymexico.com\/tlaxcala\/","name":"Tlaxcala Hoy","description":"El alma de la naci\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/grupohoymexico.com\/tlaxcala\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#\/schema\/person\/8201f3fa49669f346d08e15801e0ebc2","name":"nestor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g","caption":"nestor"},"url":"https:\/\/grupohoymexico.com\/tlaxcala\/author\/nestor\/"}]}},"_links":{"self":[{"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/posts\/3217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/comments?post=3217"}],"version-history":[{"count":7,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/posts\/3217\/revisions"}],"predecessor-version":[{"id":3225,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/posts\/3217\/revisions\/3225"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/media\/3222"}],"wp:attachment":[{"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/media?parent=3217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/categories?post=3217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/tags?post=3217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}