{"id":2341,"date":"2025-04-14T16:49:25","date_gmt":"2025-04-14T16:49:25","guid":{"rendered":"https:\/\/grupohoymexico.com\/tlaxcala\/?p=2341"},"modified":"2025-04-14T16:51:12","modified_gmt":"2025-04-14T16:51:12","slug":"el-conflicto-territorial-entre-apizaco-y-yauhquemehcan-genera-solicitud-de-delimitacion-formal","status":"publish","type":"post","link":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/estatal\/el-conflicto-territorial-entre-apizaco-y-yauhquemehcan-genera-solicitud-de-delimitacion-formal\/","title":{"rendered":"El conflicto territorial entre Apizaco y Yauhquemehcan genera solicitud de delimitaci\u00f3n formal"},"content":{"rendered":"<p style=\"text-align: left;\">El conflicto entre los<strong> municipios de Apizaco y Yauhquemehcan<\/strong> lleg\u00f3 al <a href=\"https:\/\/congresodetlaxcala.gob.mx\/legislacion\/\"><strong>Congreso del Estado<\/strong><\/a>. El <strong>30 de marzo<\/strong>, personal del <strong>Ayuntamiento de Apizaco<\/strong> suspendi\u00f3 de manera sorpresiva las obras en una agencia localizada en una zona lim\u00edtrofe con Yauhquemehcan. Dicho hecho, desat\u00f3 una <strong>disputa entre ambos municipios.<\/strong><\/p>\n<p style=\"text-align: left;\">La controversia gira en torno a la propiedad del terreno, ya que<strong> Yhcaauhquemen<\/strong> asegura que el espacio le pertenece y que las obras fueron aprobadas por ellos. Sin embargo, el municipio de <strong>Apizaco<\/strong> argument\u00f3 que los trabajos carec\u00edan de los permisos correspondientes, lo que motiv\u00f3 la intervenci\u00f3n de las autoridades locales.<\/p>\n<h2 style=\"text-align: left;\"><strong>Apizaco y Yauhquemehcan: Urgente necesidad de claridad en los l\u00edmites territoriales<\/strong><\/h2>\n<p style=\"text-align: left;\">La situaci\u00f3n afecta la<strong> construcci\u00f3n de nuevas obras y tiene repercusiones en los tr\u00e1mites municipales que deben realizar los habitantes de Apizaco. <\/strong>La indefinici\u00f3n de los l\u00edmites entre los municipios <strong>genera confusi\u00f3n y dificultades para los ciudadanos que viven en las zonas colindantes.<\/strong><\/p>\n<p style=\"text-align: left;\">Adem\u00e1s de<strong> Yauhquemehcan<\/strong>,<strong> Apizaco<\/strong> comparte l\u00edmites con otros municipios como<strong> Tzompantepec, Santa Cruz Tlaxcala y <a href=\"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/decomisan-45-mil-litros-de-combustible-robado-en-tetla-de-la-solidaridad-tlaxcala\/\">Tetla<\/a><\/strong>, lo que hace a\u00fan m\u00e1s urgente la necesidad de contar con una delimitaci\u00f3n territorial clara.<\/p>\n<p style=\"text-align: left;\">Para abordar este problema, el <strong>Congreso del Estado <\/strong>se comprometi\u00f3 a trabajar en una soluci\u00f3n. La <strong>diputada Sandra Guadalupe Aguilar Vega, presidenta de la Comisi\u00f3n de Asuntos Municipales,<\/strong> ser\u00e1 la encargada de coordinar los esfuerzos para definir de manera oficial los <strong>l\u00edmites territoriales entre Apizaco y sus municipios vecinos<\/strong>. La medida busca evitar conflictos futuros y mejorar la organizaci\u00f3n en la regi\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"El conflicto entre los municipios de Apizaco y Yauhquemehcan lleg\u00f3 al Congreso del Estado. El 30 de marzo,&hellip;","protected":false},"author":1,"featured_media":2343,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[172],"tags":[219,1301,1092,1300,1299,229,1298],"class_list":{"0":"post-2341","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-estatal","8":"tag-apizaco","9":"tag-confilcto","10":"tag-congreso","11":"tag-delimitacion","12":"tag-limites","13":"tag-tlaxcala","14":"tag-yauhquemehcan","15":"cs-entry","16":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.7 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El conflicto territorial entre Apizaco y Yauhquemehcan genera solicitud de delimitaci\u00f3n formal - Tlaxcala Hoy<\/title>\n<meta name=\"description\" content=\"Conflicto territorial entre Apizaco y Yauhquemehcan llega al Congreso de Tlaxcala; buscan definir l\u00edmites para evitar nuevos enfrentamientos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/el-conflicto-territorial-entre-apizaco-y-yauhquemehcan-genera-solicitud-de-delimitacion-formal\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El conflicto territorial entre Apizaco y Yauhquemehcan genera solicitud de delimitaci\u00f3n formal\" \/>\n<meta property=\"og:description\" content=\"Conflicto territorial entre Apizaco y Yauhquemehcan llega al Congreso de Tlaxcala; buscan definir l\u00edmites para evitar nuevos enfrentamientos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/el-conflicto-territorial-entre-apizaco-y-yauhquemehcan-genera-solicitud-de-delimitacion-formal\/\" \/>\n<meta property=\"og:site_name\" content=\"Tlaxcala Hoy\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-14T16:49:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-14T16:51:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2025\/04\/5181535008337276475.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/el-conflicto-territorial-entre-apizaco-y-yauhquemehcan-genera-solicitud-de-delimitacion-formal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/el-conflicto-territorial-entre-apizaco-y-yauhquemehcan-genera-solicitud-de-delimitacion-formal\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#\\\/schema\\\/person\\\/ce6086ac837852775a3a4f539356c297\"},\"headline\":\"El conflicto territorial entre Apizaco y Yauhquemehcan genera solicitud de delimitaci\u00f3n formal\",\"datePublished\":\"2025-04-14T16:49:25+00:00\",\"dateModified\":\"2025-04-14T16:51:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/el-conflicto-territorial-entre-apizaco-y-yauhquemehcan-genera-solicitud-de-delimitacion-formal\\\/\"},\"wordCount\":277,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/el-conflicto-territorial-entre-apizaco-y-yauhquemehcan-genera-solicitud-de-delimitacion-formal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/04\\\/5181535008337276475.jpg\",\"keywords\":[\"Apizaco\",\"confilcto\",\"Congreso\",\"delimitaci\u00f3n\",\"l\u00edmites\",\"Tlaxcala\",\"Yauhquemehcan\"],\"articleSection\":[\"Estados\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/el-conflicto-territorial-entre-apizaco-y-yauhquemehcan-genera-solicitud-de-delimitacion-formal\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/el-conflicto-territorial-entre-apizaco-y-yauhquemehcan-genera-solicitud-de-delimitacion-formal\\\/\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/el-conflicto-territorial-entre-apizaco-y-yauhquemehcan-genera-solicitud-de-delimitacion-formal\\\/\",\"name\":\"El conflicto territorial entre Apizaco y Yauhquemehcan genera solicitud de delimitaci\u00f3n formal - Tlaxcala Hoy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/el-conflicto-territorial-entre-apizaco-y-yauhquemehcan-genera-solicitud-de-delimitacion-formal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/el-conflicto-territorial-entre-apizaco-y-yauhquemehcan-genera-solicitud-de-delimitacion-formal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/04\\\/5181535008337276475.jpg\",\"datePublished\":\"2025-04-14T16:49:25+00:00\",\"dateModified\":\"2025-04-14T16:51:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#\\\/schema\\\/person\\\/ce6086ac837852775a3a4f539356c297\"},\"description\":\"Conflicto territorial entre Apizaco y Yauhquemehcan llega al Congreso de Tlaxcala; buscan definir l\u00edmites para evitar nuevos enfrentamientos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/el-conflicto-territorial-entre-apizaco-y-yauhquemehcan-genera-solicitud-de-delimitacion-formal\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/el-conflicto-territorial-entre-apizaco-y-yauhquemehcan-genera-solicitud-de-delimitacion-formal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/el-conflicto-territorial-entre-apizaco-y-yauhquemehcan-genera-solicitud-de-delimitacion-formal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/04\\\/5181535008337276475.jpg\",\"contentUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/04\\\/5181535008337276475.jpg\",\"width\":1280,\"height\":680,\"caption\":\"Apizaco\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/el-conflicto-territorial-entre-apizaco-y-yauhquemehcan-genera-solicitud-de-delimitacion-formal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El conflicto territorial entre Apizaco y Yauhquemehcan genera solicitud de delimitaci\u00f3n formal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#website\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/\",\"name\":\"Tlaxcala Hoy\",\"description\":\"El alma de la naci\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#\\\/schema\\\/person\\\/ce6086ac837852775a3a4f539356c297\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\\\/\\\/44.197.188.197.nip.io\"],\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/author\\\/user\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El conflicto territorial entre Apizaco y Yauhquemehcan genera solicitud de delimitaci\u00f3n formal - Tlaxcala Hoy","description":"Conflicto territorial entre Apizaco y Yauhquemehcan llega al Congreso de Tlaxcala; buscan definir l\u00edmites para evitar nuevos enfrentamientos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/el-conflicto-territorial-entre-apizaco-y-yauhquemehcan-genera-solicitud-de-delimitacion-formal\/","og_locale":"es_MX","og_type":"article","og_title":"El conflicto territorial entre Apizaco y Yauhquemehcan genera solicitud de delimitaci\u00f3n formal","og_description":"Conflicto territorial entre Apizaco y Yauhquemehcan llega al Congreso de Tlaxcala; buscan definir l\u00edmites para evitar nuevos enfrentamientos.","og_url":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/el-conflicto-territorial-entre-apizaco-y-yauhquemehcan-genera-solicitud-de-delimitacion-formal\/","og_site_name":"Tlaxcala Hoy","article_published_time":"2025-04-14T16:49:25+00:00","article_modified_time":"2025-04-14T16:51:12+00:00","og_image":[{"width":1280,"height":680,"url":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2025\/04\/5181535008337276475.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"user","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/el-conflicto-territorial-entre-apizaco-y-yauhquemehcan-genera-solicitud-de-delimitacion-formal\/#article","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/el-conflicto-territorial-entre-apizaco-y-yauhquemehcan-genera-solicitud-de-delimitacion-formal\/"},"author":{"name":"user","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#\/schema\/person\/ce6086ac837852775a3a4f539356c297"},"headline":"El conflicto territorial entre Apizaco y Yauhquemehcan genera solicitud de delimitaci\u00f3n formal","datePublished":"2025-04-14T16:49:25+00:00","dateModified":"2025-04-14T16:51:12+00:00","mainEntityOfPage":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/el-conflicto-territorial-entre-apizaco-y-yauhquemehcan-genera-solicitud-de-delimitacion-formal\/"},"wordCount":277,"commentCount":0,"image":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/el-conflicto-territorial-entre-apizaco-y-yauhquemehcan-genera-solicitud-de-delimitacion-formal\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2025\/04\/5181535008337276475.jpg","keywords":["Apizaco","confilcto","Congreso","delimitaci\u00f3n","l\u00edmites","Tlaxcala","Yauhquemehcan"],"articleSection":["Estados"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/el-conflicto-territorial-entre-apizaco-y-yauhquemehcan-genera-solicitud-de-delimitacion-formal\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/el-conflicto-territorial-entre-apizaco-y-yauhquemehcan-genera-solicitud-de-delimitacion-formal\/","url":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/el-conflicto-territorial-entre-apizaco-y-yauhquemehcan-genera-solicitud-de-delimitacion-formal\/","name":"El conflicto territorial entre Apizaco y Yauhquemehcan genera solicitud de delimitaci\u00f3n formal - Tlaxcala Hoy","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#website"},"primaryImageOfPage":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/el-conflicto-territorial-entre-apizaco-y-yauhquemehcan-genera-solicitud-de-delimitacion-formal\/#primaryimage"},"image":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/el-conflicto-territorial-entre-apizaco-y-yauhquemehcan-genera-solicitud-de-delimitacion-formal\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2025\/04\/5181535008337276475.jpg","datePublished":"2025-04-14T16:49:25+00:00","dateModified":"2025-04-14T16:51:12+00:00","author":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#\/schema\/person\/ce6086ac837852775a3a4f539356c297"},"description":"Conflicto territorial entre Apizaco y Yauhquemehcan llega al Congreso de Tlaxcala; buscan definir l\u00edmites para evitar nuevos enfrentamientos.","breadcrumb":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/el-conflicto-territorial-entre-apizaco-y-yauhquemehcan-genera-solicitud-de-delimitacion-formal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/el-conflicto-territorial-entre-apizaco-y-yauhquemehcan-genera-solicitud-de-delimitacion-formal\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/el-conflicto-territorial-entre-apizaco-y-yauhquemehcan-genera-solicitud-de-delimitacion-formal\/#primaryimage","url":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2025\/04\/5181535008337276475.jpg","contentUrl":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2025\/04\/5181535008337276475.jpg","width":1280,"height":680,"caption":"Apizaco"},{"@type":"BreadcrumbList","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/el-conflicto-territorial-entre-apizaco-y-yauhquemehcan-genera-solicitud-de-delimitacion-formal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/grupohoymexico.com\/tlaxcala\/"},{"@type":"ListItem","position":2,"name":"El conflicto territorial entre Apizaco y Yauhquemehcan genera solicitud de delimitaci\u00f3n formal"}]},{"@type":"WebSite","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#website","url":"https:\/\/grupohoymexico.com\/tlaxcala\/","name":"Tlaxcala Hoy","description":"El alma de la naci\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/grupohoymexico.com\/tlaxcala\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#\/schema\/person\/ce6086ac837852775a3a4f539356c297","name":"user","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:\/\/44.197.188.197.nip.io"],"url":"https:\/\/grupohoymexico.com\/tlaxcala\/author\/user\/"}]}},"_links":{"self":[{"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/posts\/2341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/comments?post=2341"}],"version-history":[{"count":2,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/posts\/2341\/revisions"}],"predecessor-version":[{"id":2344,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/posts\/2341\/revisions\/2344"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/media\/2343"}],"wp:attachment":[{"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/media?parent=2341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/categories?post=2341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/tags?post=2341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}