{"id":2025,"date":"2025-03-21T22:05:05","date_gmt":"2025-03-21T22:05:05","guid":{"rendered":"https:\/\/grupohoymexico.com\/tlaxcala\/?p=2025"},"modified":"2025-03-21T22:30:56","modified_gmt":"2025-03-21T22:30:56","slug":"gobierno-de-tlaxcala-esperara-para-rendir-informe-sobre-jovenes-fallecidos","status":"publish","type":"post","link":"https:\/\/grupohoymexico.com\/tlaxcala\/nacional\/estatal\/gobierno-de-tlaxcala-esperara-para-rendir-informe-sobre-jovenes-fallecidos\/","title":{"rendered":"Gobierno de Tlaxcala esperar\u00e1 para rendir informe sobre j\u00f3venes fallecidos"},"content":{"rendered":"<p data-pm-slice=\"1 1 []\">El titular de la <strong>Secretar\u00eda de Gobierno (Segob)<\/strong>, <strong>Luis Antonio Ram\u00edrez Hern\u00e1ndez<\/strong>, inform\u00f3 que la <strong>Fiscal\u00eda General de Justicia de Oaxaca<\/strong> ha comunicado que los j\u00f3venes hallados sin vida a principios de marzo en los l\u00edmites con <strong>Puebla<\/strong> eran originarios de la entidad. Sin embargo, aclar\u00f3 que los detalles del caso no ser\u00e1n compartidos hasta que la investigaci\u00f3n haya llegado a una resoluci\u00f3n satisfactoria.<\/p>\n<h3>Posibilidad de relaci\u00f3n entre las v\u00edctimas con el cr\u00edmen organizado<\/h3>\n<p><strong>Ram\u00edrez Hern\u00e1ndez<\/strong> explic\u00f3 que, aunque existe la posibilidad de que el hecho est\u00e9 relacionado con actividades delictivas, las autoridades de <strong>Tlaxcala<\/strong> mantienen la secrec\u00eda del proceso para no vulnerar la investigaci\u00f3n. En este sentido, subray\u00f3 que cualquier informaci\u00f3n adicional se dar\u00e1 a conocer \u00fanicamente cuando la <strong><a href=\"https:\/\/fgr.org.mx\/swb\/CNPJ\/Fiscalia_Tlaxcala\">Fiscal\u00eda General del Estado<\/a> (FGJE)<\/strong> emita una resoluci\u00f3n final.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"\" src=\"https:\/\/scontent.fmex19-1.fna.fbcdn.net\/v\/t39.30808-6\/485595279_122156040794556569_4010888904674179237_n.jpg?_nc_cat=101&amp;ccb=1-7&amp;_nc_sid=833d8c&amp;_nc_eui2=AeETu780B2qFo-NdtomcFQHp90fmBn3_NSj3R-YGff81KCqPDj4jpVbwMArn7mKR2908IKqHwtqrI6mZ1HET3O1v&amp;_nc_ohc=Ml-ETsADDjoQ7kNvgG5DgiV&amp;_nc_oc=AdnLWRpVEQAbPiEx3zOmUTDCZIfIy1a5IdIR11t1hhjgrQ3aSXoC3VaQTUN75r2NFYtRCMnsMr2luypUmyftucg3&amp;_nc_zt=23&amp;_nc_ht=scontent.fmex19-1.fna&amp;_nc_gid=joEKr0ZIRa0krK1bgU-QKw&amp;oh=00_AYFx2PS7MGn6G-SG_Px12euEwJ_JQvKQE8U3mVbO3dkaEw&amp;oe=67E3B5C1\" alt=\"Puede ser una imagen de 6 personas y personas estudiando\" width=\"721\" height=\"481\" \/><\/p>\n<h4>Trabajo coordinado entre Tlaxcala, Puebla y Oaxaca<\/h4>\n<p>&nbsp;<\/p>\n<p>El funcionario reiter\u00f3 que la coordinaci\u00f3n entre la fiscal\u00eda de <strong>Oaxaca<\/strong> y su hom\u00f3loga en <strong>Puebla<\/strong> ha sido estricta y efectiva. Se\u00f1al\u00f3 que esta colaboraci\u00f3n ha permitido avances en la investigaci\u00f3n, aunque la diferencia en los <strong>mecanismos de coordinaci\u00f3n<\/strong> entre ambas entidades ha generado diferencias en la manera de manejar la informaci\u00f3n p\u00fablica del caso.<\/p>\n<p>LEE TAMBI\u00c9N: <a href=\"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/jovenes-desaparecidos-en-huatulco-pertenecian-a-grupo-delictivo\/\">todo lo que se sabe sobre los j\u00f3venes desaparecidos en Tlaxcala\u00a0<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>\u201cHa sido la misma coordinaci\u00f3n que se ha manejado con <strong>Oaxaca<\/strong> y con <strong>Puebla<\/strong>, pero en el momento que tenga una <strong>dictaminaci\u00f3n<\/strong> final con el cierre de carpeta podr\u00eda ponerlo en conocimiento con ustedes la<strong> Fiscal\u00eda General del Estado (FGJE)<\/strong>\u201d, indic\u00f3 Ram\u00edrez Hern\u00e1ndez.<\/p>\n<h3>Investigaciones siguen su curso<\/h3>\n<p>Por el momento, las<strong> autoridades<\/strong> han descartado que la informaci\u00f3n hasta ahora obtenida contradiga los reportes previos de desaparici\u00f3n, pero insisten en mantener la <strong>confidencialidad del proceso.<\/strong> El objetivo es respetar el principio de debido proceso y evitar cualquier tipo de responsabilidad legal derivada de una <strong>divulgaci\u00f3n<\/strong> anticipada de datos.<\/p>\n<p>El <strong>gobierno estatal<\/strong> reafirm\u00f3 su compromiso de esclarecer los hechos y brindar justicia a las <strong>v\u00edctimas<\/strong> y sus<strong> familias.<\/strong> Mientras la investigaci\u00f3n sigue en curso, se espera que la coordinaci\u00f3n entre fiscal\u00edas contin\u00fae dando resultados concretos que permitan esclarecer las circunstancias de este lamentable caso.<\/p>\n<p>&nbsp;<\/p>\n<h3>\u00bfJ\u00f3venes asesinados de Tlaxcala eran pertenecientes a grupo criminal?<\/h3>\n<p>&nbsp;<\/p>\n<p data-pm-slice=\"1 1 []\">Miembros de la Secretaria de Seguridad de Oaxaca comunicaron que los cinco j\u00f3venes de <strong>Tlaxcala<\/strong>, desaparecidos en\u00a0<strong>Huatulco<\/strong>\u00a0y posteriormente encontrados sin vida dentro de un veh\u00edculo en la frontera de\u00a0<strong>Puebla<\/strong>, formaban parte de un grupo delictivo.<\/p>\n<p data-pm-slice=\"1 1 []\">\n<p>El titular de la secretar\u00eda,\u00a0\u00a0<strong>Iv\u00e1n Garc\u00eda \u00c1lvarez<\/strong>, inform\u00f3 en conferencia de prensa que las\u00a0<strong>investigaciones<\/strong>\u00a0conjuntas realizadas por las<strong>\u00a0fiscal\u00edas<\/strong>\u00a0de\u00a0<strong>Tlaxcala y Puebla<\/strong>\u00a0informan que los fallecidos, junto con otras cuatro personas, eran miembros de una\u00a0<strong>organizaci\u00f3n criminal<\/strong>\u00a0con\u00a0<strong>labores criminales<\/strong>\u00a0en los estados de<strong>\u00a0Tlaxcala, Puebla, Oaxaca y Veracruz.<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"El titular de la Secretar\u00eda de Gobierno (Segob), Luis Antonio Ram\u00edrez Hern\u00e1ndez, inform\u00f3 que la Fiscal\u00eda General de&hellip;","protected":false},"author":30,"featured_media":2030,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[172],"tags":[1134,1136,1025,377,1135],"class_list":{"0":"post-2025","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-estatal","8":"tag-gobierno-de-tlaxcal","9":"tag-informacion","10":"tag-jovenes-asesinados","11":"tag-noticias","12":"tag-tlaxcala-informe","13":"cs-entry","14":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.7 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gobierno de Tlaxcala esperar\u00e1 para rendir informe sobre j\u00f3venes fallecidos<\/title>\n<meta name=\"description\" content=\"Gobierno de Tlaxcala hasta que concluyan las investigaciones sobre el caso de los j\u00f3venes tlaxcaltecas asesinados y encontrados en Oaxaca.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/gobierno-de-tlaxcala-esperara-para-rendir-informe-sobre-jovenes-fallecidos\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gobierno de Tlaxcala esperar\u00e1 para rendir informe sobre j\u00f3venes fallecidos\" \/>\n<meta property=\"og:description\" content=\"Gobierno de Tlaxcala hasta que concluyan las investigaciones sobre el caso de los j\u00f3venes tlaxcaltecas asesinados y encontrados en Oaxaca.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/gobierno-de-tlaxcala-esperara-para-rendir-informe-sobre-jovenes-fallecidos\/\" \/>\n<meta property=\"og:site_name\" content=\"Tlaxcala Hoy\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-21T22:05:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-21T22:30:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2025\/03\/Tlaxcala-dddd.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1455\" \/>\n\t<meta property=\"og:image:height\" content=\"757\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"eduardo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"eduardo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/gobierno-de-tlaxcala-esperara-para-rendir-informe-sobre-jovenes-fallecidos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/gobierno-de-tlaxcala-esperara-para-rendir-informe-sobre-jovenes-fallecidos\\\/\"},\"author\":{\"name\":\"eduardo\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#\\\/schema\\\/person\\\/e95b7b8df1e5c291ede743c160292779\"},\"headline\":\"Gobierno de Tlaxcala esperar\u00e1 para rendir informe sobre j\u00f3venes fallecidos\",\"datePublished\":\"2025-03-21T22:05:05+00:00\",\"dateModified\":\"2025-03-21T22:30:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/gobierno-de-tlaxcala-esperara-para-rendir-informe-sobre-jovenes-fallecidos\\\/\"},\"wordCount\":513,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/gobierno-de-tlaxcala-esperara-para-rendir-informe-sobre-jovenes-fallecidos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/03\\\/Tlaxcala-dddd.jpg\",\"keywords\":[\"Gobierno de tlaxcal\",\"Informaci\u00f3n\",\"J\u00f3venes asesinados\",\"noticias\",\"Tlaxcala informe\"],\"articleSection\":[\"Estados\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/gobierno-de-tlaxcala-esperara-para-rendir-informe-sobre-jovenes-fallecidos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/gobierno-de-tlaxcala-esperara-para-rendir-informe-sobre-jovenes-fallecidos\\\/\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/gobierno-de-tlaxcala-esperara-para-rendir-informe-sobre-jovenes-fallecidos\\\/\",\"name\":\"Gobierno de Tlaxcala esperar\u00e1 para rendir informe sobre j\u00f3venes fallecidos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/gobierno-de-tlaxcala-esperara-para-rendir-informe-sobre-jovenes-fallecidos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/gobierno-de-tlaxcala-esperara-para-rendir-informe-sobre-jovenes-fallecidos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/03\\\/Tlaxcala-dddd.jpg\",\"datePublished\":\"2025-03-21T22:05:05+00:00\",\"dateModified\":\"2025-03-21T22:30:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#\\\/schema\\\/person\\\/e95b7b8df1e5c291ede743c160292779\"},\"description\":\"Gobierno de Tlaxcala hasta que concluyan las investigaciones sobre el caso de los j\u00f3venes tlaxcaltecas asesinados y encontrados en Oaxaca.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/gobierno-de-tlaxcala-esperara-para-rendir-informe-sobre-jovenes-fallecidos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/gobierno-de-tlaxcala-esperara-para-rendir-informe-sobre-jovenes-fallecidos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/gobierno-de-tlaxcala-esperara-para-rendir-informe-sobre-jovenes-fallecidos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/03\\\/Tlaxcala-dddd.jpg\",\"contentUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/03\\\/Tlaxcala-dddd.jpg\",\"width\":1455,\"height\":757,\"caption\":\"Tlaxcala\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/estatal\\\/gobierno-de-tlaxcala-esperara-para-rendir-informe-sobre-jovenes-fallecidos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gobierno de Tlaxcala esperar\u00e1 para rendir informe sobre j\u00f3venes fallecidos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#website\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/\",\"name\":\"Tlaxcala Hoy\",\"description\":\"El alma de la naci\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/#\\\/schema\\\/person\\\/e95b7b8df1e5c291ede743c160292779\",\"name\":\"eduardo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ecdd30dcf3feeb5f57f13840c3daeb08334d3b69de7bb9e067a540c4925a9788?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ecdd30dcf3feeb5f57f13840c3daeb08334d3b69de7bb9e067a540c4925a9788?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ecdd30dcf3feeb5f57f13840c3daeb08334d3b69de7bb9e067a540c4925a9788?s=96&d=mm&r=g\",\"caption\":\"eduardo\"},\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/tlaxcala\\\/author\\\/eduardo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gobierno de Tlaxcala esperar\u00e1 para rendir informe sobre j\u00f3venes fallecidos","description":"Gobierno de Tlaxcala hasta que concluyan las investigaciones sobre el caso de los j\u00f3venes tlaxcaltecas asesinados y encontrados en Oaxaca.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/gobierno-de-tlaxcala-esperara-para-rendir-informe-sobre-jovenes-fallecidos\/","og_locale":"es_MX","og_type":"article","og_title":"Gobierno de Tlaxcala esperar\u00e1 para rendir informe sobre j\u00f3venes fallecidos","og_description":"Gobierno de Tlaxcala hasta que concluyan las investigaciones sobre el caso de los j\u00f3venes tlaxcaltecas asesinados y encontrados en Oaxaca.","og_url":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/gobierno-de-tlaxcala-esperara-para-rendir-informe-sobre-jovenes-fallecidos\/","og_site_name":"Tlaxcala Hoy","article_published_time":"2025-03-21T22:05:05+00:00","article_modified_time":"2025-03-21T22:30:56+00:00","og_image":[{"width":1455,"height":757,"url":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2025\/03\/Tlaxcala-dddd.jpg","type":"image\/jpeg"}],"author":"eduardo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"eduardo","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/gobierno-de-tlaxcala-esperara-para-rendir-informe-sobre-jovenes-fallecidos\/#article","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/gobierno-de-tlaxcala-esperara-para-rendir-informe-sobre-jovenes-fallecidos\/"},"author":{"name":"eduardo","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#\/schema\/person\/e95b7b8df1e5c291ede743c160292779"},"headline":"Gobierno de Tlaxcala esperar\u00e1 para rendir informe sobre j\u00f3venes fallecidos","datePublished":"2025-03-21T22:05:05+00:00","dateModified":"2025-03-21T22:30:56+00:00","mainEntityOfPage":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/gobierno-de-tlaxcala-esperara-para-rendir-informe-sobre-jovenes-fallecidos\/"},"wordCount":513,"commentCount":0,"image":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/gobierno-de-tlaxcala-esperara-para-rendir-informe-sobre-jovenes-fallecidos\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2025\/03\/Tlaxcala-dddd.jpg","keywords":["Gobierno de tlaxcal","Informaci\u00f3n","J\u00f3venes asesinados","noticias","Tlaxcala informe"],"articleSection":["Estados"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/gobierno-de-tlaxcala-esperara-para-rendir-informe-sobre-jovenes-fallecidos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/gobierno-de-tlaxcala-esperara-para-rendir-informe-sobre-jovenes-fallecidos\/","url":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/gobierno-de-tlaxcala-esperara-para-rendir-informe-sobre-jovenes-fallecidos\/","name":"Gobierno de Tlaxcala esperar\u00e1 para rendir informe sobre j\u00f3venes fallecidos","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#website"},"primaryImageOfPage":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/gobierno-de-tlaxcala-esperara-para-rendir-informe-sobre-jovenes-fallecidos\/#primaryimage"},"image":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/gobierno-de-tlaxcala-esperara-para-rendir-informe-sobre-jovenes-fallecidos\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2025\/03\/Tlaxcala-dddd.jpg","datePublished":"2025-03-21T22:05:05+00:00","dateModified":"2025-03-21T22:30:56+00:00","author":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#\/schema\/person\/e95b7b8df1e5c291ede743c160292779"},"description":"Gobierno de Tlaxcala hasta que concluyan las investigaciones sobre el caso de los j\u00f3venes tlaxcaltecas asesinados y encontrados en Oaxaca.","breadcrumb":{"@id":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/gobierno-de-tlaxcala-esperara-para-rendir-informe-sobre-jovenes-fallecidos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/gobierno-de-tlaxcala-esperara-para-rendir-informe-sobre-jovenes-fallecidos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/gobierno-de-tlaxcala-esperara-para-rendir-informe-sobre-jovenes-fallecidos\/#primaryimage","url":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2025\/03\/Tlaxcala-dddd.jpg","contentUrl":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-content\/uploads\/sites\/4\/2025\/03\/Tlaxcala-dddd.jpg","width":1455,"height":757,"caption":"Tlaxcala"},{"@type":"BreadcrumbList","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/estatal\/gobierno-de-tlaxcala-esperara-para-rendir-informe-sobre-jovenes-fallecidos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/grupohoymexico.com\/tlaxcala\/"},{"@type":"ListItem","position":2,"name":"Gobierno de Tlaxcala esperar\u00e1 para rendir informe sobre j\u00f3venes fallecidos"}]},{"@type":"WebSite","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#website","url":"https:\/\/grupohoymexico.com\/tlaxcala\/","name":"Tlaxcala Hoy","description":"El alma de la naci\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/grupohoymexico.com\/tlaxcala\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/grupohoymexico.com\/tlaxcala\/#\/schema\/person\/e95b7b8df1e5c291ede743c160292779","name":"eduardo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ecdd30dcf3feeb5f57f13840c3daeb08334d3b69de7bb9e067a540c4925a9788?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ecdd30dcf3feeb5f57f13840c3daeb08334d3b69de7bb9e067a540c4925a9788?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ecdd30dcf3feeb5f57f13840c3daeb08334d3b69de7bb9e067a540c4925a9788?s=96&d=mm&r=g","caption":"eduardo"},"url":"https:\/\/grupohoymexico.com\/tlaxcala\/author\/eduardo\/"}]}},"_links":{"self":[{"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/posts\/2025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/comments?post=2025"}],"version-history":[{"count":3,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/posts\/2025\/revisions"}],"predecessor-version":[{"id":2031,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/posts\/2025\/revisions\/2031"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/media\/2030"}],"wp:attachment":[{"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/media?parent=2025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/categories?post=2025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grupohoymexico.com\/tlaxcala\/wp-json\/wp\/v2\/tags?post=2025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}