{"id":82887,"date":"2026-05-10T02:36:10","date_gmt":"2026-05-10T02:36:10","guid":{"rendered":"https:\/\/grupohoymexico.com\/puebla\/?p=82887"},"modified":"2026-05-10T02:36:12","modified_gmt":"2026-05-10T02:36:12","slug":"casados-con-hijos-se-renueva-con-su-tercera-temporada","status":"publish","type":"post","link":"https:\/\/grupohoymexico.com\/puebla\/2026\/05\/10\/casados-con-hijos-se-renueva-con-su-tercera-temporada\/","title":{"rendered":"&#8216;Casados con Hijos&#8217; se renueva con su tercera temporada"},"content":{"rendered":"\n<p><em>Casados Con Hijos<\/em> regresa con su tercera temporada a trav\u00e9s de <strong>Sony Channel<\/strong> gracias al \u00e9xito y la recepci\u00f3n que tiene por el p\u00fablico. La familia Olivares est\u00e1 lista para una nueva aventura y divertir con humor, caos y situaciones absurdas.<\/p>\n\n\n\n<p>Su primer episodio se estren\u00f3 el pasado domingo 3 de mayo a las 23:30 horas, pero este fin de semana promete un episodio con m\u00e1s picard\u00eda y su sello caracter\u00edstico de imperfecci\u00f3n. A trav\u00e9s de sus dos partes previas es que el p\u00fablico encontr\u00f3 una historia con la cual divertirse e identificarse a partir de los elementos de la cultura popular que inciden en el d\u00eda a d\u00eda.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-casados-con-hijos-se-renueva-con-su-tercera-temporada\">&#8216;Casados con Hijos&#8217; se renueva con su tercera temporada<\/h2>\n\n\n\n<p>Esta producci\u00f3n es posible gracias a las actuaciones de Adri\u00e1n Uribe, Sandra Echeverr\u00eda, Tamara Ni\u00f1o de Rivera, Luis Arrieta, Val Dorantes y Max Najar. Desde la primera temporada esta historia encanta al p\u00fablico con su sencillez y humor, al mismo tiempo que recupera situaciones de las <em>sitcoms<\/em> que marcaron tendencias. <\/p>\n\n\n\n<p>Para la tercera temporada, <em>Casados con hijos<\/em> presenta a una <strong>familia Olivares<\/strong> renovada y poco realista, pues sus deseos de volverse millonarios contin\u00faan. Pero, al mismo tiempo, con la intenci\u00f3n de aplicar el <strong>m\u00ednimo esfuerzo<\/strong>, como si la suerte cayera del cielo.<\/p>\n\n\n\n<p>Poncho contin\u00faa persiguiendo la riqueza con ideas tan ambiciosas como desastrosas, mientras Angie har\u00e1 todo lo posible por mantener viva la chispa en su relaci\u00f3n, incluso si eso implica evitar a toda costa una nueva maternidad.<\/p>\n\n\n\n<p>Entre apps fallidas, herencias inesperadas, romances improbables, celos, enredos familiares y hasta situaciones fuera de este mundo, esta temporada promete llevar el humor al l\u00edmite.<\/p>\n\n\n\n<p>Con esta tercera temporada, <em>Casados con hijos<\/em> invita a la audiencia a reencontrarse con una familia tan disfuncional como entra\u00f1able, donde cada episodio garantiza risas y momentos memorables.<\/p>\n","protected":false},"excerpt":{"rendered":"Casados Con Hijos regresa con su tercera temporada a trav\u00e9s de Sony Channel gracias al \u00e9xito y la&hellip;","protected":false},"author":15,"featured_media":82889,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[81,2582],"tags":[4103],"class_list":{"0":"post-82887","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-entretenimiento","8":"category-entretenamiento","9":"tag-casados-con-hijos","10":"cs-entry","11":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.7 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>&#039;Casados con Hijos&#039; se renueva con su tercera temporada - Grupo Hoy Puebla<\/title>\n<meta name=\"description\" content=\"&#039;Casados con Hijos&#039;, con los protag\u00f3nicos de Adri\u00e1n Uribe y Sandra Echeverr\u00eda, se renueva con su tercera temporada.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/grupohoymexico.com\/puebla\/2026\/05\/10\/casados-con-hijos-se-renueva-con-su-tercera-temporada\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&#039;Casados con Hijos&#039; se renueva con su tercera temporada\" \/>\n<meta property=\"og:description\" content=\"&#039;Casados con Hijos&#039;, con los protag\u00f3nicos de Adri\u00e1n Uribe y Sandra Echeverr\u00eda, se renueva con su tercera temporada.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/grupohoymexico.com\/puebla\/2026\/05\/10\/casados-con-hijos-se-renueva-con-su-tercera-temporada\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo Hoy Puebla\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-10T02:36:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-10T02:36:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/grupohoymexico.com\/puebla\/wp-content\/uploads\/sites\/3\/2026\/05\/casados_con_hijos_.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"740\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"nestor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"nestor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2026\\\/05\\\/10\\\/casados-con-hijos-se-renueva-con-su-tercera-temporada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2026\\\/05\\\/10\\\/casados-con-hijos-se-renueva-con-su-tercera-temporada\\\/\"},\"author\":{\"name\":\"nestor\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/#\\\/schema\\\/person\\\/8201f3fa49669f346d08e15801e0ebc2\"},\"headline\":\"&#8216;Casados con Hijos&#8217; se renueva con su tercera temporada\",\"datePublished\":\"2026-05-10T02:36:10+00:00\",\"dateModified\":\"2026-05-10T02:36:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2026\\\/05\\\/10\\\/casados-con-hijos-se-renueva-con-su-tercera-temporada\\\/\"},\"wordCount\":329,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2026\\\/05\\\/10\\\/casados-con-hijos-se-renueva-con-su-tercera-temporada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/05\\\/casados_con_hijos_.jpg\",\"keywords\":[\"Casados con hijos\"],\"articleSection\":[\"Entretenimiento\",\"Entretenimiento\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2026\\\/05\\\/10\\\/casados-con-hijos-se-renueva-con-su-tercera-temporada\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2026\\\/05\\\/10\\\/casados-con-hijos-se-renueva-con-su-tercera-temporada\\\/\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2026\\\/05\\\/10\\\/casados-con-hijos-se-renueva-con-su-tercera-temporada\\\/\",\"name\":\"'Casados con Hijos' se renueva con su tercera temporada - Grupo Hoy Puebla\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2026\\\/05\\\/10\\\/casados-con-hijos-se-renueva-con-su-tercera-temporada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2026\\\/05\\\/10\\\/casados-con-hijos-se-renueva-con-su-tercera-temporada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/05\\\/casados_con_hijos_.jpg\",\"datePublished\":\"2026-05-10T02:36:10+00:00\",\"dateModified\":\"2026-05-10T02:36:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/#\\\/schema\\\/person\\\/8201f3fa49669f346d08e15801e0ebc2\"},\"description\":\"'Casados con Hijos', con los protag\u00f3nicos de Adri\u00e1n Uribe y Sandra Echeverr\u00eda, se renueva con su tercera temporada.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2026\\\/05\\\/10\\\/casados-con-hijos-se-renueva-con-su-tercera-temporada\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2026\\\/05\\\/10\\\/casados-con-hijos-se-renueva-con-su-tercera-temporada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2026\\\/05\\\/10\\\/casados-con-hijos-se-renueva-con-su-tercera-temporada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/05\\\/casados_con_hijos_.jpg\",\"contentUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/05\\\/casados_con_hijos_.jpg\",\"width\":1280,\"height\":740},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2026\\\/05\\\/10\\\/casados-con-hijos-se-renueva-con-su-tercera-temporada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8216;Casados con Hijos&#8217; se renueva con su tercera temporada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/#website\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/\",\"name\":\"Grupo Hoy Puebla\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/#\\\/schema\\\/person\\\/8201f3fa49669f346d08e15801e0ebc2\",\"name\":\"nestor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g\",\"caption\":\"nestor\"},\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/author\\\/nestor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"'Casados con Hijos' se renueva con su tercera temporada - Grupo Hoy Puebla","description":"'Casados con Hijos', con los protag\u00f3nicos de Adri\u00e1n Uribe y Sandra Echeverr\u00eda, se renueva con su tercera temporada.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/grupohoymexico.com\/puebla\/2026\/05\/10\/casados-con-hijos-se-renueva-con-su-tercera-temporada\/","og_locale":"es_MX","og_type":"article","og_title":"'Casados con Hijos' se renueva con su tercera temporada","og_description":"'Casados con Hijos', con los protag\u00f3nicos de Adri\u00e1n Uribe y Sandra Echeverr\u00eda, se renueva con su tercera temporada.","og_url":"https:\/\/grupohoymexico.com\/puebla\/2026\/05\/10\/casados-con-hijos-se-renueva-con-su-tercera-temporada\/","og_site_name":"Grupo Hoy Puebla","article_published_time":"2026-05-10T02:36:10+00:00","article_modified_time":"2026-05-10T02:36:12+00:00","og_image":[{"width":1280,"height":740,"url":"https:\/\/grupohoymexico.com\/puebla\/wp-content\/uploads\/sites\/3\/2026\/05\/casados_con_hijos_.jpg","type":"image\/jpeg"}],"author":"nestor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"nestor","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/grupohoymexico.com\/puebla\/2026\/05\/10\/casados-con-hijos-se-renueva-con-su-tercera-temporada\/#article","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/puebla\/2026\/05\/10\/casados-con-hijos-se-renueva-con-su-tercera-temporada\/"},"author":{"name":"nestor","@id":"https:\/\/grupohoymexico.com\/puebla\/#\/schema\/person\/8201f3fa49669f346d08e15801e0ebc2"},"headline":"&#8216;Casados con Hijos&#8217; se renueva con su tercera temporada","datePublished":"2026-05-10T02:36:10+00:00","dateModified":"2026-05-10T02:36:12+00:00","mainEntityOfPage":{"@id":"https:\/\/grupohoymexico.com\/puebla\/2026\/05\/10\/casados-con-hijos-se-renueva-con-su-tercera-temporada\/"},"wordCount":329,"commentCount":0,"image":{"@id":"https:\/\/grupohoymexico.com\/puebla\/2026\/05\/10\/casados-con-hijos-se-renueva-con-su-tercera-temporada\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/puebla\/wp-content\/uploads\/sites\/3\/2026\/05\/casados_con_hijos_.jpg","keywords":["Casados con hijos"],"articleSection":["Entretenimiento","Entretenimiento"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/grupohoymexico.com\/puebla\/2026\/05\/10\/casados-con-hijos-se-renueva-con-su-tercera-temporada\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/grupohoymexico.com\/puebla\/2026\/05\/10\/casados-con-hijos-se-renueva-con-su-tercera-temporada\/","url":"https:\/\/grupohoymexico.com\/puebla\/2026\/05\/10\/casados-con-hijos-se-renueva-con-su-tercera-temporada\/","name":"'Casados con Hijos' se renueva con su tercera temporada - Grupo Hoy Puebla","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/puebla\/#website"},"primaryImageOfPage":{"@id":"https:\/\/grupohoymexico.com\/puebla\/2026\/05\/10\/casados-con-hijos-se-renueva-con-su-tercera-temporada\/#primaryimage"},"image":{"@id":"https:\/\/grupohoymexico.com\/puebla\/2026\/05\/10\/casados-con-hijos-se-renueva-con-su-tercera-temporada\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/puebla\/wp-content\/uploads\/sites\/3\/2026\/05\/casados_con_hijos_.jpg","datePublished":"2026-05-10T02:36:10+00:00","dateModified":"2026-05-10T02:36:12+00:00","author":{"@id":"https:\/\/grupohoymexico.com\/puebla\/#\/schema\/person\/8201f3fa49669f346d08e15801e0ebc2"},"description":"'Casados con Hijos', con los protag\u00f3nicos de Adri\u00e1n Uribe y Sandra Echeverr\u00eda, se renueva con su tercera temporada.","breadcrumb":{"@id":"https:\/\/grupohoymexico.com\/puebla\/2026\/05\/10\/casados-con-hijos-se-renueva-con-su-tercera-temporada\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/grupohoymexico.com\/puebla\/2026\/05\/10\/casados-con-hijos-se-renueva-con-su-tercera-temporada\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/grupohoymexico.com\/puebla\/2026\/05\/10\/casados-con-hijos-se-renueva-con-su-tercera-temporada\/#primaryimage","url":"https:\/\/grupohoymexico.com\/puebla\/wp-content\/uploads\/sites\/3\/2026\/05\/casados_con_hijos_.jpg","contentUrl":"https:\/\/grupohoymexico.com\/puebla\/wp-content\/uploads\/sites\/3\/2026\/05\/casados_con_hijos_.jpg","width":1280,"height":740},{"@type":"BreadcrumbList","@id":"https:\/\/grupohoymexico.com\/puebla\/2026\/05\/10\/casados-con-hijos-se-renueva-con-su-tercera-temporada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/grupohoymexico.com\/puebla\/"},{"@type":"ListItem","position":2,"name":"&#8216;Casados con Hijos&#8217; se renueva con su tercera temporada"}]},{"@type":"WebSite","@id":"https:\/\/grupohoymexico.com\/puebla\/#website","url":"https:\/\/grupohoymexico.com\/puebla\/","name":"Grupo Hoy Puebla","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/grupohoymexico.com\/puebla\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/grupohoymexico.com\/puebla\/#\/schema\/person\/8201f3fa49669f346d08e15801e0ebc2","name":"nestor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g","caption":"nestor"},"url":"https:\/\/grupohoymexico.com\/puebla\/author\/nestor\/"}]}},"_links":{"self":[{"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/posts\/82887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/comments?post=82887"}],"version-history":[{"count":1,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/posts\/82887\/revisions"}],"predecessor-version":[{"id":82888,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/posts\/82887\/revisions\/82888"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/media\/82889"}],"wp:attachment":[{"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/media?parent=82887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/categories?post=82887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/tags?post=82887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}