{"id":79214,"date":"2025-12-09T00:09:47","date_gmt":"2025-12-09T00:09:47","guid":{"rendered":"https:\/\/grupohoymexico.com\/puebla\/?p=79214"},"modified":"2025-12-09T00:09:48","modified_gmt":"2025-12-09T00:09:48","slug":"blanca-alcala-ruiz-se-acerca-al-pan","status":"publish","type":"post","link":"https:\/\/grupohoymexico.com\/puebla\/2025\/12\/09\/blanca-alcala-ruiz-se-acerca-al-pan\/","title":{"rendered":"Blanca Alcal\u00e1 Ruiz se acerca al PAN"},"content":{"rendered":"\n<p>Mario Riestra Pi\u00f1a, dirigente estatal del PAN en Puebla, confirm\u00f3 que ha sostenido pl\u00e1ticas con la priista Blanca Alcal\u00e1 Ruiz, a quien reconoci\u00f3 como una figura pol\u00edtica con relevancia rumbo a las elecciones de 2027. El l\u00edder blanquiazul se\u00f1al\u00f3 que, aunque no existe un acuerdo formal, s\u00ed se han explorado escenarios sobre una posible colaboraci\u00f3n.<\/p>\n\n\n\n<p>Alcal\u00e1 Ruiz, exalcaldesa de Puebla, revel\u00f3 recientemente que mantiene un distanciamiento con la dirigencia nacional del PRI debido a desacuerdos internos. Esa situaci\u00f3n la llev\u00f3 a decidir un a\u00f1o sab\u00e1tico en 2025, aunque ha manifestado su disposici\u00f3n para retomar actividad pol\u00edtica en 2026.<\/p>\n\n\n\n<p>Riestra Pi\u00f1a explic\u00f3 que, bajo la l\u00ednea impulsada por Jorge Romero, Acci\u00f3n Nacional pretende abrir sus puertas a perfiles ciudadanos y pol\u00edticos provenientes de otros partidos. Recalc\u00f3 que, en el caso de Alcal\u00e1, su futuro no est\u00e1 definido, pues ella tambi\u00e9n ha dialogado con otras fuerzas pol\u00edticas.<\/p>\n\n\n\n<p>\u201cEn el PAN mantenemos las puertas abiertas para liderazgos honestos, vengan del partido que vengan, as\u00ed como para ciudadanos sin afiliaci\u00f3n que quieran sumarse\u201d, coment\u00f3. <\/p>\n\n\n\n<p>Seg\u00fan informaci\u00f3n de Central Puebla, cualquier anuncio sobre la eventual incorporaci\u00f3n de Blanca Alcal\u00e1 al PAN podr\u00eda darse en enero de 2026.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.mundoejecutivopuebla.com\/#whatsapp\" rel=\"noreferrer noopener\" target=\"_blank\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"Mario Riestra Pi\u00f1a, dirigente estatal del PAN en Puebla, confirm\u00f3 que ha sostenido pl\u00e1ticas con la priista Blanca&hellip;","protected":false},"author":15,"featured_media":79216,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[26],"tags":[3274,1692,467],"class_list":{"0":"post-79214","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica","8":"tag-blanca-alcala-ruiz","9":"tag-pan","10":"tag-pri","11":"cs-entry","12":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.7 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Blanca Alcal\u00e1 Ruiz se acerca al PAN - Grupo Hoy Puebla<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/grupohoymexico.com\/puebla\/2025\/12\/09\/blanca-alcala-ruiz-se-acerca-al-pan\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blanca Alcal\u00e1 Ruiz se acerca al PAN\" \/>\n<meta property=\"og:description\" content=\"Mario Riestra Pi\u00f1a, dirigente estatal del PAN en Puebla, confirm\u00f3 que ha sostenido pl\u00e1ticas con la priista Blanca&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/grupohoymexico.com\/puebla\/2025\/12\/09\/blanca-alcala-ruiz-se-acerca-al-pan\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo Hoy Puebla\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-09T00:09:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-09T00:09:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/grupohoymexico.com\/puebla\/wp-content\/uploads\/sites\/3\/2025\/12\/5024206743761062546.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1201\" \/>\n\t<meta property=\"og:image:height\" content=\"639\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"nestor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"nestor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2025\\\/12\\\/09\\\/blanca-alcala-ruiz-se-acerca-al-pan\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2025\\\/12\\\/09\\\/blanca-alcala-ruiz-se-acerca-al-pan\\\/\"},\"author\":{\"name\":\"nestor\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/#\\\/schema\\\/person\\\/8201f3fa49669f346d08e15801e0ebc2\"},\"headline\":\"Blanca Alcal\u00e1 Ruiz se acerca al PAN\",\"datePublished\":\"2025-12-09T00:09:47+00:00\",\"dateModified\":\"2025-12-09T00:09:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2025\\\/12\\\/09\\\/blanca-alcala-ruiz-se-acerca-al-pan\\\/\"},\"wordCount\":217,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2025\\\/12\\\/09\\\/blanca-alcala-ruiz-se-acerca-al-pan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/12\\\/5024206743761062546.webp\",\"keywords\":[\"Blanca Alcal\u00e1 Ruiz\",\"PAN\",\"PRI\"],\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2025\\\/12\\\/09\\\/blanca-alcala-ruiz-se-acerca-al-pan\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2025\\\/12\\\/09\\\/blanca-alcala-ruiz-se-acerca-al-pan\\\/\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2025\\\/12\\\/09\\\/blanca-alcala-ruiz-se-acerca-al-pan\\\/\",\"name\":\"Blanca Alcal\u00e1 Ruiz se acerca al PAN - Grupo Hoy Puebla\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2025\\\/12\\\/09\\\/blanca-alcala-ruiz-se-acerca-al-pan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2025\\\/12\\\/09\\\/blanca-alcala-ruiz-se-acerca-al-pan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/12\\\/5024206743761062546.webp\",\"datePublished\":\"2025-12-09T00:09:47+00:00\",\"dateModified\":\"2025-12-09T00:09:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/#\\\/schema\\\/person\\\/8201f3fa49669f346d08e15801e0ebc2\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2025\\\/12\\\/09\\\/blanca-alcala-ruiz-se-acerca-al-pan\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2025\\\/12\\\/09\\\/blanca-alcala-ruiz-se-acerca-al-pan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2025\\\/12\\\/09\\\/blanca-alcala-ruiz-se-acerca-al-pan\\\/#primaryimage\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/12\\\/5024206743761062546.webp\",\"contentUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/12\\\/5024206743761062546.webp\",\"width\":1201,\"height\":639},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2025\\\/12\\\/09\\\/blanca-alcala-ruiz-se-acerca-al-pan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blanca Alcal\u00e1 Ruiz se acerca al PAN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/#website\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/\",\"name\":\"Grupo Hoy Puebla\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/#\\\/schema\\\/person\\\/8201f3fa49669f346d08e15801e0ebc2\",\"name\":\"nestor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g\",\"caption\":\"nestor\"},\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/author\\\/nestor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Blanca Alcal\u00e1 Ruiz se acerca al PAN - Grupo Hoy Puebla","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/grupohoymexico.com\/puebla\/2025\/12\/09\/blanca-alcala-ruiz-se-acerca-al-pan\/","og_locale":"es_MX","og_type":"article","og_title":"Blanca Alcal\u00e1 Ruiz se acerca al PAN","og_description":"Mario Riestra Pi\u00f1a, dirigente estatal del PAN en Puebla, confirm\u00f3 que ha sostenido pl\u00e1ticas con la priista Blanca&hellip;","og_url":"https:\/\/grupohoymexico.com\/puebla\/2025\/12\/09\/blanca-alcala-ruiz-se-acerca-al-pan\/","og_site_name":"Grupo Hoy Puebla","article_published_time":"2025-12-09T00:09:47+00:00","article_modified_time":"2025-12-09T00:09:48+00:00","og_image":[{"width":1201,"height":639,"url":"https:\/\/grupohoymexico.com\/puebla\/wp-content\/uploads\/sites\/3\/2025\/12\/5024206743761062546.webp","type":"image\/webp"}],"author":"nestor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"nestor","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/grupohoymexico.com\/puebla\/2025\/12\/09\/blanca-alcala-ruiz-se-acerca-al-pan\/#article","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/puebla\/2025\/12\/09\/blanca-alcala-ruiz-se-acerca-al-pan\/"},"author":{"name":"nestor","@id":"https:\/\/grupohoymexico.com\/puebla\/#\/schema\/person\/8201f3fa49669f346d08e15801e0ebc2"},"headline":"Blanca Alcal\u00e1 Ruiz se acerca al PAN","datePublished":"2025-12-09T00:09:47+00:00","dateModified":"2025-12-09T00:09:48+00:00","mainEntityOfPage":{"@id":"https:\/\/grupohoymexico.com\/puebla\/2025\/12\/09\/blanca-alcala-ruiz-se-acerca-al-pan\/"},"wordCount":217,"commentCount":0,"image":{"@id":"https:\/\/grupohoymexico.com\/puebla\/2025\/12\/09\/blanca-alcala-ruiz-se-acerca-al-pan\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/puebla\/wp-content\/uploads\/sites\/3\/2025\/12\/5024206743761062546.webp","keywords":["Blanca Alcal\u00e1 Ruiz","PAN","PRI"],"articleSection":["Pol\u00edtica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/grupohoymexico.com\/puebla\/2025\/12\/09\/blanca-alcala-ruiz-se-acerca-al-pan\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/grupohoymexico.com\/puebla\/2025\/12\/09\/blanca-alcala-ruiz-se-acerca-al-pan\/","url":"https:\/\/grupohoymexico.com\/puebla\/2025\/12\/09\/blanca-alcala-ruiz-se-acerca-al-pan\/","name":"Blanca Alcal\u00e1 Ruiz se acerca al PAN - Grupo Hoy Puebla","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/puebla\/#website"},"primaryImageOfPage":{"@id":"https:\/\/grupohoymexico.com\/puebla\/2025\/12\/09\/blanca-alcala-ruiz-se-acerca-al-pan\/#primaryimage"},"image":{"@id":"https:\/\/grupohoymexico.com\/puebla\/2025\/12\/09\/blanca-alcala-ruiz-se-acerca-al-pan\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/puebla\/wp-content\/uploads\/sites\/3\/2025\/12\/5024206743761062546.webp","datePublished":"2025-12-09T00:09:47+00:00","dateModified":"2025-12-09T00:09:48+00:00","author":{"@id":"https:\/\/grupohoymexico.com\/puebla\/#\/schema\/person\/8201f3fa49669f346d08e15801e0ebc2"},"breadcrumb":{"@id":"https:\/\/grupohoymexico.com\/puebla\/2025\/12\/09\/blanca-alcala-ruiz-se-acerca-al-pan\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/grupohoymexico.com\/puebla\/2025\/12\/09\/blanca-alcala-ruiz-se-acerca-al-pan\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/grupohoymexico.com\/puebla\/2025\/12\/09\/blanca-alcala-ruiz-se-acerca-al-pan\/#primaryimage","url":"https:\/\/grupohoymexico.com\/puebla\/wp-content\/uploads\/sites\/3\/2025\/12\/5024206743761062546.webp","contentUrl":"https:\/\/grupohoymexico.com\/puebla\/wp-content\/uploads\/sites\/3\/2025\/12\/5024206743761062546.webp","width":1201,"height":639},{"@type":"BreadcrumbList","@id":"https:\/\/grupohoymexico.com\/puebla\/2025\/12\/09\/blanca-alcala-ruiz-se-acerca-al-pan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/grupohoymexico.com\/puebla\/"},{"@type":"ListItem","position":2,"name":"Blanca Alcal\u00e1 Ruiz se acerca al PAN"}]},{"@type":"WebSite","@id":"https:\/\/grupohoymexico.com\/puebla\/#website","url":"https:\/\/grupohoymexico.com\/puebla\/","name":"Grupo Hoy Puebla","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/grupohoymexico.com\/puebla\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/grupohoymexico.com\/puebla\/#\/schema\/person\/8201f3fa49669f346d08e15801e0ebc2","name":"nestor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g","caption":"nestor"},"url":"https:\/\/grupohoymexico.com\/puebla\/author\/nestor\/"}]}},"_links":{"self":[{"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/posts\/79214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/comments?post=79214"}],"version-history":[{"count":2,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/posts\/79214\/revisions"}],"predecessor-version":[{"id":79217,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/posts\/79214\/revisions\/79217"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/media\/79216"}],"wp:attachment":[{"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/media?parent=79214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/categories?post=79214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/tags?post=79214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}