{"id":72509,"date":"2025-03-03T17:10:39","date_gmt":"2025-03-03T23:10:39","guid":{"rendered":"https:\/\/pueblahoy.com.mx\/?p=72509"},"modified":"2025-03-03T17:10:39","modified_gmt":"2025-03-03T23:10:39","slug":"puebla-registra-la-segunda-canasta-basica-mas-barata-en-el-pais","status":"publish","type":"post","link":"https:\/\/grupohoymexico.com\/puebla\/2025\/03\/03\/puebla-registra-la-segunda-canasta-basica-mas-barata-en-el-pais\/","title":{"rendered":"Puebla registra la segunda canasta b\u00e1sica m\u00e1s barata en el pa\u00eds"},"content":{"rendered":"\n<p><strong><a href=\"https:\/\/pueblahoy.com.mx\/\">Puebla<\/a><\/strong> se posicion\u00f3 como la segunda entidad con la canasta b\u00e1sica m\u00e1s barata en el pa\u00eds durante el periodo del 17 al 21 de febrero, de acuerdo con informaci\u00f3n de la <strong><a href=\"https:\/\/www.gob.mx\/profeco\">Procuradur\u00eda Federal del Consumidor (Profeco)<\/a><\/strong>. El costo de los productos esenciales alcanz\u00f3 los 771.80 pesos en la capital poblana.<\/p>\n\n\n\n<p>El titular de la Profeco, Iv\u00e1n Escalante, present\u00f3 el informe &#8220;Qui\u00e9n es Qui\u00e9n en los productos de primera necesidad&#8221; durante la conferencia matutina de la presidenta Claudia Sheinbaum. En el an\u00e1lisis, que abarc\u00f3 tres entidades, Puebla se ubic\u00f3 como la segunda con el precio m\u00e1s bajo de la canasta b\u00e1sica.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Supermercado con los mejores precios en Puebla<\/strong><\/h2>\n\n\n\n<p>El informe detall\u00f3 que el supermercado Chedraui ubicado en la calle 9 Poniente de la capital poblana, conocido como Chedraui UPAEP, ofrece la canasta b\u00e1sica a un precio de 771.80 pesos, por debajo del promedio nacional de 910 pesos. La primera posici\u00f3n en la lista la ocup\u00f3 otro supermercado de la misma cadena en Campeche, donde la canasta b\u00e1sica se vendi\u00f3 en 680 pesos.<\/p>\n\n\n\n<p>Cabe destacar que este establecimiento en Puebla ha figurado en varias ocasiones dentro del listado de supermercados con los precios m\u00e1s accesibles en el pa\u00eds.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Productos esenciales incluidos en la canasta b\u00e1sica<\/strong><\/h2>\n\n\n\n<p>De acuerdo con el gobierno federal, la canasta b\u00e1sica en M\u00e9xico est\u00e1 compuesta por granos b\u00e1sicos, carne, pescado, huevos, leche y otros l\u00e1cteos. Adem\u00e1s, incluye art\u00edculos de higiene personal, productos farmac\u00e9uticos, de limpieza, as\u00ed como frutas y verduras.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Supervisi\u00f3n a gasolineras y colocaci\u00f3n de lonas<\/strong><\/h2>\n\n\n\n<p>En el mismo reporte, Iv\u00e1n Escalante tambi\u00e9n hizo un recuento sobre la colocaci\u00f3n de lonas &#8220;No cargues aqu\u00ed&#8221; en estaciones de gasolina con irregularidades, una medida implementada desde el 8 de enero. <\/p>\n\n\n\n<p>En total, se han instalado 34 lonas en distintos puntos del pa\u00eds, una de ellas en Puebla, como parte de las acciones de vigilancia del sector.<\/p>\n","protected":false},"excerpt":{"rendered":"Puebla se posicion\u00f3 como la segunda entidad con la canasta b\u00e1sica m\u00e1s barata en el pa\u00eds durante el&hellip;","protected":false},"author":1,"featured_media":72520,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[29],"tags":[],"class_list":{"0":"post-72509","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-estatal","8":"cs-entry","9":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.7 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Puebla registra la segunda canasta b\u00e1sica m\u00e1s barata en el pa\u00eds - Grupo Hoy Puebla<\/title>\n<meta name=\"description\" content=\"Puebla se posicion\u00f3 como la segunda entidad con la canasta b\u00e1sica m\u00e1s barata en el pa\u00eds durante el periodo del 17 al 21 de febrero.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/grupohoymexico.com\/puebla\/2025\/03\/03\/puebla-registra-la-segunda-canasta-basica-mas-barata-en-el-pais\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Puebla registra la segunda canasta b\u00e1sica m\u00e1s barata en el pa\u00eds\" \/>\n<meta property=\"og:description\" content=\"Puebla se posicion\u00f3 como la segunda entidad con la canasta b\u00e1sica m\u00e1s barata en el pa\u00eds durante el periodo del 17 al 21 de febrero.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/grupohoymexico.com\/puebla\/2025\/03\/03\/puebla-registra-la-segunda-canasta-basica-mas-barata-en-el-pais\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo Hoy Puebla\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-03T23:10:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/grupohoymexico.com\/puebla\/wp-content\/uploads\/sites\/3\/2025\/03\/photo_5058052211791212012_y.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2025\\\/03\\\/03\\\/puebla-registra-la-segunda-canasta-basica-mas-barata-en-el-pais\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2025\\\/03\\\/03\\\/puebla-registra-la-segunda-canasta-basica-mas-barata-en-el-pais\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/#\\\/schema\\\/person\\\/ce6086ac837852775a3a4f539356c297\"},\"headline\":\"Puebla registra la segunda canasta b\u00e1sica m\u00e1s barata en el pa\u00eds\",\"datePublished\":\"2025-03-03T23:10:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2025\\\/03\\\/03\\\/puebla-registra-la-segunda-canasta-basica-mas-barata-en-el-pais\\\/\"},\"wordCount\":341,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2025\\\/03\\\/03\\\/puebla-registra-la-segunda-canasta-basica-mas-barata-en-el-pais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/03\\\/photo_5058052211791212012_y.jpg\",\"articleSection\":[\"Estados\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2025\\\/03\\\/03\\\/puebla-registra-la-segunda-canasta-basica-mas-barata-en-el-pais\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2025\\\/03\\\/03\\\/puebla-registra-la-segunda-canasta-basica-mas-barata-en-el-pais\\\/\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2025\\\/03\\\/03\\\/puebla-registra-la-segunda-canasta-basica-mas-barata-en-el-pais\\\/\",\"name\":\"Puebla registra la segunda canasta b\u00e1sica m\u00e1s barata en el pa\u00eds - Grupo Hoy Puebla\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2025\\\/03\\\/03\\\/puebla-registra-la-segunda-canasta-basica-mas-barata-en-el-pais\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2025\\\/03\\\/03\\\/puebla-registra-la-segunda-canasta-basica-mas-barata-en-el-pais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/03\\\/photo_5058052211791212012_y.jpg\",\"datePublished\":\"2025-03-03T23:10:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/#\\\/schema\\\/person\\\/ce6086ac837852775a3a4f539356c297\"},\"description\":\"Puebla se posicion\u00f3 como la segunda entidad con la canasta b\u00e1sica m\u00e1s barata en el pa\u00eds durante el periodo del 17 al 21 de febrero.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2025\\\/03\\\/03\\\/puebla-registra-la-segunda-canasta-basica-mas-barata-en-el-pais\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2025\\\/03\\\/03\\\/puebla-registra-la-segunda-canasta-basica-mas-barata-en-el-pais\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2025\\\/03\\\/03\\\/puebla-registra-la-segunda-canasta-basica-mas-barata-en-el-pais\\\/#primaryimage\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/03\\\/photo_5058052211791212012_y.jpg\",\"contentUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/03\\\/photo_5058052211791212012_y.jpg\",\"width\":1280,\"height\":680,\"caption\":\"Puebla registra la segunda canasta b\u00e1sica m\u00e1s barata en el pa\u00eds\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2025\\\/03\\\/03\\\/puebla-registra-la-segunda-canasta-basica-mas-barata-en-el-pais\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Puebla registra la segunda canasta b\u00e1sica m\u00e1s barata en el pa\u00eds\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/#website\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/\",\"name\":\"Grupo Hoy Puebla\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/#\\\/schema\\\/person\\\/ce6086ac837852775a3a4f539356c297\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\\\/\\\/44.197.188.197.nip.io\"],\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/author\\\/user\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Puebla registra la segunda canasta b\u00e1sica m\u00e1s barata en el pa\u00eds - Grupo Hoy Puebla","description":"Puebla se posicion\u00f3 como la segunda entidad con la canasta b\u00e1sica m\u00e1s barata en el pa\u00eds durante el periodo del 17 al 21 de febrero.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/grupohoymexico.com\/puebla\/2025\/03\/03\/puebla-registra-la-segunda-canasta-basica-mas-barata-en-el-pais\/","og_locale":"es_MX","og_type":"article","og_title":"Puebla registra la segunda canasta b\u00e1sica m\u00e1s barata en el pa\u00eds","og_description":"Puebla se posicion\u00f3 como la segunda entidad con la canasta b\u00e1sica m\u00e1s barata en el pa\u00eds durante el periodo del 17 al 21 de febrero.","og_url":"https:\/\/grupohoymexico.com\/puebla\/2025\/03\/03\/puebla-registra-la-segunda-canasta-basica-mas-barata-en-el-pais\/","og_site_name":"Grupo Hoy Puebla","article_published_time":"2025-03-03T23:10:39+00:00","og_image":[{"width":1280,"height":680,"url":"https:\/\/grupohoymexico.com\/puebla\/wp-content\/uploads\/sites\/3\/2025\/03\/photo_5058052211791212012_y.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"user","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/grupohoymexico.com\/puebla\/2025\/03\/03\/puebla-registra-la-segunda-canasta-basica-mas-barata-en-el-pais\/#article","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/puebla\/2025\/03\/03\/puebla-registra-la-segunda-canasta-basica-mas-barata-en-el-pais\/"},"author":{"name":"user","@id":"https:\/\/grupohoymexico.com\/puebla\/#\/schema\/person\/ce6086ac837852775a3a4f539356c297"},"headline":"Puebla registra la segunda canasta b\u00e1sica m\u00e1s barata en el pa\u00eds","datePublished":"2025-03-03T23:10:39+00:00","mainEntityOfPage":{"@id":"https:\/\/grupohoymexico.com\/puebla\/2025\/03\/03\/puebla-registra-la-segunda-canasta-basica-mas-barata-en-el-pais\/"},"wordCount":341,"commentCount":0,"image":{"@id":"https:\/\/grupohoymexico.com\/puebla\/2025\/03\/03\/puebla-registra-la-segunda-canasta-basica-mas-barata-en-el-pais\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/puebla\/wp-content\/uploads\/sites\/3\/2025\/03\/photo_5058052211791212012_y.jpg","articleSection":["Estados"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/grupohoymexico.com\/puebla\/2025\/03\/03\/puebla-registra-la-segunda-canasta-basica-mas-barata-en-el-pais\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/grupohoymexico.com\/puebla\/2025\/03\/03\/puebla-registra-la-segunda-canasta-basica-mas-barata-en-el-pais\/","url":"https:\/\/grupohoymexico.com\/puebla\/2025\/03\/03\/puebla-registra-la-segunda-canasta-basica-mas-barata-en-el-pais\/","name":"Puebla registra la segunda canasta b\u00e1sica m\u00e1s barata en el pa\u00eds - Grupo Hoy Puebla","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/puebla\/#website"},"primaryImageOfPage":{"@id":"https:\/\/grupohoymexico.com\/puebla\/2025\/03\/03\/puebla-registra-la-segunda-canasta-basica-mas-barata-en-el-pais\/#primaryimage"},"image":{"@id":"https:\/\/grupohoymexico.com\/puebla\/2025\/03\/03\/puebla-registra-la-segunda-canasta-basica-mas-barata-en-el-pais\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/puebla\/wp-content\/uploads\/sites\/3\/2025\/03\/photo_5058052211791212012_y.jpg","datePublished":"2025-03-03T23:10:39+00:00","author":{"@id":"https:\/\/grupohoymexico.com\/puebla\/#\/schema\/person\/ce6086ac837852775a3a4f539356c297"},"description":"Puebla se posicion\u00f3 como la segunda entidad con la canasta b\u00e1sica m\u00e1s barata en el pa\u00eds durante el periodo del 17 al 21 de febrero.","breadcrumb":{"@id":"https:\/\/grupohoymexico.com\/puebla\/2025\/03\/03\/puebla-registra-la-segunda-canasta-basica-mas-barata-en-el-pais\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/grupohoymexico.com\/puebla\/2025\/03\/03\/puebla-registra-la-segunda-canasta-basica-mas-barata-en-el-pais\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/grupohoymexico.com\/puebla\/2025\/03\/03\/puebla-registra-la-segunda-canasta-basica-mas-barata-en-el-pais\/#primaryimage","url":"https:\/\/grupohoymexico.com\/puebla\/wp-content\/uploads\/sites\/3\/2025\/03\/photo_5058052211791212012_y.jpg","contentUrl":"https:\/\/grupohoymexico.com\/puebla\/wp-content\/uploads\/sites\/3\/2025\/03\/photo_5058052211791212012_y.jpg","width":1280,"height":680,"caption":"Puebla registra la segunda canasta b\u00e1sica m\u00e1s barata en el pa\u00eds"},{"@type":"BreadcrumbList","@id":"https:\/\/grupohoymexico.com\/puebla\/2025\/03\/03\/puebla-registra-la-segunda-canasta-basica-mas-barata-en-el-pais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/grupohoymexico.com\/puebla\/"},{"@type":"ListItem","position":2,"name":"Puebla registra la segunda canasta b\u00e1sica m\u00e1s barata en el pa\u00eds"}]},{"@type":"WebSite","@id":"https:\/\/grupohoymexico.com\/puebla\/#website","url":"https:\/\/grupohoymexico.com\/puebla\/","name":"Grupo Hoy Puebla","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/grupohoymexico.com\/puebla\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/grupohoymexico.com\/puebla\/#\/schema\/person\/ce6086ac837852775a3a4f539356c297","name":"user","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:\/\/44.197.188.197.nip.io"],"url":"https:\/\/grupohoymexico.com\/puebla\/author\/user\/"}]}},"_links":{"self":[{"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/posts\/72509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/comments?post=72509"}],"version-history":[{"count":0,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/posts\/72509\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/media\/72520"}],"wp:attachment":[{"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/media?parent=72509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/categories?post=72509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/tags?post=72509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}