{"id":65311,"date":"2024-01-24T15:00:11","date_gmt":"2024-01-24T21:00:11","guid":{"rendered":"https:\/\/pueblahoy.com.mx\/?p=65311"},"modified":"2024-01-24T15:00:11","modified_gmt":"2024-01-24T21:00:11","slug":"anuncian-primera-donacion-multiorganica-en-este-2024","status":"publish","type":"post","link":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/24\/anuncian-primera-donacion-multiorganica-en-este-2024\/","title":{"rendered":"Anuncian primera donaci\u00f3n multiorg\u00e1nica en este 2024"},"content":{"rendered":"<p>El Hospital Regional de Alta Especialidad (HRAE) Puebla, perteneciente al Instituto de Seguridad y Servicios Sociales de los Trabajadores del Estado (ISSSTE), celebr\u00f3 el pasado 14 de enero su primera donaci\u00f3n multiorg\u00e1nica del a\u00f1o 2024. Esta generosa acci\u00f3n permiti\u00f3 obtener ri\u00f1ones y c\u00f3rneas, brindando una nueva oportunidad de vida a tres personas.<\/p>\n<p>La hero\u00edna donante, una mujer de 45 a\u00f1os y maestra, derechohabiente del municipio de Zihuateutla, <a href=\"https:\/\/pueblahoy.com.mx\/el-ayuntamiento-de-puebla-clausurara-definitivamente-bares-y-antros-por-incumplir-reglamento\/\">Puebla<\/a>, lamentablemente present\u00f3 muerte cerebral.<\/p>\n<p>El director general del ISSSTE, Pedro Zenteno Santaella, expres\u00f3 su profundo agradecimiento a la familia de la donante por tomar la decisi\u00f3n de realizar esta acto tan generoso en un momento tan dif\u00edcil. Invit\u00f3 a la poblaci\u00f3n a unirse a esta cadena de ayuda humanitaria y registrarse como donantes voluntarios en el Centro Nacional de Trasplantes (Cenatra) a trav\u00e9s de <a href=\"https:\/\/goo.su\/ucv7l\" target=\"_new\" rel=\"noopener\">https:\/\/goo.su\/ucv7l<\/a>.<\/p>\n<p>Zenteno Santaella destac\u00f3 la importancia de la donaci\u00f3n de \u00f3rganos y subray\u00f3 que todos, en alg\u00fan momento de la vida, podr\u00edamos requerir un trasplante. Registrarse como donante voluntario no solo puede ser una oportunidad de salud para otros, sino tambi\u00e9n una forma de contribuir a la esperanza y la vida.<\/p>\n<p>La instituci\u00f3n agradeci\u00f3 a la hero\u00edna donante y a su familia por este acto de generosidad que ha impactado de manera positiva en la vida de aquellos que han recibido estos valiosos \u00f3rganos. La donaci\u00f3n de \u00f3rganos sigue siendo una acci\u00f3n fundamental para mejorar la calidad de vida de quienes enfrentan condiciones m\u00e9dicas cr\u00edticas.<\/p>\n","protected":false},"excerpt":{"rendered":"El Hospital Regional de Alta Especialidad (HRAE) Puebla, perteneciente al Instituto de Seguridad y Servicios Sociales de los&hellip;","protected":false},"author":1,"featured_media":65318,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[29],"tags":[],"class_list":["post-65311","post","type-post","status-publish","format-standard","has-post-thumbnail","category-estatal","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Anuncian primera donaci\u00f3n multiorg\u00e1nica en este 2024 - Grupo Hoy Puebla<\/title>\n<meta name=\"description\" content=\"El Hospital Regional de Alta Especialidad (HRAE) Puebla realiza su primera donaci\u00f3n multiorg\u00e1nica de 2024.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/24\/anuncian-primera-donacion-multiorganica-en-este-2024\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anuncian primera donaci\u00f3n multiorg\u00e1nica en este 2024\" \/>\n<meta property=\"og:description\" content=\"El Hospital Regional de Alta Especialidad (HRAE) Puebla realiza su primera donaci\u00f3n multiorg\u00e1nica de 2024.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/24\/anuncian-primera-donacion-multiorganica-en-este-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo Hoy Puebla\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-24T21:00:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/grupohoymexico.com\/puebla\/wp-content\/uploads\/sites\/3\/2024\/01\/img-01-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/24\\\/anuncian-primera-donacion-multiorganica-en-este-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/24\\\/anuncian-primera-donacion-multiorganica-en-este-2024\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/#\\\/schema\\\/person\\\/ce6086ac837852775a3a4f539356c297\"},\"headline\":\"Anuncian primera donaci\u00f3n multiorg\u00e1nica en este 2024\",\"datePublished\":\"2024-01-24T21:00:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/24\\\/anuncian-primera-donacion-multiorganica-en-este-2024\\\/\"},\"wordCount\":268,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/24\\\/anuncian-primera-donacion-multiorganica-en-este-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/01\\\/img-01-1.jpg\",\"articleSection\":[\"Estados\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/24\\\/anuncian-primera-donacion-multiorganica-en-este-2024\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/24\\\/anuncian-primera-donacion-multiorganica-en-este-2024\\\/\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/24\\\/anuncian-primera-donacion-multiorganica-en-este-2024\\\/\",\"name\":\"Anuncian primera donaci\u00f3n multiorg\u00e1nica en este 2024 - Grupo Hoy Puebla\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/24\\\/anuncian-primera-donacion-multiorganica-en-este-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/24\\\/anuncian-primera-donacion-multiorganica-en-este-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/01\\\/img-01-1.jpg\",\"datePublished\":\"2024-01-24T21:00:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/#\\\/schema\\\/person\\\/ce6086ac837852775a3a4f539356c297\"},\"description\":\"El Hospital Regional de Alta Especialidad (HRAE) Puebla realiza su primera donaci\u00f3n multiorg\u00e1nica de 2024.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/24\\\/anuncian-primera-donacion-multiorganica-en-este-2024\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/24\\\/anuncian-primera-donacion-multiorganica-en-este-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/24\\\/anuncian-primera-donacion-multiorganica-en-este-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/01\\\/img-01-1.jpg\",\"contentUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/01\\\/img-01-1.jpg\",\"width\":800,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/24\\\/anuncian-primera-donacion-multiorganica-en-este-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anuncian primera donaci\u00f3n multiorg\u00e1nica en este 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/#website\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/\",\"name\":\"Grupo Hoy Puebla\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/#\\\/schema\\\/person\\\/ce6086ac837852775a3a4f539356c297\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\\\/\\\/44.197.188.197.nip.io\"],\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/author\\\/user\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Anuncian primera donaci\u00f3n multiorg\u00e1nica en este 2024 - Grupo Hoy Puebla","description":"El Hospital Regional de Alta Especialidad (HRAE) Puebla realiza su primera donaci\u00f3n multiorg\u00e1nica de 2024.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/24\/anuncian-primera-donacion-multiorganica-en-este-2024\/","og_locale":"es_MX","og_type":"article","og_title":"Anuncian primera donaci\u00f3n multiorg\u00e1nica en este 2024","og_description":"El Hospital Regional de Alta Especialidad (HRAE) Puebla realiza su primera donaci\u00f3n multiorg\u00e1nica de 2024.","og_url":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/24\/anuncian-primera-donacion-multiorganica-en-este-2024\/","og_site_name":"Grupo Hoy Puebla","article_published_time":"2024-01-24T21:00:11+00:00","og_image":[{"width":800,"height":500,"url":"https:\/\/grupohoymexico.com\/puebla\/wp-content\/uploads\/sites\/3\/2024\/01\/img-01-1.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"user","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/24\/anuncian-primera-donacion-multiorganica-en-este-2024\/#article","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/24\/anuncian-primera-donacion-multiorganica-en-este-2024\/"},"author":{"name":"user","@id":"https:\/\/grupohoymexico.com\/puebla\/#\/schema\/person\/ce6086ac837852775a3a4f539356c297"},"headline":"Anuncian primera donaci\u00f3n multiorg\u00e1nica en este 2024","datePublished":"2024-01-24T21:00:11+00:00","mainEntityOfPage":{"@id":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/24\/anuncian-primera-donacion-multiorganica-en-este-2024\/"},"wordCount":268,"commentCount":0,"image":{"@id":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/24\/anuncian-primera-donacion-multiorganica-en-este-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/puebla\/wp-content\/uploads\/sites\/3\/2024\/01\/img-01-1.jpg","articleSection":["Estados"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/grupohoymexico.com\/puebla\/2024\/01\/24\/anuncian-primera-donacion-multiorganica-en-este-2024\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/24\/anuncian-primera-donacion-multiorganica-en-este-2024\/","url":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/24\/anuncian-primera-donacion-multiorganica-en-este-2024\/","name":"Anuncian primera donaci\u00f3n multiorg\u00e1nica en este 2024 - Grupo Hoy Puebla","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/puebla\/#website"},"primaryImageOfPage":{"@id":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/24\/anuncian-primera-donacion-multiorganica-en-este-2024\/#primaryimage"},"image":{"@id":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/24\/anuncian-primera-donacion-multiorganica-en-este-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/puebla\/wp-content\/uploads\/sites\/3\/2024\/01\/img-01-1.jpg","datePublished":"2024-01-24T21:00:11+00:00","author":{"@id":"https:\/\/grupohoymexico.com\/puebla\/#\/schema\/person\/ce6086ac837852775a3a4f539356c297"},"description":"El Hospital Regional de Alta Especialidad (HRAE) Puebla realiza su primera donaci\u00f3n multiorg\u00e1nica de 2024.","breadcrumb":{"@id":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/24\/anuncian-primera-donacion-multiorganica-en-este-2024\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/grupohoymexico.com\/puebla\/2024\/01\/24\/anuncian-primera-donacion-multiorganica-en-este-2024\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/24\/anuncian-primera-donacion-multiorganica-en-este-2024\/#primaryimage","url":"https:\/\/grupohoymexico.com\/puebla\/wp-content\/uploads\/sites\/3\/2024\/01\/img-01-1.jpg","contentUrl":"https:\/\/grupohoymexico.com\/puebla\/wp-content\/uploads\/sites\/3\/2024\/01\/img-01-1.jpg","width":800,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/24\/anuncian-primera-donacion-multiorganica-en-este-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/grupohoymexico.com\/puebla\/"},{"@type":"ListItem","position":2,"name":"Anuncian primera donaci\u00f3n multiorg\u00e1nica en este 2024"}]},{"@type":"WebSite","@id":"https:\/\/grupohoymexico.com\/puebla\/#website","url":"https:\/\/grupohoymexico.com\/puebla\/","name":"Grupo Hoy Puebla","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/grupohoymexico.com\/puebla\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/grupohoymexico.com\/puebla\/#\/schema\/person\/ce6086ac837852775a3a4f539356c297","name":"user","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:\/\/44.197.188.197.nip.io"],"url":"https:\/\/grupohoymexico.com\/puebla\/author\/user\/"}]}},"_links":{"self":[{"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/posts\/65311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/comments?post=65311"}],"version-history":[{"count":0,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/posts\/65311\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/media\/65318"}],"wp:attachment":[{"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/media?parent=65311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/categories?post=65311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/tags?post=65311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}