{"id":65240,"date":"2024-01-22T13:00:58","date_gmt":"2024-01-22T19:00:58","guid":{"rendered":"https:\/\/pueblahoy.com.mx\/?p=65240"},"modified":"2024-01-22T13:00:58","modified_gmt":"2024-01-22T19:00:58","slug":"alejandro-armenta-resalta-la-eficiencia-presupuestal-en-la-era-de-la-4t","status":"publish","type":"post","link":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/22\/alejandro-armenta-resalta-la-eficiencia-presupuestal-en-la-era-de-la-4t\/","title":{"rendered":"Alejandro Armenta resalta la eficiencia presupuestal en la era de la 4T"},"content":{"rendered":"<p>En una serie de foros y reuniones con diversos sectores de la sociedad, el senador <a href=\"https:\/\/es.wikipedia.org\/wiki\/Alejandro_Armenta_Mier\">Alejandro Armenta<\/a> ha destacado la eficiencia presupuestal alcanzada por el gobierno del presidente Andr\u00e9s Manuel L\u00f3pez Obrador, subrayando el papel crucial de la lucha contra la corrupci\u00f3n en este logro. Durante sus intervenciones, Armenta enfatiz\u00f3 el contraste entre el presupuesto ejercido en 2023, durante el quinto a\u00f1o de la administraci\u00f3n de L\u00f3pez Obrador, y los gastos del \u00faltimo a\u00f1o del gobierno anterior<a href=\"https:\/\/pueblahoy.com.mx\/\">.<\/a><\/p>\n<blockquote><p><em><strong>\u201cEl a\u00f1o 2023, siendo el quinto de la Cuarta Transformaci\u00f3n (4T), marc\u00f3 un hito en la historia de M\u00e9xico con un presupuesto honesto de 533 millones de pesos, notablemente inferior a los 3 mil 681 millones gastados en 2018&#8243;<\/strong><\/em>, declar\u00f3 Armenta, resaltando el compromiso del actual gobierno con la transparencia y la eficiencia en la gesti\u00f3n de los recursos p\u00fablicos.<\/p><\/blockquote>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/imagenes.razon.com.mx\/files\/image_940_470\/uploads\/2024\/01\/21\/65adb0132a524.jpeg\" alt=\"\" width=\"940\" height=\"470\" \/><\/p>\n<p>El senador por Morena enfatiz\u00f3 la importancia de la austeridad republicana, una pol\u00edtica que, seg\u00fan \u00e9l, representa una gran responsabilidad en el manejo del gasto p\u00fablico. Alejandro Armenta asegur\u00f3 que esta pol\u00edtica se orienta principalmente hacia proyectos de inversi\u00f3n en sectores clave como educaci\u00f3n, salud y seguridad. \u201cEsto es el Humanismo Mexicano, esto es la Cuarta Transformaci\u00f3n\u201d, afirm\u00f3.<\/p>\n<blockquote><p>En sus discursos, Alejandro Armenta comparti\u00f3 su visi\u00f3n de un gobierno alineado con los intereses del pueblo: <em><strong>\u201cNo puede haber un gobierno rico con un pueblo pobre. La prioridad de nuestra lucha democr\u00e1tica debe ser siempre el bienestar del pueblo mexicano, y eso es posible gracias a la transformaci\u00f3n que vive M\u00e9xico\u201d<\/strong><\/em>.<\/p><\/blockquote>\n<p>Con la mirada puesta en el pr\u00f3ximo 5 de febrero, aniversario de la Promulgaci\u00f3n de la Constituci\u00f3n Mexicana, Armenta resalt\u00f3 el anuncio del presidente Andr\u00e9s Manuel L\u00f3pez Obrador sobre un paquete de iniciativas de reformas. Estas reformas, seg\u00fan el senador, est\u00e1n relacionadas con temas cr\u00edticos como el bienestar social, salarios, pensiones, el Poder Judicial y el \u00e1mbito electoral.<\/p>\n<p>El senador adelant\u00f3 que estas iniciativas buscan adecuar el marco legal a \u201ceste M\u00e9xico que exige transparencia y honestidad por parte de todos los actores pol\u00edticos y en el ejercicio de los recursos que deben servir al pueblo\u201d. Con estas palabras, Armenta reafirma su compromiso y el del gobierno de L\u00f3pez Obrador con la transformaci\u00f3n de M\u00e9xico hacia un modelo de gobernanza m\u00e1s justo y equitativo.<\/p>\n","protected":false},"excerpt":{"rendered":"En una serie de foros y reuniones con diversos sectores de la sociedad, el senador Alejandro Armenta ha&hellip;","protected":false},"author":1,"featured_media":65241,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[26],"tags":[],"class_list":{"0":"post-65240","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica","8":"cs-entry","9":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.7 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Alejandro Armenta resalta la eficiencia presupuestal en la era de la 4T - Grupo Hoy Puebla<\/title>\n<meta name=\"description\" content=\"Alejandro Armenta ha destacado la eficiencia presupuestal alcanzada por el gobierno del presidente Andr\u00e9s Manuel L\u00f3pez Obrador.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/22\/alejandro-armenta-resalta-la-eficiencia-presupuestal-en-la-era-de-la-4t\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alejandro Armenta resalta la eficiencia presupuestal en la era de la 4T\" \/>\n<meta property=\"og:description\" content=\"Alejandro Armenta ha destacado la eficiencia presupuestal alcanzada por el gobierno del presidente Andr\u00e9s Manuel L\u00f3pez Obrador.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/22\/alejandro-armenta-resalta-la-eficiencia-presupuestal-en-la-era-de-la-4t\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo Hoy Puebla\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-22T19:00:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/grupohoymexico.com\/puebla\/wp-content\/uploads\/sites\/3\/2024\/01\/1900-PUEBLA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/22\\\/alejandro-armenta-resalta-la-eficiencia-presupuestal-en-la-era-de-la-4t\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/22\\\/alejandro-armenta-resalta-la-eficiencia-presupuestal-en-la-era-de-la-4t\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/#\\\/schema\\\/person\\\/ce6086ac837852775a3a4f539356c297\"},\"headline\":\"Alejandro Armenta resalta la eficiencia presupuestal en la era de la 4T\",\"datePublished\":\"2024-01-22T19:00:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/22\\\/alejandro-armenta-resalta-la-eficiencia-presupuestal-en-la-era-de-la-4t\\\/\"},\"wordCount\":413,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/22\\\/alejandro-armenta-resalta-la-eficiencia-presupuestal-en-la-era-de-la-4t\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/01\\\/1900-PUEBLA.jpg\",\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/22\\\/alejandro-armenta-resalta-la-eficiencia-presupuestal-en-la-era-de-la-4t\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/22\\\/alejandro-armenta-resalta-la-eficiencia-presupuestal-en-la-era-de-la-4t\\\/\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/22\\\/alejandro-armenta-resalta-la-eficiencia-presupuestal-en-la-era-de-la-4t\\\/\",\"name\":\"Alejandro Armenta resalta la eficiencia presupuestal en la era de la 4T - Grupo Hoy Puebla\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/22\\\/alejandro-armenta-resalta-la-eficiencia-presupuestal-en-la-era-de-la-4t\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/22\\\/alejandro-armenta-resalta-la-eficiencia-presupuestal-en-la-era-de-la-4t\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/01\\\/1900-PUEBLA.jpg\",\"datePublished\":\"2024-01-22T19:00:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/#\\\/schema\\\/person\\\/ce6086ac837852775a3a4f539356c297\"},\"description\":\"Alejandro Armenta ha destacado la eficiencia presupuestal alcanzada por el gobierno del presidente Andr\u00e9s Manuel L\u00f3pez Obrador.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/22\\\/alejandro-armenta-resalta-la-eficiencia-presupuestal-en-la-era-de-la-4t\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/22\\\/alejandro-armenta-resalta-la-eficiencia-presupuestal-en-la-era-de-la-4t\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/22\\\/alejandro-armenta-resalta-la-eficiencia-presupuestal-en-la-era-de-la-4t\\\/#primaryimage\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/01\\\/1900-PUEBLA.jpg\",\"contentUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/01\\\/1900-PUEBLA.jpg\",\"width\":1000,\"height\":600,\"caption\":\"Alejandro Armenta resalta la eficiencia presupuestal en la era de la 4T\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/22\\\/alejandro-armenta-resalta-la-eficiencia-presupuestal-en-la-era-de-la-4t\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alejandro Armenta resalta la eficiencia presupuestal en la era de la 4T\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/#website\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/\",\"name\":\"Grupo Hoy Puebla\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/#\\\/schema\\\/person\\\/ce6086ac837852775a3a4f539356c297\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\\\/\\\/44.197.188.197.nip.io\"],\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/author\\\/user\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Alejandro Armenta resalta la eficiencia presupuestal en la era de la 4T - Grupo Hoy Puebla","description":"Alejandro Armenta ha destacado la eficiencia presupuestal alcanzada por el gobierno del presidente Andr\u00e9s Manuel L\u00f3pez Obrador.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/22\/alejandro-armenta-resalta-la-eficiencia-presupuestal-en-la-era-de-la-4t\/","og_locale":"es_MX","og_type":"article","og_title":"Alejandro Armenta resalta la eficiencia presupuestal en la era de la 4T","og_description":"Alejandro Armenta ha destacado la eficiencia presupuestal alcanzada por el gobierno del presidente Andr\u00e9s Manuel L\u00f3pez Obrador.","og_url":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/22\/alejandro-armenta-resalta-la-eficiencia-presupuestal-en-la-era-de-la-4t\/","og_site_name":"Grupo Hoy Puebla","article_published_time":"2024-01-22T19:00:58+00:00","og_image":[{"width":1000,"height":600,"url":"https:\/\/grupohoymexico.com\/puebla\/wp-content\/uploads\/sites\/3\/2024\/01\/1900-PUEBLA.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"user","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/22\/alejandro-armenta-resalta-la-eficiencia-presupuestal-en-la-era-de-la-4t\/#article","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/22\/alejandro-armenta-resalta-la-eficiencia-presupuestal-en-la-era-de-la-4t\/"},"author":{"name":"user","@id":"https:\/\/grupohoymexico.com\/puebla\/#\/schema\/person\/ce6086ac837852775a3a4f539356c297"},"headline":"Alejandro Armenta resalta la eficiencia presupuestal en la era de la 4T","datePublished":"2024-01-22T19:00:58+00:00","mainEntityOfPage":{"@id":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/22\/alejandro-armenta-resalta-la-eficiencia-presupuestal-en-la-era-de-la-4t\/"},"wordCount":413,"commentCount":0,"image":{"@id":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/22\/alejandro-armenta-resalta-la-eficiencia-presupuestal-en-la-era-de-la-4t\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/puebla\/wp-content\/uploads\/sites\/3\/2024\/01\/1900-PUEBLA.jpg","articleSection":["Pol\u00edtica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/grupohoymexico.com\/puebla\/2024\/01\/22\/alejandro-armenta-resalta-la-eficiencia-presupuestal-en-la-era-de-la-4t\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/22\/alejandro-armenta-resalta-la-eficiencia-presupuestal-en-la-era-de-la-4t\/","url":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/22\/alejandro-armenta-resalta-la-eficiencia-presupuestal-en-la-era-de-la-4t\/","name":"Alejandro Armenta resalta la eficiencia presupuestal en la era de la 4T - Grupo Hoy Puebla","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/puebla\/#website"},"primaryImageOfPage":{"@id":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/22\/alejandro-armenta-resalta-la-eficiencia-presupuestal-en-la-era-de-la-4t\/#primaryimage"},"image":{"@id":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/22\/alejandro-armenta-resalta-la-eficiencia-presupuestal-en-la-era-de-la-4t\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/puebla\/wp-content\/uploads\/sites\/3\/2024\/01\/1900-PUEBLA.jpg","datePublished":"2024-01-22T19:00:58+00:00","author":{"@id":"https:\/\/grupohoymexico.com\/puebla\/#\/schema\/person\/ce6086ac837852775a3a4f539356c297"},"description":"Alejandro Armenta ha destacado la eficiencia presupuestal alcanzada por el gobierno del presidente Andr\u00e9s Manuel L\u00f3pez Obrador.","breadcrumb":{"@id":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/22\/alejandro-armenta-resalta-la-eficiencia-presupuestal-en-la-era-de-la-4t\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/grupohoymexico.com\/puebla\/2024\/01\/22\/alejandro-armenta-resalta-la-eficiencia-presupuestal-en-la-era-de-la-4t\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/22\/alejandro-armenta-resalta-la-eficiencia-presupuestal-en-la-era-de-la-4t\/#primaryimage","url":"https:\/\/grupohoymexico.com\/puebla\/wp-content\/uploads\/sites\/3\/2024\/01\/1900-PUEBLA.jpg","contentUrl":"https:\/\/grupohoymexico.com\/puebla\/wp-content\/uploads\/sites\/3\/2024\/01\/1900-PUEBLA.jpg","width":1000,"height":600,"caption":"Alejandro Armenta resalta la eficiencia presupuestal en la era de la 4T"},{"@type":"BreadcrumbList","@id":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/22\/alejandro-armenta-resalta-la-eficiencia-presupuestal-en-la-era-de-la-4t\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/grupohoymexico.com\/puebla\/"},{"@type":"ListItem","position":2,"name":"Alejandro Armenta resalta la eficiencia presupuestal en la era de la 4T"}]},{"@type":"WebSite","@id":"https:\/\/grupohoymexico.com\/puebla\/#website","url":"https:\/\/grupohoymexico.com\/puebla\/","name":"Grupo Hoy Puebla","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/grupohoymexico.com\/puebla\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/grupohoymexico.com\/puebla\/#\/schema\/person\/ce6086ac837852775a3a4f539356c297","name":"user","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:\/\/44.197.188.197.nip.io"],"url":"https:\/\/grupohoymexico.com\/puebla\/author\/user\/"}]}},"_links":{"self":[{"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/posts\/65240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/comments?post=65240"}],"version-history":[{"count":0,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/posts\/65240\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/media\/65241"}],"wp:attachment":[{"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/media?parent=65240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/categories?post=65240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/tags?post=65240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}