{"id":64700,"date":"2024-01-02T16:45:31","date_gmt":"2024-01-02T22:45:31","guid":{"rendered":"https:\/\/pueblahoy.com.mx\/?p=64700"},"modified":"2024-01-02T16:45:31","modified_gmt":"2024-01-02T22:45:31","slug":"mickey-mouse-del-mundo-de-encantado-al-terror-cinematografico","status":"publish","type":"post","link":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/02\/mickey-mouse-del-mundo-de-encantado-al-terror-cinematografico\/","title":{"rendered":"Mickey Mouse: Del mundo de encantado al terror cinematogr\u00e1fico"},"content":{"rendered":"<p>El ic\u00f3nico personaje de Disney, Mickey Mouse, ha dejado de ser propiedad intelectual de la compa\u00f1\u00eda desde el 1 de enero de 2024, al ingresar al dominio p\u00fablico. Siguiendo los pasos de Winnie the Pooh, quien recientemente protagoniz\u00f3 una pel\u00edcula de terror, ahora Mickey Mouse enfrenta un destino similar, alej\u00e1ndose de su imagen amigable y entra\u00f1able.<\/p>\n<p>La versi\u00f3n de 1928 de Mickey Mouse, conocida por su papel en el corto animado &#8220;Steamboat Willie&#8221;, es la que ha ingresado al dominio p\u00fablico, y este cambio ha dado lugar a dos pel\u00edculas de terror que explorar\u00e1n un lado oscuro y siniestro del querido rat\u00f3n.<\/p>\n<p>La primera pel\u00edcula, dirigida por Steven LaMorte, quien anteriormente trabaj\u00f3 en una versi\u00f3n sangrienta de El Grinch, presenta a Mickey Mouse como un rat\u00f3n s\u00e1dico que aterroriza a los pasajeros de un ferry. La producci\u00f3n comenzar\u00e1 a rodarse en primavera, seg\u00fan informa la revista Variety. LaMorte expres\u00f3 su entusiasmo por explorar el &#8220;potencial para el terror puro y desquiciado&#8221; que se inspira en el personaje de Steamboat Willie.<\/p>\n<p>La segunda pel\u00edcula, titulada &#8220;Mickey\u2019s Mouse Trap&#8221;, ya es una realidad, y su tr\u00e1iler ha sido lanzado recientemente. En esta cinta, un peligroso asesino con una m\u00e1scara de Mickey Mouse y un cuchillo de cocina aterroriza a un grupo de j\u00f3venes en una feria. Aunque a\u00fan no hay una fecha oficial de estreno, se espera que llegue a las salas de cine en marzo de 2024.<\/p>\n<div style=\"width: 842px;\" class=\"wp-video\"><!--[if lt IE 9]><script>document.createElement('video');<\/script><![endif]-->\n<video class=\"wp-video-shortcode\" id=\"video-64700-1\" width=\"842\" height=\"360\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/www.mexicohoy.mx\/wp-content\/uploads\/2024\/01\/ssstwitter.com_1704194128879.mp4?_=1\" \/><a href=\"https:\/\/www.mexicohoy.mx\/wp-content\/uploads\/2024\/01\/ssstwitter.com_1704194128879.mp4\">https:\/\/www.mexicohoy.mx\/wp-content\/uploads\/2024\/01\/ssstwitter.com_1704194128879.mp4<\/a><\/video><\/div>\n<h4>&#8220;MICKEY&#8217;S MOUSE TRAP&#8221;: UN RELATO DE TERROR<\/h4>\n<p>Seg\u00fan Deadline, la pel\u00edcula sigue el &#8220;cumplea\u00f1os n\u00famero 21 de Alex, pero est\u00e1 atrapada en la sala de juegos en un turno de noche, por lo que sus amigos deciden sorprenderla. Un asesino enmascarado vestido como Mickey Mouse decide jugar un juego propio con ellos al que ella debe sobrevivir&#8221;. La fecha de estreno en Estados Unidos est\u00e1 programada para marzo, lo que sugiere que podr\u00eda llegar a las salas de cine mexicanas en abril de este a\u00f1o.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"\" src=\"https:\/\/m.media-amazon.com\/images\/M\/MV5BYzdjZmQ3OWYtZWExNS00NWRlLWE1NGEtMjRlNDY0OGY0MmU0XkEyXkFqcGdeQXVyMTk3OTE2MjY@._V1_.jpg\" alt=\"Mickey's Mouse Trap - IMDb\" width=\"561\" height=\"833\" \/><\/p>\n<h4>MICKEY MOUSE EN EL MUNDO DE LOS VIDEOJUEGOS DE TERROR<\/h4>\n<p>No solo la industria cinematogr\u00e1fica se ha interesado en la versi\u00f3n original de Mickey Mouse; las compa\u00f1\u00edas de videojuegos tambi\u00e9n han aprovechado la oportunidad para explorar nuevas narrativas aterradoras. Un nuevo juego de terror titulado &#8220;Infestation 88&#8221; ha presentado un tr\u00e1iler en el que ratas zombis, lideradas por un enorme Mickey Mouse con la piel carcomida, amenazan con una invasi\u00f3n. Los jugadores deber\u00e1n sobrevivir a la infestaci\u00f3n y enfrentarse al rat\u00f3n mutante en este videojuego espeluznante.<\/p>\n<p><img decoding=\"async\" class=\"alignnone\" src=\"https:\/\/media.vandal.net\/m\/1-2024\/2\/20241210244492_1.jpg\" alt=\"\" width=\"928\" height=\"522\" \/><\/p>\n<p>Hasta el momento, Disney no ha emitido comentarios oficiales sobre ninguno de estos proyectos, pero ha dejado claro que estar\u00e1n vigilantes ante cualquier afiliaci\u00f3n o similitud con su marca y tomar\u00e1n medidas legales en caso necesario.<\/p>\n<p>El mundo parece haberse adentrado en una nueva era para los personajes ic\u00f3nicos de la cultura popular, donde la imaginaci\u00f3n y la creatividad de los creadores llevan a estos personajes a terrenos inexplorados, oscuros y a veces aterradores.<\/p>\n","protected":false},"excerpt":{"rendered":"El ic\u00f3nico personaje de Disney, Mickey Mouse, ha dejado de ser propiedad intelectual de la compa\u00f1\u00eda desde el&hellip;","protected":false},"author":1,"featured_media":64701,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[21],"tags":[],"class_list":{"0":"post-64700","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-espectaculos","8":"cs-entry","9":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.7 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mickey Mouse: Del mundo de encantado al terror cinematogr\u00e1fico - Grupo Hoy Puebla<\/title>\n<meta name=\"description\" content=\"El ic\u00f3nico personaje de Disney, Mickey Mouse, protagonizar\u00e1 una pel\u00edcula de terror, alej\u00e1ndose de su imagen amigable y entra\u00f1able.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/02\/mickey-mouse-del-mundo-de-encantado-al-terror-cinematografico\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mickey Mouse: Del mundo de encantado al terror cinematogr\u00e1fico\" \/>\n<meta property=\"og:description\" content=\"El ic\u00f3nico personaje de Disney, Mickey Mouse, protagonizar\u00e1 una pel\u00edcula de terror, alej\u00e1ndose de su imagen amigable y entra\u00f1able.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/02\/mickey-mouse-del-mundo-de-encantado-al-terror-cinematografico\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo Hoy Puebla\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-02T22:45:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/grupohoymexico.com\/puebla\/wp-content\/uploads\/sites\/3\/2024\/01\/1973-GRUPO-HOY.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/02\\\/mickey-mouse-del-mundo-de-encantado-al-terror-cinematografico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/02\\\/mickey-mouse-del-mundo-de-encantado-al-terror-cinematografico\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/#\\\/schema\\\/person\\\/ce6086ac837852775a3a4f539356c297\"},\"headline\":\"Mickey Mouse: Del mundo de encantado al terror cinematogr\u00e1fico\",\"datePublished\":\"2024-01-02T22:45:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/02\\\/mickey-mouse-del-mundo-de-encantado-al-terror-cinematografico\\\/\"},\"wordCount\":543,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/02\\\/mickey-mouse-del-mundo-de-encantado-al-terror-cinematografico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/01\\\/1973-GRUPO-HOY.jpg\",\"articleSection\":[\"Espect\u00e1culos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/02\\\/mickey-mouse-del-mundo-de-encantado-al-terror-cinematografico\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/02\\\/mickey-mouse-del-mundo-de-encantado-al-terror-cinematografico\\\/\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/02\\\/mickey-mouse-del-mundo-de-encantado-al-terror-cinematografico\\\/\",\"name\":\"Mickey Mouse: Del mundo de encantado al terror cinematogr\u00e1fico - Grupo Hoy Puebla\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/02\\\/mickey-mouse-del-mundo-de-encantado-al-terror-cinematografico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/02\\\/mickey-mouse-del-mundo-de-encantado-al-terror-cinematografico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/01\\\/1973-GRUPO-HOY.jpg\",\"datePublished\":\"2024-01-02T22:45:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/#\\\/schema\\\/person\\\/ce6086ac837852775a3a4f539356c297\"},\"description\":\"El ic\u00f3nico personaje de Disney, Mickey Mouse, protagonizar\u00e1 una pel\u00edcula de terror, alej\u00e1ndose de su imagen amigable y entra\u00f1able.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/02\\\/mickey-mouse-del-mundo-de-encantado-al-terror-cinematografico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/02\\\/mickey-mouse-del-mundo-de-encantado-al-terror-cinematografico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/02\\\/mickey-mouse-del-mundo-de-encantado-al-terror-cinematografico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/01\\\/1973-GRUPO-HOY.jpg\",\"contentUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/01\\\/1973-GRUPO-HOY.jpg\",\"width\":1000,\"height\":600,\"caption\":\"Mickey Mouse: Del mundo de encantado al terror cinematogr\u00e1fico\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/2024\\\/01\\\/02\\\/mickey-mouse-del-mundo-de-encantado-al-terror-cinematografico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mickey Mouse: Del mundo de encantado al terror cinematogr\u00e1fico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/#website\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/\",\"name\":\"Grupo Hoy Puebla\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/#\\\/schema\\\/person\\\/ce6086ac837852775a3a4f539356c297\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\\\/\\\/44.197.188.197.nip.io\"],\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/puebla\\\/author\\\/user\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mickey Mouse: Del mundo de encantado al terror cinematogr\u00e1fico - Grupo Hoy Puebla","description":"El ic\u00f3nico personaje de Disney, Mickey Mouse, protagonizar\u00e1 una pel\u00edcula de terror, alej\u00e1ndose de su imagen amigable y entra\u00f1able.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/02\/mickey-mouse-del-mundo-de-encantado-al-terror-cinematografico\/","og_locale":"es_MX","og_type":"article","og_title":"Mickey Mouse: Del mundo de encantado al terror cinematogr\u00e1fico","og_description":"El ic\u00f3nico personaje de Disney, Mickey Mouse, protagonizar\u00e1 una pel\u00edcula de terror, alej\u00e1ndose de su imagen amigable y entra\u00f1able.","og_url":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/02\/mickey-mouse-del-mundo-de-encantado-al-terror-cinematografico\/","og_site_name":"Grupo Hoy Puebla","article_published_time":"2024-01-02T22:45:31+00:00","og_image":[{"width":1000,"height":600,"url":"https:\/\/grupohoymexico.com\/puebla\/wp-content\/uploads\/sites\/3\/2024\/01\/1973-GRUPO-HOY.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"user","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/02\/mickey-mouse-del-mundo-de-encantado-al-terror-cinematografico\/#article","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/02\/mickey-mouse-del-mundo-de-encantado-al-terror-cinematografico\/"},"author":{"name":"user","@id":"https:\/\/grupohoymexico.com\/puebla\/#\/schema\/person\/ce6086ac837852775a3a4f539356c297"},"headline":"Mickey Mouse: Del mundo de encantado al terror cinematogr\u00e1fico","datePublished":"2024-01-02T22:45:31+00:00","mainEntityOfPage":{"@id":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/02\/mickey-mouse-del-mundo-de-encantado-al-terror-cinematografico\/"},"wordCount":543,"commentCount":0,"image":{"@id":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/02\/mickey-mouse-del-mundo-de-encantado-al-terror-cinematografico\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/puebla\/wp-content\/uploads\/sites\/3\/2024\/01\/1973-GRUPO-HOY.jpg","articleSection":["Espect\u00e1culos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/grupohoymexico.com\/puebla\/2024\/01\/02\/mickey-mouse-del-mundo-de-encantado-al-terror-cinematografico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/02\/mickey-mouse-del-mundo-de-encantado-al-terror-cinematografico\/","url":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/02\/mickey-mouse-del-mundo-de-encantado-al-terror-cinematografico\/","name":"Mickey Mouse: Del mundo de encantado al terror cinematogr\u00e1fico - Grupo Hoy Puebla","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/puebla\/#website"},"primaryImageOfPage":{"@id":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/02\/mickey-mouse-del-mundo-de-encantado-al-terror-cinematografico\/#primaryimage"},"image":{"@id":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/02\/mickey-mouse-del-mundo-de-encantado-al-terror-cinematografico\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/puebla\/wp-content\/uploads\/sites\/3\/2024\/01\/1973-GRUPO-HOY.jpg","datePublished":"2024-01-02T22:45:31+00:00","author":{"@id":"https:\/\/grupohoymexico.com\/puebla\/#\/schema\/person\/ce6086ac837852775a3a4f539356c297"},"description":"El ic\u00f3nico personaje de Disney, Mickey Mouse, protagonizar\u00e1 una pel\u00edcula de terror, alej\u00e1ndose de su imagen amigable y entra\u00f1able.","breadcrumb":{"@id":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/02\/mickey-mouse-del-mundo-de-encantado-al-terror-cinematografico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/grupohoymexico.com\/puebla\/2024\/01\/02\/mickey-mouse-del-mundo-de-encantado-al-terror-cinematografico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/02\/mickey-mouse-del-mundo-de-encantado-al-terror-cinematografico\/#primaryimage","url":"https:\/\/grupohoymexico.com\/puebla\/wp-content\/uploads\/sites\/3\/2024\/01\/1973-GRUPO-HOY.jpg","contentUrl":"https:\/\/grupohoymexico.com\/puebla\/wp-content\/uploads\/sites\/3\/2024\/01\/1973-GRUPO-HOY.jpg","width":1000,"height":600,"caption":"Mickey Mouse: Del mundo de encantado al terror cinematogr\u00e1fico"},{"@type":"BreadcrumbList","@id":"https:\/\/grupohoymexico.com\/puebla\/2024\/01\/02\/mickey-mouse-del-mundo-de-encantado-al-terror-cinematografico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/grupohoymexico.com\/puebla\/"},{"@type":"ListItem","position":2,"name":"Mickey Mouse: Del mundo de encantado al terror cinematogr\u00e1fico"}]},{"@type":"WebSite","@id":"https:\/\/grupohoymexico.com\/puebla\/#website","url":"https:\/\/grupohoymexico.com\/puebla\/","name":"Grupo Hoy Puebla","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/grupohoymexico.com\/puebla\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/grupohoymexico.com\/puebla\/#\/schema\/person\/ce6086ac837852775a3a4f539356c297","name":"user","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:\/\/44.197.188.197.nip.io"],"url":"https:\/\/grupohoymexico.com\/puebla\/author\/user\/"}]}},"_links":{"self":[{"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/posts\/64700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/comments?post=64700"}],"version-history":[{"count":0,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/posts\/64700\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/media\/64701"}],"wp:attachment":[{"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/media?parent=64700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/categories?post=64700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grupohoymexico.com\/puebla\/wp-json\/wp\/v2\/tags?post=64700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}