{"id":35833,"date":"2026-05-08T11:26:48","date_gmt":"2026-05-08T17:26:48","guid":{"rendered":"https:\/\/grupohoymexico.com\/nuevo-leon\/?p=35833"},"modified":"2026-05-08T11:26:48","modified_gmt":"2026-05-08T17:26:48","slug":"la-4t-hunde-la-educacion-en-mexico-con-la-peor-caida-en-matematicas-comprension-lectora-y-ciencias-en-19-anos","status":"publish","type":"post","link":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/08\/la-4t-hunde-la-educacion-en-mexico-con-la-peor-caida-en-matematicas-comprension-lectora-y-ciencias-en-19-anos\/","title":{"rendered":"La 4T hunde la educaci\u00f3n en M\u00e9xico con la peor ca\u00edda en matem\u00e1ticas, comprensi\u00f3n lectora y ciencias en 19 a\u00f1os"},"content":{"rendered":"\n<p>Luego de las maniobras que las autoridades educativas del <strong>gobierno de Claudia Sheinbaum<\/strong> decidieron adelantar un mes el fin del <strong>Ciclo Escolar 2025-2026<\/strong> por el Mundial, el <strong>IMCO <\/strong>record\u00f3 que <strong>M\u00e9xico <\/strong>vivi\u00f3 su peor ca\u00edda en matem\u00e1ticas y otras \u00e1reas bajo el gobierno de la 4T. <\/p>\n\n\n\n<p>Por la tarde del mi\u00e9rcoles 7 de mayo la <strong>SEP<\/strong> acord\u00f3 que se adelantara un mes el fin del ciclo escolar 2025-2026. Es decir que las clases concluyan el <strong>pr\u00f3ximo 5 de junio<\/strong>. La medida se tom\u00f3 ante peticiones, como las de <strong>Clara Brugada<\/strong>, para que los ni\u00f1os no tuvieran clases durante el <strong>Mundial 2026<\/strong> y se redujera el tr\u00e1nsito en la ciudad. <\/p>\n\n\n\n<p><strong>TAMBI\u00c9N LEE:<\/strong> <a href=\"https:\/\/grupohoymexico.com\/2026\/05\/08\/tragedia-en-los-mochis-incendio-en-plaza-fiesta-las-palmas-deja-5-muertos-y-mas-de-30-lesionados\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00a1Tragedia en Los Mochis! Incendio en Plaza Fiesta Las Palmas deja 5 muertos y m\u00e1s de 30 lesionados<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-la-4t-hunde-la-educacion-en-mexico-con-la-peor-caida-en-matematicas-comprension-lectora-y-ciencias-en-19-anos\">La 4T hunde la educaci\u00f3n en M\u00e9xico con la peor ca\u00edda en matem\u00e1ticas, comprensi\u00f3n lectora y ciencias en 19 a\u00f1os<\/h2>\n\n\n\n<p>El IMCO inform\u00f3, de acuerdo con datos de PISA, que la educaci\u00f3n en M\u00e9xico registr\u00f3 una <strong>tendencia a la baja en matem\u00e1ticas, comprensi\u00f3n lectora y ciencias<\/strong>. Si bien en la \u00faltima registr\u00f3 una ligera alza bajo el gobierno de <strong>Enrique Pe\u00f1a Nieto<\/strong>, despu\u00e9s volvi\u00f3 a la baja. En el caso de las primeras dos habilidades formativas, la tendencia a la baja no se recupera y en el caso de las operaciones num\u00e9ricas, se trata de la herramienta que enfrenta la mayor debacle.<\/p>\n\n\n\n<p>Las matem\u00e1ticas son una de las habilidades esenciales para la vida, pero en M\u00e9xico, bajo el gobierno de la 4T, no muestra mejor\u00eda. &#8220;En 2022, M\u00e9xico tuvo una ca\u00edda matem\u00e1ticas, comprensi\u00f3n lectora y ciencias, registrando su peor puntaje desde 2003&#8221;, sostuvo el IMCO.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>&#8220;De \u00faltimo minuto, M\u00e9xico anticip\u00f3 el cierre del #cicloescolar al 5 de junio. M\u00e1s de un mes antes de lo previsto. \u00bfQu\u00e9 impacto tendr\u00e1 en el rezago educativo?&#8221;, cuestion\u00f3 el centro de investigaci\u00f3n apartidista.<\/p>\n<\/blockquote>\n\n\n\n<p><strong>TAMBI\u00c9N LEE:<\/strong> <a href=\"https:\/\/grupohoymexico.com\/2026\/05\/08\/otro-logro-del-army-detienen-a-14-revendedores-de-boletos-en-concierto-de-bts-en-cdmx\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00a1Otro logro del ARMY! Detienen a 14 revendedores de boletos en concierto de BTS en CDMX<\/a><\/p>\n\n\n\n<p>La educaci\u00f3n en M\u00e9xico enfrenta una de las situaciones m\u00e1s complejas por los gobiernos de Andr\u00e9s Manuel L\u00f3pez Obrador y Claudia Sheinbaum. Esto debido a los esc\u00e1ndalos de la SEP bajo las administraciones de <strong>Esteban Moctezuma Barrag\u00e1n<\/strong> (2018-2021), <strong>Delfina G\u00f3mez \u00c1lvarez<\/strong> (2021-2022), <strong>Leticia Ram\u00edrez Amaya<\/strong> (2022-2024) y Mario Delgado (2024-2026). Unos de los m\u00e1s importantes son casos de acoso escolar, pero tambi\u00e9n deficiencias en los materiales educativos, principalmente los <strong>Libros de Texto Gratuitos<\/strong> de la Conaliteg, que presidi\u00f3 <strong>Marx Arriaga<\/strong>.<\/p>\n\n\n\n<p><em>Con informaci\u00f3n de N\u00e9stor Ram\u00edrez Vega<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"Luego de las maniobras que las autoridades educativas del gobierno de Claudia Sheinbaum decidieron adelantar un mes el&hellip;","protected":false},"author":1,"featured_media":35834,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[8],"tags":[1184,251,1669,1674],"class_list":{"0":"post-35833","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nacional","8":"tag-4t","9":"tag-amlo","10":"tag-educacion-en-mexico","11":"tag-imco","12":"cs-entry","13":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.7 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La 4T hunde la educaci\u00f3n en M\u00e9xico con la peor ca\u00edda en matem\u00e1ticas, comprensi\u00f3n lectora y ciencias en 19 a\u00f1os - Grupo Hoy Nuevo Leon<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/08\/la-4t-hunde-la-educacion-en-mexico-con-la-peor-caida-en-matematicas-comprension-lectora-y-ciencias-en-19-anos\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La 4T hunde la educaci\u00f3n en M\u00e9xico con la peor ca\u00edda en matem\u00e1ticas, comprensi\u00f3n lectora y ciencias en 19 a\u00f1os\" \/>\n<meta property=\"og:description\" content=\"Luego de las maniobras que las autoridades educativas del gobierno de Claudia Sheinbaum decidieron adelantar un mes el&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/08\/la-4t-hunde-la-educacion-en-mexico-con-la-peor-caida-en-matematicas-comprension-lectora-y-ciencias-en-19-anos\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo Hoy Nuevo Leon\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-08T17:26:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-content\/uploads\/sites\/6\/2026\/05\/la_4t_hunde_la_educacion_en_mexico_con_la_peor_caida_en_matematicas_y_comprension_lectora_19_anos.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"638\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/08\\\/la-4t-hunde-la-educacion-en-mexico-con-la-peor-caida-en-matematicas-comprension-lectora-y-ciencias-en-19-anos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/08\\\/la-4t-hunde-la-educacion-en-mexico-con-la-peor-caida-en-matematicas-comprension-lectora-y-ciencias-en-19-anos\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/#\\\/schema\\\/person\\\/ce6086ac837852775a3a4f539356c297\"},\"headline\":\"La 4T hunde la educaci\u00f3n en M\u00e9xico con la peor ca\u00edda en matem\u00e1ticas, comprensi\u00f3n lectora y ciencias en 19 a\u00f1os\",\"datePublished\":\"2026-05-08T17:26:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/08\\\/la-4t-hunde-la-educacion-en-mexico-con-la-peor-caida-en-matematicas-comprension-lectora-y-ciencias-en-19-anos\\\/\"},\"wordCount\":474,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/08\\\/la-4t-hunde-la-educacion-en-mexico-con-la-peor-caida-en-matematicas-comprension-lectora-y-ciencias-en-19-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2026\\\/05\\\/la_4t_hunde_la_educacion_en_mexico_con_la_peor_caida_en_matematicas_y_comprension_lectora_19_anos.png\",\"keywords\":[\"4T\",\"Amlo\",\"Educaci\u00f3n en M\u00e9xico\",\"IMCO\"],\"articleSection\":[\"Nacional\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/08\\\/la-4t-hunde-la-educacion-en-mexico-con-la-peor-caida-en-matematicas-comprension-lectora-y-ciencias-en-19-anos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/08\\\/la-4t-hunde-la-educacion-en-mexico-con-la-peor-caida-en-matematicas-comprension-lectora-y-ciencias-en-19-anos\\\/\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/08\\\/la-4t-hunde-la-educacion-en-mexico-con-la-peor-caida-en-matematicas-comprension-lectora-y-ciencias-en-19-anos\\\/\",\"name\":\"La 4T hunde la educaci\u00f3n en M\u00e9xico con la peor ca\u00edda en matem\u00e1ticas, comprensi\u00f3n lectora y ciencias en 19 a\u00f1os - Grupo Hoy Nuevo Leon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/08\\\/la-4t-hunde-la-educacion-en-mexico-con-la-peor-caida-en-matematicas-comprension-lectora-y-ciencias-en-19-anos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/08\\\/la-4t-hunde-la-educacion-en-mexico-con-la-peor-caida-en-matematicas-comprension-lectora-y-ciencias-en-19-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2026\\\/05\\\/la_4t_hunde_la_educacion_en_mexico_con_la_peor_caida_en_matematicas_y_comprension_lectora_19_anos.png\",\"datePublished\":\"2026-05-08T17:26:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/#\\\/schema\\\/person\\\/ce6086ac837852775a3a4f539356c297\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/08\\\/la-4t-hunde-la-educacion-en-mexico-con-la-peor-caida-en-matematicas-comprension-lectora-y-ciencias-en-19-anos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/08\\\/la-4t-hunde-la-educacion-en-mexico-con-la-peor-caida-en-matematicas-comprension-lectora-y-ciencias-en-19-anos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/08\\\/la-4t-hunde-la-educacion-en-mexico-con-la-peor-caida-en-matematicas-comprension-lectora-y-ciencias-en-19-anos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2026\\\/05\\\/la_4t_hunde_la_educacion_en_mexico_con_la_peor_caida_en_matematicas_y_comprension_lectora_19_anos.png\",\"contentUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2026\\\/05\\\/la_4t_hunde_la_educacion_en_mexico_con_la_peor_caida_en_matematicas_y_comprension_lectora_19_anos.png\",\"width\":1200,\"height\":638,\"caption\":\"Foto: Pexels\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/08\\\/la-4t-hunde-la-educacion-en-mexico-con-la-peor-caida-en-matematicas-comprension-lectora-y-ciencias-en-19-anos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La 4T hunde la educaci\u00f3n en M\u00e9xico con la peor ca\u00edda en matem\u00e1ticas, comprensi\u00f3n lectora y ciencias en 19 a\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/#website\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/\",\"name\":\"Grupo Hoy Nuevo Leon\",\"description\":\"Sitio l\u00edder de noticias en M\u00e9xico\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/#\\\/schema\\\/person\\\/ce6086ac837852775a3a4f539356c297\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\\\/\\\/44.197.188.197.nip.io\"],\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/author\\\/user\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La 4T hunde la educaci\u00f3n en M\u00e9xico con la peor ca\u00edda en matem\u00e1ticas, comprensi\u00f3n lectora y ciencias en 19 a\u00f1os - Grupo Hoy Nuevo Leon","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/08\/la-4t-hunde-la-educacion-en-mexico-con-la-peor-caida-en-matematicas-comprension-lectora-y-ciencias-en-19-anos\/","og_locale":"es_MX","og_type":"article","og_title":"La 4T hunde la educaci\u00f3n en M\u00e9xico con la peor ca\u00edda en matem\u00e1ticas, comprensi\u00f3n lectora y ciencias en 19 a\u00f1os","og_description":"Luego de las maniobras que las autoridades educativas del gobierno de Claudia Sheinbaum decidieron adelantar un mes el&hellip;","og_url":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/08\/la-4t-hunde-la-educacion-en-mexico-con-la-peor-caida-en-matematicas-comprension-lectora-y-ciencias-en-19-anos\/","og_site_name":"Grupo Hoy Nuevo Leon","article_published_time":"2026-05-08T17:26:48+00:00","og_image":[{"width":1200,"height":638,"url":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-content\/uploads\/sites\/6\/2026\/05\/la_4t_hunde_la_educacion_en_mexico_con_la_peor_caida_en_matematicas_y_comprension_lectora_19_anos.png","type":"image\/png"}],"author":"user","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"user","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/08\/la-4t-hunde-la-educacion-en-mexico-con-la-peor-caida-en-matematicas-comprension-lectora-y-ciencias-en-19-anos\/#article","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/08\/la-4t-hunde-la-educacion-en-mexico-con-la-peor-caida-en-matematicas-comprension-lectora-y-ciencias-en-19-anos\/"},"author":{"name":"user","@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/#\/schema\/person\/ce6086ac837852775a3a4f539356c297"},"headline":"La 4T hunde la educaci\u00f3n en M\u00e9xico con la peor ca\u00edda en matem\u00e1ticas, comprensi\u00f3n lectora y ciencias en 19 a\u00f1os","datePublished":"2026-05-08T17:26:48+00:00","mainEntityOfPage":{"@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/08\/la-4t-hunde-la-educacion-en-mexico-con-la-peor-caida-en-matematicas-comprension-lectora-y-ciencias-en-19-anos\/"},"wordCount":474,"commentCount":0,"image":{"@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/08\/la-4t-hunde-la-educacion-en-mexico-con-la-peor-caida-en-matematicas-comprension-lectora-y-ciencias-en-19-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-content\/uploads\/sites\/6\/2026\/05\/la_4t_hunde_la_educacion_en_mexico_con_la_peor_caida_en_matematicas_y_comprension_lectora_19_anos.png","keywords":["4T","Amlo","Educaci\u00f3n en M\u00e9xico","IMCO"],"articleSection":["Nacional"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/08\/la-4t-hunde-la-educacion-en-mexico-con-la-peor-caida-en-matematicas-comprension-lectora-y-ciencias-en-19-anos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/08\/la-4t-hunde-la-educacion-en-mexico-con-la-peor-caida-en-matematicas-comprension-lectora-y-ciencias-en-19-anos\/","url":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/08\/la-4t-hunde-la-educacion-en-mexico-con-la-peor-caida-en-matematicas-comprension-lectora-y-ciencias-en-19-anos\/","name":"La 4T hunde la educaci\u00f3n en M\u00e9xico con la peor ca\u00edda en matem\u00e1ticas, comprensi\u00f3n lectora y ciencias en 19 a\u00f1os - Grupo Hoy Nuevo Leon","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/08\/la-4t-hunde-la-educacion-en-mexico-con-la-peor-caida-en-matematicas-comprension-lectora-y-ciencias-en-19-anos\/#primaryimage"},"image":{"@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/08\/la-4t-hunde-la-educacion-en-mexico-con-la-peor-caida-en-matematicas-comprension-lectora-y-ciencias-en-19-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-content\/uploads\/sites\/6\/2026\/05\/la_4t_hunde_la_educacion_en_mexico_con_la_peor_caida_en_matematicas_y_comprension_lectora_19_anos.png","datePublished":"2026-05-08T17:26:48+00:00","author":{"@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/#\/schema\/person\/ce6086ac837852775a3a4f539356c297"},"breadcrumb":{"@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/08\/la-4t-hunde-la-educacion-en-mexico-con-la-peor-caida-en-matematicas-comprension-lectora-y-ciencias-en-19-anos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/08\/la-4t-hunde-la-educacion-en-mexico-con-la-peor-caida-en-matematicas-comprension-lectora-y-ciencias-en-19-anos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/08\/la-4t-hunde-la-educacion-en-mexico-con-la-peor-caida-en-matematicas-comprension-lectora-y-ciencias-en-19-anos\/#primaryimage","url":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-content\/uploads\/sites\/6\/2026\/05\/la_4t_hunde_la_educacion_en_mexico_con_la_peor_caida_en_matematicas_y_comprension_lectora_19_anos.png","contentUrl":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-content\/uploads\/sites\/6\/2026\/05\/la_4t_hunde_la_educacion_en_mexico_con_la_peor_caida_en_matematicas_y_comprension_lectora_19_anos.png","width":1200,"height":638,"caption":"Foto: Pexels"},{"@type":"BreadcrumbList","@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/08\/la-4t-hunde-la-educacion-en-mexico-con-la-peor-caida-en-matematicas-comprension-lectora-y-ciencias-en-19-anos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/grupohoymexico.com\/nuevo-leon\/"},{"@type":"ListItem","position":2,"name":"La 4T hunde la educaci\u00f3n en M\u00e9xico con la peor ca\u00edda en matem\u00e1ticas, comprensi\u00f3n lectora y ciencias en 19 a\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/#website","url":"https:\/\/grupohoymexico.com\/nuevo-leon\/","name":"Grupo Hoy Nuevo Leon","description":"Sitio l\u00edder de noticias en M\u00e9xico","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/grupohoymexico.com\/nuevo-leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/#\/schema\/person\/ce6086ac837852775a3a4f539356c297","name":"user","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:\/\/44.197.188.197.nip.io"],"url":"https:\/\/grupohoymexico.com\/nuevo-leon\/author\/user\/"}]}},"_links":{"self":[{"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/posts\/35833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/comments?post=35833"}],"version-history":[{"count":3,"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/posts\/35833\/revisions"}],"predecessor-version":[{"id":35837,"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/posts\/35833\/revisions\/35837"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/media\/35834"}],"wp:attachment":[{"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/media?parent=35833"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/categories?post=35833"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/tags?post=35833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}