{"id":35824,"date":"2026-05-07T11:52:37","date_gmt":"2026-05-07T17:52:37","guid":{"rendered":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/07\/en-mi-pais-era-conocido-no-por-cosas-malas-chapo-guzman-manda-nueva-carta-a-la-corte-federal-de-brooklyn\/"},"modified":"2026-05-07T11:52:38","modified_gmt":"2026-05-07T17:52:38","slug":"en-mi-pais-era-conocido-no-por-cosas-malas-chapo-guzman-manda-nueva-carta-a-la-corte-federal-de-brooklyn","status":"publish","type":"post","link":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/07\/en-mi-pais-era-conocido-no-por-cosas-malas-chapo-guzman-manda-nueva-carta-a-la-corte-federal-de-brooklyn\/","title":{"rendered":"&#8220;En mi pa\u00eds era conocido, no por cosas malas&#8221;: &#8220;Chapo&#8221; Guzm\u00e1n manda nueva carta a la corte federal de Brooklyn"},"content":{"rendered":"\n<p><strong>Joaqu\u00edn Guzm\u00e1n Loera<\/strong>, conocido mundialmente como <strong>&#8220;El Chapo&#8221;<\/strong>, volvi\u00f3 a comunicarse con la <strong>corte federal de Brooklyn<\/strong>, en <strong>Nueva York<\/strong>, mediante una nueva carta en la que asegur\u00f3 haber sido condenado injustamente por delitos relacionados con narcotr\u00e1fico y delincuencia organizada en <strong>Estados Unidos<\/strong>.<\/p>\n\n\n\n<p>El <strong>exl\u00edder del C\u00e1rtel de Sinaloa<\/strong>, quien cumple una <strong>sentencia de cadena perpetua en una prisi\u00f3n de m\u00e1xima seguridad<\/strong>, afirm\u00f3 en el documento que fue responsabilizado por cr\u00edmenes que, seg\u00fan sostuvo, nunca cometi\u00f3.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><strong><em>&#8220;Me culparon por cosas que no hice, todo por qui\u00e9n soy&#8221;<\/em><\/strong>, expres\u00f3 Guzm\u00e1n Loera en la misiva enviada a las autoridades judiciales estadounidenses.<\/p>\n<\/blockquote>\n\n\n\n<p>La <strong>nueva carta de &#8220;El Chapo&#8221;<\/strong> se suma a una serie de comunicaciones enviadas desde 2019, a\u00f1o en el que fue declarado culpable por <strong>cargos de narcotr\u00e1fico internacional<\/strong>, <strong>lavado de dinero<\/strong>, <strong>delincuencia organizada<\/strong> y <strong>uso ilegal de armas de fuego<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-sigue-nuestras-cuentas-en-facebook-e-instagram-para-mantenerte-informado-con-las-noticias-mas-relevantes\"><strong>Sigue nuestras cuentas en Facebook e Instagram para mantenerte informado con las noticias m\u00e1s relevantes.<\/strong><\/h3>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-no-hice-dano-a-nadie-afirma-el-chapo-guzman\"><strong>&#8220;No hice da\u00f1o a nadie&#8221;, afirma &#8220;El Chapo\u201d&#8221; Guzm\u00e1n<\/strong><\/h2>\n\n\n\n<p>En el escrito redactado en ingl\u00e9s, <strong>Joaqu\u00edn Guzm\u00e1n<\/strong> insisti\u00f3 en que durante su estancia en M\u00e9xico era reconocido por <strong>&#8220;las buenas cosas&#8221; que hizo y neg\u00f3 haber causado da\u00f1o a otras personas<\/strong>.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><strong><em>&#8220;En mi pa\u00eds era conocido no por cosas malas, sino por las cosas buenas que he hecho en M\u00e9xico&#8221;<\/em><\/strong>, afirm\u00f3.<\/p>\n<\/blockquote>\n\n\n\n<p>El capo sinaloense tambi\u00e9n se\u00f1al\u00f3 que la notoriedad p\u00fablica de su figura influy\u00f3 directamente en el resultado del juicio celebrado en la <strong>Corte del Distrito Este de Nueva York<\/strong>, donde finalmente fue sentenciado a cadena perpetua m\u00e1s 30 a\u00f1os adicionales.<\/p>\n\n\n\n<p><strong>Seg\u00fan Guzm\u00e1n Loera<\/strong>, la imagen construida alrededor de su nombre tuvo m\u00e1s peso que las pruebas presentadas por la fiscal\u00eda estadounidense durante el proceso judicial.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-el-chapo-acusa-irregularidades-en-su-juicio-en-brooklyn\"><strong>&#8220;El Chapo&#8221; acusa irregularidades en su juicio en Brooklyn<\/strong><\/h2>\n\n\n\n<p>En la carta, el exl\u00edder criminal cuestion\u00f3 el papel de fiscales estadounidenses y asegur\u00f3 que fue vinculado con una empresa criminal pese a que, seg\u00fan \u00e9l, <strong>&#8220;no ten\u00eda nada que ver con los cr\u00edmenes en Estados Unidos&#8221;<\/strong>.<\/p>\n\n\n\n<p>Asimismo, acus\u00f3 al gobierno mexicano de ser responsable de hechos violentos relacionados con el narcotr\u00e1fico.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><strong><em>&#8220;El gobierno mexicano fue responsable de todos los cr\u00edmenes violentos. Yo no le hice da\u00f1o a nadie&#8221;<\/em><\/strong>, escribi\u00f3.<\/p>\n<\/blockquote>\n\n\n\n<p>Adem\u00e1s, <strong>Guzm\u00e1n Loera<\/strong> afirm\u00f3 que durante el juicio permitieron declaraciones en su contra sin pruebas contundentes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-leer-mas-balacera-en-veracruz-deja-4-muertos-tras-enfrentamiento-entre-policias-y-presuntos-secuestradores\"><strong><em>Leer m\u00e1s: <a href=\"https:\/\/grupohoymexico.com\/2026\/05\/07\/balacera-en-veracruz-deja-4-muertos-tras-enfrentamiento-entre-policias-y-presuntos-secuestradores\/\">Balacera en Veracruz deja 4 muertos tras enfrentamiento entre polic\u00edas y presuntos secuestradores<\/a><\/em><\/strong><\/h3>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-joaquin-guzman-solicita-regresar-a-mexico\"><strong>Joaqu\u00edn Guzm\u00e1n solicita regresar a M\u00e9xico<\/strong><\/h2>\n\n\n\n<p>Uno de los puntos centrales de la carta enviada por <strong>&#8220;El Chapo&#8221;<\/strong> es la petici\u00f3n formal para obtener un nuevo juicio y solicitar su <strong>retorno a M\u00e9xico mediante una cl\u00e1usula de extradici\u00f3n<\/strong>.<\/p>\n\n\n\n<p>El <strong>exl\u00edder del C\u00e1rtel de Sinaloa<\/strong> pidi\u00f3 a las autoridades estadounidenses reconsiderar el veredicto emitido en su contra y revisar las supuestas violaciones a sus derechos durante el proceso penal.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><strong><em>&#8220;Solicito a los tribunales, en mi apelaci\u00f3n, un nuevo juicio y una cl\u00e1usula de extradici\u00f3n de regreso a M\u00e9xico&#8221;<\/em><\/strong>, se\u00f1al\u00f3.<\/p>\n<\/blockquote>\n\n\n\n<p>Tambi\u00e9n agradeci\u00f3 a la corte por recibir su carta y reiter\u00f3 que busca &#8220;equidad&#8221; y una nueva revisi\u00f3n de las pruebas presentadas en el juicio.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-la-condena-de-el-chapo-guzman-en-estados-unidos\"><strong>La condena de &#8220;El Chapo&#8221; Guzm\u00e1n en Estados Unidos<\/strong><\/h2>\n\n\n\n<p><strong>Joaqu\u00edn Guzm\u00e1n Loera fue condenado en 2019<\/strong> por una corte federal de Brooklyn tras uno de los juicios m\u00e1s medi\u00e1ticos en la historia reciente de Estados Unidos.<\/p>\n\n\n\n<p>La fiscal\u00eda estadounidense lo se\u00f1al\u00f3 como l\u00edder del <strong>C\u00e1rtel de Sinaloa<\/strong> y responsable de introducir toneladas de droga a territorio norteamericano durante d\u00e9cadas.<\/p>\n\n\n\n<p>Actualmente, &#8220;El Chapo&#8221; permanece recluido en la prisi\u00f3n ADX Florence, en Colorado, considerada una de las c\u00e1rceles de mayor seguridad en el mundo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-leer-mas-detienen-a-el-tyson-en-sinaloa-presunto-lider-criminal-ligado-a-ataques-armados-en-durango\"><em><strong>Leer m\u00e1s: <a href=\"https:\/\/grupohoymexico.com\/2026\/05\/06\/detienen-a-el-tyson-en-sinaloa-presunto-lider-criminal-ligado-a-ataques-armados-en-durango\/\">Detienen a &#8220;El Tyson&#8221; en Sinaloa, presunto l\u00edder criminal ligado a ataques armados en Durango<\/a><\/strong><\/em><\/h3>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-carta-en-espanol-de-el-chapo\"><strong>Carta en espa\u00f1ol de &#8220;El Chapo&#8221;<\/strong><\/h2>\n\n\n\n<p><em>\u201cMi nombre es Joaqu\u00edn Guzm\u00e1n y estoy luchando contra la condena injusta de los tribunales bajo la suposici\u00f3n de Ray Donovan como fiscal de distrito y Richard Donoghue, quienes estuvieron se\u00f1al\u00e1ndome y culp\u00e1ndome por una empresa criminal, cuando ya estaba establecido que no ten\u00eda nada que ver con los cr\u00edmenes en Estados Unidos. <\/em><\/p>\n\n\n\n<p><em>El gobierno mexicano fue responsable de todos los cr\u00edmenes violentos. Yo no le hice da\u00f1o a nadie. Estos cargos de mi condena, en los que fui testigo de mi propio caso, no tengo idea de por qu\u00e9 el gobierno federal permiti\u00f3 testificar en mi contra sin pruebas. En mi pa\u00eds era conocido no por cosas malas, sino por las cosas buenas que he hecho en M\u00e9xico, como querer que la familia est\u00e9 unida y tener una buena vida. Ante los tribunales del Distrito Este, me culparon por cosas que no hice, todo por qui\u00e9n soy. <\/em><\/p>\n\n\n\n<p><em>Solicito a los tribunales, en mi apelaci\u00f3n, un nuevo juicio y una cl\u00e1usula de extradici\u00f3n de regreso a M\u00e9xico en ambos pa\u00edses, para hacer valer las leyes seg\u00fan mi solicitud y en la violaci\u00f3n de mis derechos extranjeros seg\u00fan la pol\u00edtica de EE. UU. Gracias a los tribunales por aceptar esta carta en mi b\u00fasqueda de equidad para solicitar otro veredicto sobre pruebas que no eran contundentes&#8221;. <\/em><strong>Joaqu\u00edn Guzm\u00e1n.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-unete-a-nuestro-canal-de-whatsapp\"><strong><a href=\"https:\/\/whatsapp.com\/channel\/0029Vaylt1XG3R3gm4Nsgp2m\">\u00danete a nuestro canal de WhatsApp<\/a><\/strong><\/h2>\n","protected":false},"excerpt":{"rendered":"Joaqu\u00edn Guzm\u00e1n Loera, conocido mundialmente como &#8220;El Chapo&#8221;, volvi\u00f3 a comunicarse con la corte federal de Brooklyn, en&hellip;","protected":false},"author":5,"featured_media":35825,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[8],"tags":[1639,1666,32,33,1640,240,21,36],"class_list":{"0":"post-35824","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nacional","8":"tag-brooklyn","9":"tag-carta","10":"tag-el-chapo","11":"tag-estados-unidos","12":"tag-extradicion","13":"tag-joaquin-guzman","14":"tag-mexico","15":"tag-nueva-york","16":"cs-entry","17":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.7 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>&quot;En mi pa\u00eds era conocido, no por cosas malas&quot;: &quot;Chapo&quot; Guzm\u00e1n manda nueva carta a la corte federal de Brooklyn - Grupo Hoy Nuevo Leon<\/title>\n<meta name=\"description\" content=\"Nueva carta de &quot;El Chapo&quot; Guzm\u00e1n a corte Brooklyn: niega narcotr\u00e1fico, acusa irregularidades en juicio y pide regreso a M\u00e9xico.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/07\/en-mi-pais-era-conocido-no-por-cosas-malas-chapo-guzman-manda-nueva-carta-a-la-corte-federal-de-brooklyn\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;En mi pa\u00eds era conocido, no por cosas malas&quot;: &quot;Chapo&quot; Guzm\u00e1n manda nueva carta a la corte federal de Brooklyn\" \/>\n<meta property=\"og:description\" content=\"Nueva carta de &quot;El Chapo&quot; Guzm\u00e1n a corte Brooklyn: niega narcotr\u00e1fico, acusa irregularidades en juicio y pide regreso a M\u00e9xico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/07\/en-mi-pais-era-conocido-no-por-cosas-malas-chapo-guzman-manda-nueva-carta-a-la-corte-federal-de-brooklyn\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo Hoy Nuevo Leon\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-07T17:52:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-07T17:52:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-content\/uploads\/sites\/6\/2026\/05\/El-Chapo-carta.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"638\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jair\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"jair\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/07\\\/en-mi-pais-era-conocido-no-por-cosas-malas-chapo-guzman-manda-nueva-carta-a-la-corte-federal-de-brooklyn\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/07\\\/en-mi-pais-era-conocido-no-por-cosas-malas-chapo-guzman-manda-nueva-carta-a-la-corte-federal-de-brooklyn\\\/\"},\"author\":{\"name\":\"jair\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/#\\\/schema\\\/person\\\/98e2425fe99fbbdf486895b69dab3c3d\"},\"headline\":\"&#8220;En mi pa\u00eds era conocido, no por cosas malas&#8221;: &#8220;Chapo&#8221; Guzm\u00e1n manda nueva carta a la corte federal de Brooklyn\",\"datePublished\":\"2026-05-07T17:52:37+00:00\",\"dateModified\":\"2026-05-07T17:52:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/07\\\/en-mi-pais-era-conocido-no-por-cosas-malas-chapo-guzman-manda-nueva-carta-a-la-corte-federal-de-brooklyn\\\/\"},\"wordCount\":948,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/07\\\/en-mi-pais-era-conocido-no-por-cosas-malas-chapo-guzman-manda-nueva-carta-a-la-corte-federal-de-brooklyn\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2026\\\/05\\\/El-Chapo-carta.jpg\",\"keywords\":[\"Brooklyn\",\"Carta\",\"El Chapo\",\"Estados Unidos\",\"extradici\u00f3n\",\"Joaqu\u00edn Guzm\u00e1n\",\"M\u00e9xico\",\"Nueva York\"],\"articleSection\":[\"Nacional\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/07\\\/en-mi-pais-era-conocido-no-por-cosas-malas-chapo-guzman-manda-nueva-carta-a-la-corte-federal-de-brooklyn\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/07\\\/en-mi-pais-era-conocido-no-por-cosas-malas-chapo-guzman-manda-nueva-carta-a-la-corte-federal-de-brooklyn\\\/\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/07\\\/en-mi-pais-era-conocido-no-por-cosas-malas-chapo-guzman-manda-nueva-carta-a-la-corte-federal-de-brooklyn\\\/\",\"name\":\"\\\"En mi pa\u00eds era conocido, no por cosas malas\\\": \\\"Chapo\\\" Guzm\u00e1n manda nueva carta a la corte federal de Brooklyn - Grupo Hoy Nuevo Leon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/07\\\/en-mi-pais-era-conocido-no-por-cosas-malas-chapo-guzman-manda-nueva-carta-a-la-corte-federal-de-brooklyn\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/07\\\/en-mi-pais-era-conocido-no-por-cosas-malas-chapo-guzman-manda-nueva-carta-a-la-corte-federal-de-brooklyn\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2026\\\/05\\\/El-Chapo-carta.jpg\",\"datePublished\":\"2026-05-07T17:52:37+00:00\",\"dateModified\":\"2026-05-07T17:52:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/#\\\/schema\\\/person\\\/98e2425fe99fbbdf486895b69dab3c3d\"},\"description\":\"Nueva carta de \\\"El Chapo\\\" Guzm\u00e1n a corte Brooklyn: niega narcotr\u00e1fico, acusa irregularidades en juicio y pide regreso a M\u00e9xico.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/07\\\/en-mi-pais-era-conocido-no-por-cosas-malas-chapo-guzman-manda-nueva-carta-a-la-corte-federal-de-brooklyn\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/07\\\/en-mi-pais-era-conocido-no-por-cosas-malas-chapo-guzman-manda-nueva-carta-a-la-corte-federal-de-brooklyn\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/07\\\/en-mi-pais-era-conocido-no-por-cosas-malas-chapo-guzman-manda-nueva-carta-a-la-corte-federal-de-brooklyn\\\/#primaryimage\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2026\\\/05\\\/El-Chapo-carta.jpg\",\"contentUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2026\\\/05\\\/El-Chapo-carta.jpg\",\"width\":1200,\"height\":638,\"caption\":\"Foto: El Chapo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/07\\\/en-mi-pais-era-conocido-no-por-cosas-malas-chapo-guzman-manda-nueva-carta-a-la-corte-federal-de-brooklyn\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;En mi pa\u00eds era conocido, no por cosas malas&#8221;: &#8220;Chapo&#8221; Guzm\u00e1n manda nueva carta a la corte federal de Brooklyn\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/#website\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/\",\"name\":\"Grupo Hoy Nuevo Leon\",\"description\":\"Sitio l\u00edder de noticias en M\u00e9xico\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/#\\\/schema\\\/person\\\/98e2425fe99fbbdf486895b69dab3c3d\",\"name\":\"jair\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ec205dfb8733a1ce1601942dddb04fc9294fb780c832e3c1ec58faa8e4e64e9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ec205dfb8733a1ce1601942dddb04fc9294fb780c832e3c1ec58faa8e4e64e9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ec205dfb8733a1ce1601942dddb04fc9294fb780c832e3c1ec58faa8e4e64e9b?s=96&d=mm&r=g\",\"caption\":\"jair\"},\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/author\\\/jair\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\"En mi pa\u00eds era conocido, no por cosas malas\": \"Chapo\" Guzm\u00e1n manda nueva carta a la corte federal de Brooklyn - Grupo Hoy Nuevo Leon","description":"Nueva carta de \"El Chapo\" Guzm\u00e1n a corte Brooklyn: niega narcotr\u00e1fico, acusa irregularidades en juicio y pide regreso a M\u00e9xico.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/07\/en-mi-pais-era-conocido-no-por-cosas-malas-chapo-guzman-manda-nueva-carta-a-la-corte-federal-de-brooklyn\/","og_locale":"es_MX","og_type":"article","og_title":"\"En mi pa\u00eds era conocido, no por cosas malas\": \"Chapo\" Guzm\u00e1n manda nueva carta a la corte federal de Brooklyn","og_description":"Nueva carta de \"El Chapo\" Guzm\u00e1n a corte Brooklyn: niega narcotr\u00e1fico, acusa irregularidades en juicio y pide regreso a M\u00e9xico.","og_url":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/07\/en-mi-pais-era-conocido-no-por-cosas-malas-chapo-guzman-manda-nueva-carta-a-la-corte-federal-de-brooklyn\/","og_site_name":"Grupo Hoy Nuevo Leon","article_published_time":"2026-05-07T17:52:37+00:00","article_modified_time":"2026-05-07T17:52:38+00:00","og_image":[{"width":1200,"height":638,"url":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-content\/uploads\/sites\/6\/2026\/05\/El-Chapo-carta.jpg","type":"image\/jpeg"}],"author":"jair","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"jair","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/07\/en-mi-pais-era-conocido-no-por-cosas-malas-chapo-guzman-manda-nueva-carta-a-la-corte-federal-de-brooklyn\/#article","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/07\/en-mi-pais-era-conocido-no-por-cosas-malas-chapo-guzman-manda-nueva-carta-a-la-corte-federal-de-brooklyn\/"},"author":{"name":"jair","@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/#\/schema\/person\/98e2425fe99fbbdf486895b69dab3c3d"},"headline":"&#8220;En mi pa\u00eds era conocido, no por cosas malas&#8221;: &#8220;Chapo&#8221; Guzm\u00e1n manda nueva carta a la corte federal de Brooklyn","datePublished":"2026-05-07T17:52:37+00:00","dateModified":"2026-05-07T17:52:38+00:00","mainEntityOfPage":{"@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/07\/en-mi-pais-era-conocido-no-por-cosas-malas-chapo-guzman-manda-nueva-carta-a-la-corte-federal-de-brooklyn\/"},"wordCount":948,"commentCount":0,"image":{"@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/07\/en-mi-pais-era-conocido-no-por-cosas-malas-chapo-guzman-manda-nueva-carta-a-la-corte-federal-de-brooklyn\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-content\/uploads\/sites\/6\/2026\/05\/El-Chapo-carta.jpg","keywords":["Brooklyn","Carta","El Chapo","Estados Unidos","extradici\u00f3n","Joaqu\u00edn Guzm\u00e1n","M\u00e9xico","Nueva York"],"articleSection":["Nacional"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/07\/en-mi-pais-era-conocido-no-por-cosas-malas-chapo-guzman-manda-nueva-carta-a-la-corte-federal-de-brooklyn\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/07\/en-mi-pais-era-conocido-no-por-cosas-malas-chapo-guzman-manda-nueva-carta-a-la-corte-federal-de-brooklyn\/","url":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/07\/en-mi-pais-era-conocido-no-por-cosas-malas-chapo-guzman-manda-nueva-carta-a-la-corte-federal-de-brooklyn\/","name":"\"En mi pa\u00eds era conocido, no por cosas malas\": \"Chapo\" Guzm\u00e1n manda nueva carta a la corte federal de Brooklyn - Grupo Hoy Nuevo Leon","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/07\/en-mi-pais-era-conocido-no-por-cosas-malas-chapo-guzman-manda-nueva-carta-a-la-corte-federal-de-brooklyn\/#primaryimage"},"image":{"@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/07\/en-mi-pais-era-conocido-no-por-cosas-malas-chapo-guzman-manda-nueva-carta-a-la-corte-federal-de-brooklyn\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-content\/uploads\/sites\/6\/2026\/05\/El-Chapo-carta.jpg","datePublished":"2026-05-07T17:52:37+00:00","dateModified":"2026-05-07T17:52:38+00:00","author":{"@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/#\/schema\/person\/98e2425fe99fbbdf486895b69dab3c3d"},"description":"Nueva carta de \"El Chapo\" Guzm\u00e1n a corte Brooklyn: niega narcotr\u00e1fico, acusa irregularidades en juicio y pide regreso a M\u00e9xico.","breadcrumb":{"@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/07\/en-mi-pais-era-conocido-no-por-cosas-malas-chapo-guzman-manda-nueva-carta-a-la-corte-federal-de-brooklyn\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/07\/en-mi-pais-era-conocido-no-por-cosas-malas-chapo-guzman-manda-nueva-carta-a-la-corte-federal-de-brooklyn\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/07\/en-mi-pais-era-conocido-no-por-cosas-malas-chapo-guzman-manda-nueva-carta-a-la-corte-federal-de-brooklyn\/#primaryimage","url":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-content\/uploads\/sites\/6\/2026\/05\/El-Chapo-carta.jpg","contentUrl":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-content\/uploads\/sites\/6\/2026\/05\/El-Chapo-carta.jpg","width":1200,"height":638,"caption":"Foto: El Chapo"},{"@type":"BreadcrumbList","@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/07\/en-mi-pais-era-conocido-no-por-cosas-malas-chapo-guzman-manda-nueva-carta-a-la-corte-federal-de-brooklyn\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/grupohoymexico.com\/nuevo-leon\/"},{"@type":"ListItem","position":2,"name":"&#8220;En mi pa\u00eds era conocido, no por cosas malas&#8221;: &#8220;Chapo&#8221; Guzm\u00e1n manda nueva carta a la corte federal de Brooklyn"}]},{"@type":"WebSite","@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/#website","url":"https:\/\/grupohoymexico.com\/nuevo-leon\/","name":"Grupo Hoy Nuevo Leon","description":"Sitio l\u00edder de noticias en M\u00e9xico","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/grupohoymexico.com\/nuevo-leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/#\/schema\/person\/98e2425fe99fbbdf486895b69dab3c3d","name":"jair","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ec205dfb8733a1ce1601942dddb04fc9294fb780c832e3c1ec58faa8e4e64e9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ec205dfb8733a1ce1601942dddb04fc9294fb780c832e3c1ec58faa8e4e64e9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ec205dfb8733a1ce1601942dddb04fc9294fb780c832e3c1ec58faa8e4e64e9b?s=96&d=mm&r=g","caption":"jair"},"url":"https:\/\/grupohoymexico.com\/nuevo-leon\/author\/jair\/"}]}},"_links":{"self":[{"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/posts\/35824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/comments?post=35824"}],"version-history":[{"count":0,"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/posts\/35824\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/media\/35825"}],"wp:attachment":[{"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/media?parent=35824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/categories?post=35824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/tags?post=35824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}