{"id":35812,"date":"2026-05-06T09:38:29","date_gmt":"2026-05-06T15:38:29","guid":{"rendered":"https:\/\/grupohoymexico.com\/nuevo-leon\/?p=35812"},"modified":"2026-05-06T09:38:29","modified_gmt":"2026-05-06T15:38:29","slug":"enrique-inzunza-le-huye-a-la-camara-alta-pero-deja-a-su-familia-con-cargos-en-el-senado","status":"publish","type":"post","link":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/06\/enrique-inzunza-le-huye-a-la-camara-alta-pero-deja-a-su-familia-con-cargos-en-el-senado\/","title":{"rendered":"Enrique Inzunza le huye a la C\u00e1mara Alta, pero deja a su familia con cargos en el Senado"},"content":{"rendered":"\n<p>Pese a que prometi\u00f3 que estar\u00eda en el <strong>Senado de la Rep\u00fablica<\/strong> en cumplimiento de sus actividades, el morenista <strong>Enrique Inzunza <\/strong>se ech\u00f3 para atr\u00e1s y dijo que no estar\u00e1 en la <strong>C\u00e1mara Alta<\/strong>. Esto luego de las acusaciones de presuntos nexos con el narco que se le hacen, al mismo tiempo que se le revel\u00f3 c\u00f3mo es que meti\u00f3 a su <strong>familia a la n\u00f3mina del gobierno<\/strong>.<\/p>\n\n\n\n<p>Pese a que desde Badiraguato, Sinaloa, prometi\u00f3 el 2 de mayo que iniciar\u00eda los trabajos de la Comisi\u00f3n Permanente este 6 de mayo, a las 9:00 horas de este mi\u00e9rcoles cambi\u00f3 de opini\u00f3n. Dijo que sus valores le imponen comunicar que no estar\u00e1 en la sesi\u00f3n de hoy.<\/p>\n\n\n\n<p><strong>TAMBI\u00c9N LEE:<\/strong> <a href=\"https:\/\/grupohoymexico.com\/2026\/05\/05\/detienen-a-banda-de-peruanos-por-robo-a-cuentahabiente-en-irapuato-guanajuato\/\" target=\"_blank\" rel=\"noreferrer noopener\">Detienen a banda de peruanos por robo a cuentahabiente en Irapuato, Guanajuato<\/a><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Dijo que la raz\u00f3n es que no le ofrecer\u00e1 &#8220;ocasi\u00f3n a personeros de la derecha conservadora, de que, so pretexto, hagan de la sesi\u00f3n un espect\u00e1culo indigno del recinto parlamentario del Senado, como acostumbran&#8221;.<\/p>\n<\/blockquote>\n\n\n\n<p>Las palabras de <strong>Enrique Inzunza<\/strong> sobre el <strong>Senado de la Rep\u00fablica<\/strong> cobran relevancia, luego que pol\u00edticos de <strong>Morena<\/strong> tambi\u00e9n buscan el colapso de discusiones que les comprometen. Al mismo tiempo caen en agresiones y otras acciones de menosprecio en el recinto legislativo.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>&#8220;Estoy en mi tierra, a ras de suelo y con la frente en alto, con las y los nuestros: el pueblo de Sinaloa&#8221;, agreg\u00f3.<\/p>\n<\/blockquote>\n\n\n\n<p><strong>TAMBI\u00c9N LEE.<\/strong> <a href=\"https:\/\/grupohoymexico.com\/2026\/05\/05\/diputado-acusa-a-mario-delgado-y-americo-villarreal-de-nexos-con-redes-de-huachicol\/\" target=\"_blank\" rel=\"noreferrer noopener\">Diputado acusa a Mario Delgado y Am\u00e9rico Villarreal de nexos con redes de huachicol<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-enrique-inzunza-le-huye-a-la-camara-alta-pero-deja-a-su-familia-con-cargos-en-el-senado\">Enrique Inzunza le huye a la C\u00e1mara Alta, pero deja a su familia con cargos en el Senado<\/h2>\n\n\n\n<p>El peri\u00f3dico <em>Exc\u00e9lsior<\/em> revel\u00f3 que el senador por Morena no solo enfrenta la pol\u00e9mica por nexos con el <strong>C\u00e1rtel de Sinaloa<\/strong>. Ahora tambi\u00e9n porque coloc\u00f3 a su esposa, tres hermanos, tres sobrinos, una prima, su mam\u00e1 y un hermano dentro de puestos p\u00fablicos.<\/p>\n\n\n\n<p>Incluso su hija trabaja en la Coordinaci\u00f3n de Asesores de la bancada de Morena en el Senado. Todo esto pese a que la estructura de Morena proh\u00edbe el <strong>nepotismo<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"Pese a que prometi\u00f3 que estar\u00eda en el Senado de la Rep\u00fablica en cumplimiento de sus actividades, el&hellip;","protected":false},"author":15,"featured_media":35813,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[8],"tags":[1619,1657,677],"class_list":{"0":"post-35812","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nacional","8":"tag-enrique-inzunza","9":"tag-nepotismo","10":"tag-senado","11":"cs-entry","12":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.7 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Enrique Inzunza le huye a la C\u00e1mara Alta, pero deja a su familia con cargos en el Senado - Grupo Hoy Nuevo Leon<\/title>\n<meta name=\"description\" content=\"Pese a que dijo que asistir\u00eda al Senado, Enrique Inzunza huy\u00f3 de la C\u00e1mara Alta, en medio de esc\u00e1ndalos de nexos con el narco y nepotismo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/06\/enrique-inzunza-le-huye-a-la-camara-alta-pero-deja-a-su-familia-con-cargos-en-el-senado\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Enrique Inzunza le huye a la C\u00e1mara Alta, pero deja a su familia con cargos en el Senado\" \/>\n<meta property=\"og:description\" content=\"Pese a que dijo que asistir\u00eda al Senado, Enrique Inzunza huy\u00f3 de la C\u00e1mara Alta, en medio de esc\u00e1ndalos de nexos con el narco y nepotismo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/06\/enrique-inzunza-le-huye-a-la-camara-alta-pero-deja-a-su-familia-con-cargos-en-el-senado\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo Hoy Nuevo Leon\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-06T15:38:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-content\/uploads\/sites\/6\/2026\/05\/enrique_inzunza_senado_camara_alta_familia_1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"638\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"nestor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"nestor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/06\\\/enrique-inzunza-le-huye-a-la-camara-alta-pero-deja-a-su-familia-con-cargos-en-el-senado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/06\\\/enrique-inzunza-le-huye-a-la-camara-alta-pero-deja-a-su-familia-con-cargos-en-el-senado\\\/\"},\"author\":{\"name\":\"nestor\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/#\\\/schema\\\/person\\\/8201f3fa49669f346d08e15801e0ebc2\"},\"headline\":\"Enrique Inzunza le huye a la C\u00e1mara Alta, pero deja a su familia con cargos en el Senado\",\"datePublished\":\"2026-05-06T15:38:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/06\\\/enrique-inzunza-le-huye-a-la-camara-alta-pero-deja-a-su-familia-con-cargos-en-el-senado\\\/\"},\"wordCount\":382,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/06\\\/enrique-inzunza-le-huye-a-la-camara-alta-pero-deja-a-su-familia-con-cargos-en-el-senado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2026\\\/05\\\/enrique_inzunza_senado_camara_alta_familia_1.webp\",\"keywords\":[\"Enrique Inzunza\",\"Nepotismo\",\"Senado\"],\"articleSection\":[\"Nacional\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/06\\\/enrique-inzunza-le-huye-a-la-camara-alta-pero-deja-a-su-familia-con-cargos-en-el-senado\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/06\\\/enrique-inzunza-le-huye-a-la-camara-alta-pero-deja-a-su-familia-con-cargos-en-el-senado\\\/\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/06\\\/enrique-inzunza-le-huye-a-la-camara-alta-pero-deja-a-su-familia-con-cargos-en-el-senado\\\/\",\"name\":\"Enrique Inzunza le huye a la C\u00e1mara Alta, pero deja a su familia con cargos en el Senado - Grupo Hoy Nuevo Leon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/06\\\/enrique-inzunza-le-huye-a-la-camara-alta-pero-deja-a-su-familia-con-cargos-en-el-senado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/06\\\/enrique-inzunza-le-huye-a-la-camara-alta-pero-deja-a-su-familia-con-cargos-en-el-senado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2026\\\/05\\\/enrique_inzunza_senado_camara_alta_familia_1.webp\",\"datePublished\":\"2026-05-06T15:38:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/#\\\/schema\\\/person\\\/8201f3fa49669f346d08e15801e0ebc2\"},\"description\":\"Pese a que dijo que asistir\u00eda al Senado, Enrique Inzunza huy\u00f3 de la C\u00e1mara Alta, en medio de esc\u00e1ndalos de nexos con el narco y nepotismo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/06\\\/enrique-inzunza-le-huye-a-la-camara-alta-pero-deja-a-su-familia-con-cargos-en-el-senado\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/06\\\/enrique-inzunza-le-huye-a-la-camara-alta-pero-deja-a-su-familia-con-cargos-en-el-senado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/06\\\/enrique-inzunza-le-huye-a-la-camara-alta-pero-deja-a-su-familia-con-cargos-en-el-senado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2026\\\/05\\\/enrique_inzunza_senado_camara_alta_familia_1.webp\",\"contentUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2026\\\/05\\\/enrique_inzunza_senado_camara_alta_familia_1.webp\",\"width\":1200,\"height\":638},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2026\\\/05\\\/06\\\/enrique-inzunza-le-huye-a-la-camara-alta-pero-deja-a-su-familia-con-cargos-en-el-senado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Enrique Inzunza le huye a la C\u00e1mara Alta, pero deja a su familia con cargos en el Senado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/#website\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/\",\"name\":\"Grupo Hoy Nuevo Leon\",\"description\":\"Sitio l\u00edder de noticias en M\u00e9xico\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/#\\\/schema\\\/person\\\/8201f3fa49669f346d08e15801e0ebc2\",\"name\":\"nestor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g\",\"caption\":\"nestor\"},\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/author\\\/nestor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Enrique Inzunza le huye a la C\u00e1mara Alta, pero deja a su familia con cargos en el Senado - Grupo Hoy Nuevo Leon","description":"Pese a que dijo que asistir\u00eda al Senado, Enrique Inzunza huy\u00f3 de la C\u00e1mara Alta, en medio de esc\u00e1ndalos de nexos con el narco y nepotismo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/06\/enrique-inzunza-le-huye-a-la-camara-alta-pero-deja-a-su-familia-con-cargos-en-el-senado\/","og_locale":"es_MX","og_type":"article","og_title":"Enrique Inzunza le huye a la C\u00e1mara Alta, pero deja a su familia con cargos en el Senado","og_description":"Pese a que dijo que asistir\u00eda al Senado, Enrique Inzunza huy\u00f3 de la C\u00e1mara Alta, en medio de esc\u00e1ndalos de nexos con el narco y nepotismo.","og_url":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/06\/enrique-inzunza-le-huye-a-la-camara-alta-pero-deja-a-su-familia-con-cargos-en-el-senado\/","og_site_name":"Grupo Hoy Nuevo Leon","article_published_time":"2026-05-06T15:38:29+00:00","og_image":[{"width":1200,"height":638,"url":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-content\/uploads\/sites\/6\/2026\/05\/enrique_inzunza_senado_camara_alta_familia_1.webp","type":"image\/webp"}],"author":"nestor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"nestor","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/06\/enrique-inzunza-le-huye-a-la-camara-alta-pero-deja-a-su-familia-con-cargos-en-el-senado\/#article","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/06\/enrique-inzunza-le-huye-a-la-camara-alta-pero-deja-a-su-familia-con-cargos-en-el-senado\/"},"author":{"name":"nestor","@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/#\/schema\/person\/8201f3fa49669f346d08e15801e0ebc2"},"headline":"Enrique Inzunza le huye a la C\u00e1mara Alta, pero deja a su familia con cargos en el Senado","datePublished":"2026-05-06T15:38:29+00:00","mainEntityOfPage":{"@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/06\/enrique-inzunza-le-huye-a-la-camara-alta-pero-deja-a-su-familia-con-cargos-en-el-senado\/"},"wordCount":382,"commentCount":0,"image":{"@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/06\/enrique-inzunza-le-huye-a-la-camara-alta-pero-deja-a-su-familia-con-cargos-en-el-senado\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-content\/uploads\/sites\/6\/2026\/05\/enrique_inzunza_senado_camara_alta_familia_1.webp","keywords":["Enrique Inzunza","Nepotismo","Senado"],"articleSection":["Nacional"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/06\/enrique-inzunza-le-huye-a-la-camara-alta-pero-deja-a-su-familia-con-cargos-en-el-senado\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/06\/enrique-inzunza-le-huye-a-la-camara-alta-pero-deja-a-su-familia-con-cargos-en-el-senado\/","url":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/06\/enrique-inzunza-le-huye-a-la-camara-alta-pero-deja-a-su-familia-con-cargos-en-el-senado\/","name":"Enrique Inzunza le huye a la C\u00e1mara Alta, pero deja a su familia con cargos en el Senado - Grupo Hoy Nuevo Leon","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/06\/enrique-inzunza-le-huye-a-la-camara-alta-pero-deja-a-su-familia-con-cargos-en-el-senado\/#primaryimage"},"image":{"@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/06\/enrique-inzunza-le-huye-a-la-camara-alta-pero-deja-a-su-familia-con-cargos-en-el-senado\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-content\/uploads\/sites\/6\/2026\/05\/enrique_inzunza_senado_camara_alta_familia_1.webp","datePublished":"2026-05-06T15:38:29+00:00","author":{"@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/#\/schema\/person\/8201f3fa49669f346d08e15801e0ebc2"},"description":"Pese a que dijo que asistir\u00eda al Senado, Enrique Inzunza huy\u00f3 de la C\u00e1mara Alta, en medio de esc\u00e1ndalos de nexos con el narco y nepotismo.","breadcrumb":{"@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/06\/enrique-inzunza-le-huye-a-la-camara-alta-pero-deja-a-su-familia-con-cargos-en-el-senado\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/06\/enrique-inzunza-le-huye-a-la-camara-alta-pero-deja-a-su-familia-con-cargos-en-el-senado\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/06\/enrique-inzunza-le-huye-a-la-camara-alta-pero-deja-a-su-familia-con-cargos-en-el-senado\/#primaryimage","url":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-content\/uploads\/sites\/6\/2026\/05\/enrique_inzunza_senado_camara_alta_familia_1.webp","contentUrl":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-content\/uploads\/sites\/6\/2026\/05\/enrique_inzunza_senado_camara_alta_familia_1.webp","width":1200,"height":638},{"@type":"BreadcrumbList","@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2026\/05\/06\/enrique-inzunza-le-huye-a-la-camara-alta-pero-deja-a-su-familia-con-cargos-en-el-senado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/grupohoymexico.com\/nuevo-leon\/"},{"@type":"ListItem","position":2,"name":"Enrique Inzunza le huye a la C\u00e1mara Alta, pero deja a su familia con cargos en el Senado"}]},{"@type":"WebSite","@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/#website","url":"https:\/\/grupohoymexico.com\/nuevo-leon\/","name":"Grupo Hoy Nuevo Leon","description":"Sitio l\u00edder de noticias en M\u00e9xico","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/grupohoymexico.com\/nuevo-leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/#\/schema\/person\/8201f3fa49669f346d08e15801e0ebc2","name":"nestor","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6675a6d9279ab1d8e7b7c55956d0013492fdc51e007e555bc58e5e0eac33d094?s=96&d=mm&r=g","caption":"nestor"},"url":"https:\/\/grupohoymexico.com\/nuevo-leon\/author\/nestor\/"}]}},"_links":{"self":[{"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/posts\/35812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/comments?post=35812"}],"version-history":[{"count":1,"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/posts\/35812\/revisions"}],"predecessor-version":[{"id":35814,"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/posts\/35812\/revisions\/35814"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/media\/35813"}],"wp:attachment":[{"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/media?parent=35812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/categories?post=35812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/tags?post=35812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}