{"id":31566,"date":"2025-07-04T22:45:32","date_gmt":"2025-07-04T22:45:32","guid":{"rendered":"https:\/\/grupohoymexico.com\/?p=31566"},"modified":"2025-07-04T22:45:32","modified_gmt":"2025-07-04T22:45:32","slug":"cuando-y-cuales-seran-las-sedes-del-drinky-fest-2025","status":"publish","type":"post","link":"https:\/\/grupohoymexico.com\/nuevo-leon\/2025\/07\/04\/cuando-y-cuales-seran-las-sedes-del-drinky-fest-2025\/","title":{"rendered":"\u00bfCu\u00e1ndo y cu\u00e1les ser\u00e1n las sedes del Drinky Fest 2025?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El <strong>Drinky Fest 2025<\/strong> est\u00e1 listo para reunir a los amantes del teatro, el vino y el caf\u00e9 en una de las fiestas que gana terreno dentro de la <strong>programaci\u00f3n de la CDMX<\/strong>. Este a\u00f1o el encuentro celebra su tercera edici\u00f3n y para ello planea una programaci\u00f3n extensa. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El <strong>festival del teatro en cafeter\u00edas<\/strong>, restaurantes y bares reactiva la econom\u00eda local a trav\u00e9s de varios d\u00edas de actividades. A lo largo de poco m\u00e1s de dos semanas es que el p\u00fablico se podr\u00e1 reunir con algunas propuestas esc\u00e9nicas que ofrecen experiencias \u00fanicas a la ciudadan\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>TAMBI\u00c9N LEE:<\/strong> <a href=\"https:\/\/grupohoymexico.com\/2025\/07\/03\/mubi-fest-2025-no-se-realizara-seguridad-y-finanzas-en-duda\/\" target=\"_blank\" rel=\"noreferrer noopener\">Mubi Fest 2025 no se realizar\u00e1: seguridad y finanzas en duda<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-que-es-el-drinky-fest-2025-cuando-sera-y-en-donde\">\u00bfQu\u00e9 es el Drinky Fest 2025, cu\u00e1ndo ser\u00e1 y en d\u00f3nde?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Este espacio reivindica el car\u00e1cter colectivo, popular y festivo del teatro. La intenci\u00f3n es acerca la escena a donde la vida cotidiana. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Edgar Uscanga<\/strong>, fundador y director del festival, sostuvo que este encuentro naci\u00f3 a partir de la necesidad de llegar el arte esc\u00e9nico a espacios donde las historias se mezclen con la vida cotidiana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>TAMBI\u00c9N LEE:<\/strong> <a href=\"https:\/\/grupohoymexico.com\/2025\/07\/04\/oasis-regresa-a-los-escenarios-este-viernes-tras-16-anos-de-ausencia\/\" target=\"_blank\" rel=\"noreferrer noopener\">Oasis regresa este viernes a los escenarios tras 16 a\u00f1os de ausencia<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;\u201cLo que hace \u00fanico al Drinky Fest es que aqu\u00ed el teatro no se ve a lo lejos, se respira a dos metros&#8221;, sostuvo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las sedes del Drinky Fest 2025 ser\u00e1n:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Bejuco Caf\u00e9 Bar \u2013 Madrid 13, colonia Del Carmen, Coyoac\u00e1n<\/li>\n\n\n\n<li>Nola Jazz \u2013 Centenario 49, colonia Del Carmen, Coyoac\u00e1n<\/li>\n\n\n\n<li>El 33 \u2013 Pensilvania 266, colonia N\u00e1poles, Benito Ju\u00e1rez<\/li>\n\n\n\n<li>\u00c1gora Caf\u00e9 \u2013 Acapulco 13B, colonia Roma Norte, Cuauht\u00e9moc<\/li>\n\n\n\n<li>Cocoliche Resto-Bar \u2013 Versalles 57B, colonia Ju\u00e1rez, Cuauht\u00e9moc<\/li>\n\n\n\n<li>Centenario 107 \u2013 colonia Del Carmen, Coyoac\u00e1n<\/li>\n\n\n\n<li>El Hijo del Cuervo \u2013 Jard\u00edn Centenario 17, Coyoac\u00e1n<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">El Drinky Fest 2025 contar\u00e1 con un programa compuesto por 32 espect\u00e1culos esc\u00e9nicos. Estos estar\u00e1n disponibles entre el 14 de julio y el 3 de agosto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los boletos est\u00e1n disponibles en preventa desde\u00a0<strong>$150 pesos<\/strong>\u00a0y pueden adquirirse en el <a href=\"http:\/\/www.drinkyfest.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">sitio web oficial del festival<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"El Drinky Fest 2025 est\u00e1 listo para reunir a los amantes del teatro, el vino y el caf\u00e9&hellip;","protected":false},"author":1,"featured_media":31574,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[2],"tags":[106,107,108,109],"class_list":["post-31566","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cdmx","tag-cafeterias-en-cdmx","tag-drinky-fest-2025","tag-teatro","tag-vino","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00bfCu\u00e1ndo y cu\u00e1les ser\u00e1n las sedes del Drinky Fest 2025? - Grupo Hoy Nuevo Leon<\/title>\n<meta name=\"description\" content=\"El Drinky Fest 2025 se aproxima y por ello te compartimos las fechas y las sedes de este encuentro esc\u00e9nico.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/grupohoymexico.com\/nuevo-leon\/2025\/07\/04\/cuando-y-cuales-seran-las-sedes-del-drinky-fest-2025\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfCu\u00e1ndo y cu\u00e1les ser\u00e1n las sedes del Drinky Fest 2025?\" \/>\n<meta property=\"og:description\" content=\"El Drinky Fest 2025 se aproxima y por ello te compartimos las fechas y las sedes de este encuentro esc\u00e9nico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/grupohoymexico.com\/nuevo-leon\/2025\/07\/04\/cuando-y-cuales-seran-las-sedes-del-drinky-fest-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo Hoy Nuevo Leon\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-04T22:45:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-content\/uploads\/sites\/6\/2025\/07\/drinky_fest_2025.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2025\\\/07\\\/04\\\/cuando-y-cuales-seran-las-sedes-del-drinky-fest-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2025\\\/07\\\/04\\\/cuando-y-cuales-seran-las-sedes-del-drinky-fest-2025\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/#\\\/schema\\\/person\\\/ce6086ac837852775a3a4f539356c297\"},\"headline\":\"\u00bfCu\u00e1ndo y cu\u00e1les ser\u00e1n las sedes del Drinky Fest 2025?\",\"datePublished\":\"2025-07-04T22:45:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2025\\\/07\\\/04\\\/cuando-y-cuales-seran-las-sedes-del-drinky-fest-2025\\\/\"},\"wordCount\":349,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2025\\\/07\\\/04\\\/cuando-y-cuales-seran-las-sedes-del-drinky-fest-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/07\\\/drinky_fest_2025.jpg\",\"keywords\":[\"Cafeter\u00edas en CDMX\",\"Drinky Fest 2025\",\"Teatro\",\"Vino\"],\"articleSection\":[\"CDMX\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2025\\\/07\\\/04\\\/cuando-y-cuales-seran-las-sedes-del-drinky-fest-2025\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2025\\\/07\\\/04\\\/cuando-y-cuales-seran-las-sedes-del-drinky-fest-2025\\\/\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2025\\\/07\\\/04\\\/cuando-y-cuales-seran-las-sedes-del-drinky-fest-2025\\\/\",\"name\":\"\u00bfCu\u00e1ndo y cu\u00e1les ser\u00e1n las sedes del Drinky Fest 2025? - Grupo Hoy Nuevo Leon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2025\\\/07\\\/04\\\/cuando-y-cuales-seran-las-sedes-del-drinky-fest-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2025\\\/07\\\/04\\\/cuando-y-cuales-seran-las-sedes-del-drinky-fest-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/07\\\/drinky_fest_2025.jpg\",\"datePublished\":\"2025-07-04T22:45:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/#\\\/schema\\\/person\\\/ce6086ac837852775a3a4f539356c297\"},\"description\":\"El Drinky Fest 2025 se aproxima y por ello te compartimos las fechas y las sedes de este encuentro esc\u00e9nico.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2025\\\/07\\\/04\\\/cuando-y-cuales-seran-las-sedes-del-drinky-fest-2025\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2025\\\/07\\\/04\\\/cuando-y-cuales-seran-las-sedes-del-drinky-fest-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2025\\\/07\\\/04\\\/cuando-y-cuales-seran-las-sedes-del-drinky-fest-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/07\\\/drinky_fest_2025.jpg\",\"contentUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2025\\\/07\\\/drinky_fest_2025.jpg\",\"width\":1280,\"height\":680,\"caption\":\"Las sedes del Drinky Fest 2025 fueron anunciadas. El programa de este a\u00f1o contar\u00e1 con 32 espect\u00e1culos. Foto: Cortes\u00eda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/2025\\\/07\\\/04\\\/cuando-y-cuales-seran-las-sedes-del-drinky-fest-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfCu\u00e1ndo y cu\u00e1les ser\u00e1n las sedes del Drinky Fest 2025?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/#website\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/\",\"name\":\"Grupo Hoy Nuevo Leon\",\"description\":\"Sitio l\u00edder de noticias en M\u00e9xico\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/#\\\/schema\\\/person\\\/ce6086ac837852775a3a4f539356c297\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\\\/\\\/44.197.188.197.nip.io\"],\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/nuevo-leon\\\/author\\\/user\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00bfCu\u00e1ndo y cu\u00e1les ser\u00e1n las sedes del Drinky Fest 2025? - Grupo Hoy Nuevo Leon","description":"El Drinky Fest 2025 se aproxima y por ello te compartimos las fechas y las sedes de este encuentro esc\u00e9nico.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/grupohoymexico.com\/nuevo-leon\/2025\/07\/04\/cuando-y-cuales-seran-las-sedes-del-drinky-fest-2025\/","og_locale":"es_MX","og_type":"article","og_title":"\u00bfCu\u00e1ndo y cu\u00e1les ser\u00e1n las sedes del Drinky Fest 2025?","og_description":"El Drinky Fest 2025 se aproxima y por ello te compartimos las fechas y las sedes de este encuentro esc\u00e9nico.","og_url":"https:\/\/grupohoymexico.com\/nuevo-leon\/2025\/07\/04\/cuando-y-cuales-seran-las-sedes-del-drinky-fest-2025\/","og_site_name":"Grupo Hoy Nuevo Leon","article_published_time":"2025-07-04T22:45:32+00:00","og_image":[{"width":1280,"height":680,"url":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-content\/uploads\/sites\/6\/2025\/07\/drinky_fest_2025.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"user","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2025\/07\/04\/cuando-y-cuales-seran-las-sedes-del-drinky-fest-2025\/#article","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2025\/07\/04\/cuando-y-cuales-seran-las-sedes-del-drinky-fest-2025\/"},"author":{"name":"user","@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/#\/schema\/person\/ce6086ac837852775a3a4f539356c297"},"headline":"\u00bfCu\u00e1ndo y cu\u00e1les ser\u00e1n las sedes del Drinky Fest 2025?","datePublished":"2025-07-04T22:45:32+00:00","mainEntityOfPage":{"@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2025\/07\/04\/cuando-y-cuales-seran-las-sedes-del-drinky-fest-2025\/"},"wordCount":349,"commentCount":0,"image":{"@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2025\/07\/04\/cuando-y-cuales-seran-las-sedes-del-drinky-fest-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-content\/uploads\/sites\/6\/2025\/07\/drinky_fest_2025.jpg","keywords":["Cafeter\u00edas en CDMX","Drinky Fest 2025","Teatro","Vino"],"articleSection":["CDMX"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/grupohoymexico.com\/nuevo-leon\/2025\/07\/04\/cuando-y-cuales-seran-las-sedes-del-drinky-fest-2025\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2025\/07\/04\/cuando-y-cuales-seran-las-sedes-del-drinky-fest-2025\/","url":"https:\/\/grupohoymexico.com\/nuevo-leon\/2025\/07\/04\/cuando-y-cuales-seran-las-sedes-del-drinky-fest-2025\/","name":"\u00bfCu\u00e1ndo y cu\u00e1les ser\u00e1n las sedes del Drinky Fest 2025? - Grupo Hoy Nuevo Leon","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/#website"},"primaryImageOfPage":{"@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2025\/07\/04\/cuando-y-cuales-seran-las-sedes-del-drinky-fest-2025\/#primaryimage"},"image":{"@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2025\/07\/04\/cuando-y-cuales-seran-las-sedes-del-drinky-fest-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-content\/uploads\/sites\/6\/2025\/07\/drinky_fest_2025.jpg","datePublished":"2025-07-04T22:45:32+00:00","author":{"@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/#\/schema\/person\/ce6086ac837852775a3a4f539356c297"},"description":"El Drinky Fest 2025 se aproxima y por ello te compartimos las fechas y las sedes de este encuentro esc\u00e9nico.","breadcrumb":{"@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2025\/07\/04\/cuando-y-cuales-seran-las-sedes-del-drinky-fest-2025\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/grupohoymexico.com\/nuevo-leon\/2025\/07\/04\/cuando-y-cuales-seran-las-sedes-del-drinky-fest-2025\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2025\/07\/04\/cuando-y-cuales-seran-las-sedes-del-drinky-fest-2025\/#primaryimage","url":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-content\/uploads\/sites\/6\/2025\/07\/drinky_fest_2025.jpg","contentUrl":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-content\/uploads\/sites\/6\/2025\/07\/drinky_fest_2025.jpg","width":1280,"height":680,"caption":"Las sedes del Drinky Fest 2025 fueron anunciadas. El programa de este a\u00f1o contar\u00e1 con 32 espect\u00e1culos. Foto: Cortes\u00eda"},{"@type":"BreadcrumbList","@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/2025\/07\/04\/cuando-y-cuales-seran-las-sedes-del-drinky-fest-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/grupohoymexico.com\/nuevo-leon\/"},{"@type":"ListItem","position":2,"name":"\u00bfCu\u00e1ndo y cu\u00e1les ser\u00e1n las sedes del Drinky Fest 2025?"}]},{"@type":"WebSite","@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/#website","url":"https:\/\/grupohoymexico.com\/nuevo-leon\/","name":"Grupo Hoy Nuevo Leon","description":"Sitio l\u00edder de noticias en M\u00e9xico","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/grupohoymexico.com\/nuevo-leon\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/grupohoymexico.com\/nuevo-leon\/#\/schema\/person\/ce6086ac837852775a3a4f539356c297","name":"user","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/25f78de4fa956f6f7c01f8d96f8087d8958ebe06d57e630cd54e36aefb9dacea?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:\/\/44.197.188.197.nip.io"],"url":"https:\/\/grupohoymexico.com\/nuevo-leon\/author\/user\/"}]}},"_links":{"self":[{"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/posts\/31566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/comments?post=31566"}],"version-history":[{"count":0,"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/posts\/31566\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/media\/31574"}],"wp:attachment":[{"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/media?parent=31566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/categories?post=31566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grupohoymexico.com\/nuevo-leon\/wp-json\/wp\/v2\/tags?post=31566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}