{"id":582,"date":"2024-11-13T03:44:21","date_gmt":"2024-11-13T03:44:21","guid":{"rendered":"https:\/\/100.25.185.217\/?p=582"},"modified":"2024-11-13T03:44:22","modified_gmt":"2024-11-13T03:44:22","slug":"crece-a-205-personas-sin-vida-en-valencia-tras-las-severas-inundaciones","status":"publish","type":"post","link":"https:\/\/grupohoymexico.com\/hidalgo\/internacional\/crece-a-205-personas-sin-vida-en-valencia-tras-las-severas-inundaciones\/","title":{"rendered":"Crece a 205 personas sin vida en Valencia tras las severas inundaciones"},"content":{"rendered":"\n<p>Tres d\u00edas despu\u00e9s de las devastadoras inundaciones que azotaron el sur de Valencia, la regi\u00f3n sigue sumida en el caos. Las inundaciones repentinas, provocadas por lluvias torrenciales que cayeron el martes y mi\u00e9rcoles, han dejado al menos 205 personas fallecidas, 202 de ellas en Valencia. Las autoridades de emergencia contin\u00faan elevando el n\u00famero de v\u00edctimas, mientras que muchas calles permanecen bloqueadas por veh\u00edculos y escombros, dejando a numerosos residentes atrapados en sus hogares sin electricidad, agua corriente o telefon\u00eda estable.<\/p>\n\n\n\n<p>La magnitud de los da\u00f1os recuerda los efectos de un tsunami, con calles, hogares y negocios convertidos en escombros. En localidades como Masanasa y Chiva, donde el impacto ha sido devastador, los habitantes se encuentran en una situaci\u00f3n l\u00edmite.&nbsp;<em><strong>\u201cLa situaci\u00f3n es incre\u00edble. Mucho desastre y muy poca ayuda\u201d, comenta Emilio Cuartero, vecino de Masanasa. \u201cNecesitamos maquinaria, gr\u00faas, para que se pueda acceder a los sitios. Necesitamos mucha ayuda. Y pan y agua\u201d<\/strong><\/em>.<\/p>\n\n\n\n<p>En Chiva, la alcaldesa Amparo Fort relata la destrucci\u00f3n:&nbsp;<strong>\u201cHan desaparecido casas enteras, no sabemos si con gente o no dentro\u201d<\/strong>. Los residentes trabajan incansablemente removiendo escombros, limpiando calles llenas de lodo y recuperando lo que queda de sus vidas. La lluvia acumulada el martes fue mayor que la recibida en los \u00faltimos 20 meses, causando el desbordamiento de acequias que atraviesan la ciudad y arrasando con carreteras y muros de viviendas.<\/p>\n\n\n\n<p>\u200b<\/p>\n\n\n\n<p><strong>Solidaridad y desesperaci\u00f3n<\/strong><\/p>\n\n\n\n<p>A pesar de la gravedad de la situaci\u00f3n, la cat\u00e1strofe ha desencadenado una ola de solidaridad. En Paiporta y Catarroja, donde tambi\u00e9n se reportaron numerosas muertes, los vecinos caminan kil\u00f3metros para conseguir provisiones en Valencia, mientras otros residentes de \u00e1reas no afectadas llevan agua y productos b\u00e1sicos para ayudar en la limpieza. Sin embargo, la llegada de voluntarios ha generado congesti\u00f3n en las carreteras, complicando el trabajo de los servicios de emergencia. Las autoridades han solicitado que los voluntarios no conduzcan hasta las zonas afectadas y, en cambio, conf\u00eden en la distribuci\u00f3n de ayuda a cargo de Cruz Roja y los ayuntamientos locales.<\/p>\n\n\n\n<p>En el pueblo de Alfafar, una de las zonas m\u00e1s afectadas, la situaci\u00f3n es cr\u00edtica. La residente de Alfafar expres\u00f3 en TVE:&nbsp;<em><strong>\u201cEsto es un desastre. Hay much\u00edsima gente mayor que no tiene medicamentos. Hay ni\u00f1os que no tienen potitos. No tenemos leche, no tenemos agua. No tenemos acceso a nada\u201d<\/strong><\/em>. El alcalde de Alfafar, Juan Ram\u00f3n Adsuara, advirti\u00f3 que los recursos se est\u00e1n agotando r\u00e1pidamente:&nbsp;<em><strong>\u201cHay gente conviviendo con cad\u00e1veres en casa, eso es muy triste&#8230; Aqu\u00ed estamos totalmente olvidados\u201d<\/strong><\/em>.<\/p>\n\n\n\n<p>\u200b<\/p>\n\n\n\n<p><strong>P\u00e9rdidas y saqueos<\/strong><\/p>\n\n\n\n<p>El torrente de agua convirti\u00f3 las calles estrechas en trampas mortales, llev\u00e1ndose hogares y negocios, muchos de los cuales quedaron inhabitables. En medio del caos, se han registrado saqueos en tiendas, lo que llev\u00f3 a las autoridades a arrestar a 50 personas. Las im\u00e1genes previas y posteriores al desastre muestran una Valencia sumergida en aguas turbias, con la autopista V-33 cubierta de lodo, transformando el paisaje de la ciudad mediterr\u00e1nea en una zona de desastre.<\/p>\n\n\n\n<p>La inundaci\u00f3n repentina en Valencia, considerada la m\u00e1s grave en la memoria reciente, ha sido vinculada al cambio clim\u00e1tico. Un an\u00e1lisis parcial de World Weather Attribution, un grupo de cient\u00edficos internacionales, sugiere que el cambio clim\u00e1tico ha duplicado la probabilidad de una tormenta de esta magnitud. Espa\u00f1a ha experimentado una sequ\u00eda de casi dos a\u00f1os que endureci\u00f3 el suelo, reduciendo su capacidad de absorber el agua, agravando as\u00ed las inundaciones. A lo largo de la costa mediterr\u00e1nea, acostumbrada a tormentas de oto\u00f1o, el calentamiento del mar y el aumento de temperaturas han exacerbado los eventos clim\u00e1ticos extremos.<\/p>\n\n\n\n<p>\u200b<\/p>\n\n\n\n<p><strong>La esperanza en la solidaridad<\/strong><\/p>\n\n\n\n<p>Las redes sociales se han convertido en una herramienta vital para canalizar las necesidades de los afectados. Iniciativas como&nbsp;<em>Suport Mutu<\/em>&nbsp;han conectado a los solicitantes de ayuda con voluntarios dispuestos a contribuir, mientras se han organizado colectas de productos b\u00e1sicos y recaudaciones de fondos en toda Espa\u00f1a. Aunque la tragedia ha dejado una huella profunda en Valencia, la respuesta de la comunidad muestra una resiliencia y solidaridad inquebrantables.<\/p>\n\n\n\n<p>Las autoridades meteorol\u00f3gicas advirtieron que se esperan m\u00e1s lluvias en los pr\u00f3ximos d\u00edas en Tarragona, Catalu\u00f1a, y parte de las Islas Baleares. Mientras tanto, los residentes y voluntarios enfrentan una labor tit\u00e1nica para despejar el barro que ha cubierto sus hogares y calles, manteniendo la esperanza de reconstruir lo que queda de sus vidas.<\/p>\n","protected":false},"excerpt":{"rendered":"Tres d\u00edas despu\u00e9s de las devastadoras inundaciones que azotaron el sur de Valencia, la regi\u00f3n sigue sumida en&hellip;","protected":false},"author":34,"featured_media":583,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[176],"tags":[],"class_list":{"0":"post-582","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-internacional","8":"cs-entry","9":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.7 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Crece a 205 personas sin vida en Valencia tras las severas inundaciones - Hidalgo Hoy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/grupohoymexico.com\/hidalgo\/internacional\/crece-a-205-personas-sin-vida-en-valencia-tras-las-severas-inundaciones\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Crece a 205 personas sin vida en Valencia tras las severas inundaciones\" \/>\n<meta property=\"og:description\" content=\"Tres d\u00edas despu\u00e9s de las devastadoras inundaciones que azotaron el sur de Valencia, la regi\u00f3n sigue sumida en&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/grupohoymexico.com\/hidalgo\/internacional\/crece-a-205-personas-sin-vida-en-valencia-tras-las-severas-inundaciones\/\" \/>\n<meta property=\"og:site_name\" content=\"Hidalgo Hoy\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-13T03:44:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-13T03:44:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/grupohoymexico.com\/hidalgo\/wp-content\/uploads\/sites\/5\/2024\/11\/post-2024-11-01-15-02-04-e73e97b6-c70d-4fbb-abe7-fa77e4c80e95.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1201\" \/>\n\t<meta property=\"og:image:height\" content=\"629\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n Grupo Hoy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n Grupo Hoy\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/internacional\\\/crece-a-205-personas-sin-vida-en-valencia-tras-las-severas-inundaciones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/internacional\\\/crece-a-205-personas-sin-vida-en-valencia-tras-las-severas-inundaciones\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n Grupo Hoy\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/#\\\/schema\\\/person\\\/bc870cc34e948548ddb62cf78ef8474b\"},\"headline\":\"Crece a 205 personas sin vida en Valencia tras las severas inundaciones\",\"datePublished\":\"2024-11-13T03:44:21+00:00\",\"dateModified\":\"2024-11-13T03:44:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/internacional\\\/crece-a-205-personas-sin-vida-en-valencia-tras-las-severas-inundaciones\\\/\"},\"wordCount\":786,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/internacional\\\/crece-a-205-personas-sin-vida-en-valencia-tras-las-severas-inundaciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/11\\\/post-2024-11-01-15-02-04-e73e97b6-c70d-4fbb-abe7-fa77e4c80e95.jpg\",\"articleSection\":[\"Internacional\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/internacional\\\/crece-a-205-personas-sin-vida-en-valencia-tras-las-severas-inundaciones\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/internacional\\\/crece-a-205-personas-sin-vida-en-valencia-tras-las-severas-inundaciones\\\/\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/internacional\\\/crece-a-205-personas-sin-vida-en-valencia-tras-las-severas-inundaciones\\\/\",\"name\":\"Crece a 205 personas sin vida en Valencia tras las severas inundaciones - Hidalgo Hoy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/internacional\\\/crece-a-205-personas-sin-vida-en-valencia-tras-las-severas-inundaciones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/internacional\\\/crece-a-205-personas-sin-vida-en-valencia-tras-las-severas-inundaciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/11\\\/post-2024-11-01-15-02-04-e73e97b6-c70d-4fbb-abe7-fa77e4c80e95.jpg\",\"datePublished\":\"2024-11-13T03:44:21+00:00\",\"dateModified\":\"2024-11-13T03:44:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/#\\\/schema\\\/person\\\/bc870cc34e948548ddb62cf78ef8474b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/internacional\\\/crece-a-205-personas-sin-vida-en-valencia-tras-las-severas-inundaciones\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/internacional\\\/crece-a-205-personas-sin-vida-en-valencia-tras-las-severas-inundaciones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/internacional\\\/crece-a-205-personas-sin-vida-en-valencia-tras-las-severas-inundaciones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/11\\\/post-2024-11-01-15-02-04-e73e97b6-c70d-4fbb-abe7-fa77e4c80e95.jpg\",\"contentUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/11\\\/post-2024-11-01-15-02-04-e73e97b6-c70d-4fbb-abe7-fa77e4c80e95.jpg\",\"width\":1201,\"height\":629},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/internacional\\\/crece-a-205-personas-sin-vida-en-valencia-tras-las-severas-inundaciones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Crece a 205 personas sin vida en Valencia tras las severas inundaciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/#website\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/\",\"name\":\"Hidalgo Hoy\",\"description\":\"El alma de la noticia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/#\\\/schema\\\/person\\\/bc870cc34e948548ddb62cf78ef8474b\",\"name\":\"Redacci\u00f3n Grupo Hoy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e8a44ae8f1b7592837f8c496178e70e065758a27945df208805f8cf6fdd56893?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e8a44ae8f1b7592837f8c496178e70e065758a27945df208805f8cf6fdd56893?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e8a44ae8f1b7592837f8c496178e70e065758a27945df208805f8cf6fdd56893?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3n Grupo Hoy\"},\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Crece a 205 personas sin vida en Valencia tras las severas inundaciones - Hidalgo Hoy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/grupohoymexico.com\/hidalgo\/internacional\/crece-a-205-personas-sin-vida-en-valencia-tras-las-severas-inundaciones\/","og_locale":"es_MX","og_type":"article","og_title":"Crece a 205 personas sin vida en Valencia tras las severas inundaciones","og_description":"Tres d\u00edas despu\u00e9s de las devastadoras inundaciones que azotaron el sur de Valencia, la regi\u00f3n sigue sumida en&hellip;","og_url":"https:\/\/grupohoymexico.com\/hidalgo\/internacional\/crece-a-205-personas-sin-vida-en-valencia-tras-las-severas-inundaciones\/","og_site_name":"Hidalgo Hoy","article_published_time":"2024-11-13T03:44:21+00:00","article_modified_time":"2024-11-13T03:44:22+00:00","og_image":[{"width":1201,"height":629,"url":"https:\/\/grupohoymexico.com\/hidalgo\/wp-content\/uploads\/sites\/5\/2024\/11\/post-2024-11-01-15-02-04-e73e97b6-c70d-4fbb-abe7-fa77e4c80e95.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n Grupo Hoy","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redacci\u00f3n Grupo Hoy","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/grupohoymexico.com\/hidalgo\/internacional\/crece-a-205-personas-sin-vida-en-valencia-tras-las-severas-inundaciones\/#article","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/hidalgo\/internacional\/crece-a-205-personas-sin-vida-en-valencia-tras-las-severas-inundaciones\/"},"author":{"name":"Redacci\u00f3n Grupo Hoy","@id":"https:\/\/grupohoymexico.com\/hidalgo\/#\/schema\/person\/bc870cc34e948548ddb62cf78ef8474b"},"headline":"Crece a 205 personas sin vida en Valencia tras las severas inundaciones","datePublished":"2024-11-13T03:44:21+00:00","dateModified":"2024-11-13T03:44:22+00:00","mainEntityOfPage":{"@id":"https:\/\/grupohoymexico.com\/hidalgo\/internacional\/crece-a-205-personas-sin-vida-en-valencia-tras-las-severas-inundaciones\/"},"wordCount":786,"commentCount":0,"image":{"@id":"https:\/\/grupohoymexico.com\/hidalgo\/internacional\/crece-a-205-personas-sin-vida-en-valencia-tras-las-severas-inundaciones\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/hidalgo\/wp-content\/uploads\/sites\/5\/2024\/11\/post-2024-11-01-15-02-04-e73e97b6-c70d-4fbb-abe7-fa77e4c80e95.jpg","articleSection":["Internacional"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/grupohoymexico.com\/hidalgo\/internacional\/crece-a-205-personas-sin-vida-en-valencia-tras-las-severas-inundaciones\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/grupohoymexico.com\/hidalgo\/internacional\/crece-a-205-personas-sin-vida-en-valencia-tras-las-severas-inundaciones\/","url":"https:\/\/grupohoymexico.com\/hidalgo\/internacional\/crece-a-205-personas-sin-vida-en-valencia-tras-las-severas-inundaciones\/","name":"Crece a 205 personas sin vida en Valencia tras las severas inundaciones - Hidalgo Hoy","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/hidalgo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/grupohoymexico.com\/hidalgo\/internacional\/crece-a-205-personas-sin-vida-en-valencia-tras-las-severas-inundaciones\/#primaryimage"},"image":{"@id":"https:\/\/grupohoymexico.com\/hidalgo\/internacional\/crece-a-205-personas-sin-vida-en-valencia-tras-las-severas-inundaciones\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/hidalgo\/wp-content\/uploads\/sites\/5\/2024\/11\/post-2024-11-01-15-02-04-e73e97b6-c70d-4fbb-abe7-fa77e4c80e95.jpg","datePublished":"2024-11-13T03:44:21+00:00","dateModified":"2024-11-13T03:44:22+00:00","author":{"@id":"https:\/\/grupohoymexico.com\/hidalgo\/#\/schema\/person\/bc870cc34e948548ddb62cf78ef8474b"},"breadcrumb":{"@id":"https:\/\/grupohoymexico.com\/hidalgo\/internacional\/crece-a-205-personas-sin-vida-en-valencia-tras-las-severas-inundaciones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/grupohoymexico.com\/hidalgo\/internacional\/crece-a-205-personas-sin-vida-en-valencia-tras-las-severas-inundaciones\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/grupohoymexico.com\/hidalgo\/internacional\/crece-a-205-personas-sin-vida-en-valencia-tras-las-severas-inundaciones\/#primaryimage","url":"https:\/\/grupohoymexico.com\/hidalgo\/wp-content\/uploads\/sites\/5\/2024\/11\/post-2024-11-01-15-02-04-e73e97b6-c70d-4fbb-abe7-fa77e4c80e95.jpg","contentUrl":"https:\/\/grupohoymexico.com\/hidalgo\/wp-content\/uploads\/sites\/5\/2024\/11\/post-2024-11-01-15-02-04-e73e97b6-c70d-4fbb-abe7-fa77e4c80e95.jpg","width":1201,"height":629},{"@type":"BreadcrumbList","@id":"https:\/\/grupohoymexico.com\/hidalgo\/internacional\/crece-a-205-personas-sin-vida-en-valencia-tras-las-severas-inundaciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/grupohoymexico.com\/hidalgo\/"},{"@type":"ListItem","position":2,"name":"Crece a 205 personas sin vida en Valencia tras las severas inundaciones"}]},{"@type":"WebSite","@id":"https:\/\/grupohoymexico.com\/hidalgo\/#website","url":"https:\/\/grupohoymexico.com\/hidalgo\/","name":"Hidalgo Hoy","description":"El alma de la noticia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/grupohoymexico.com\/hidalgo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/grupohoymexico.com\/hidalgo\/#\/schema\/person\/bc870cc34e948548ddb62cf78ef8474b","name":"Redacci\u00f3n Grupo Hoy","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e8a44ae8f1b7592837f8c496178e70e065758a27945df208805f8cf6fdd56893?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e8a44ae8f1b7592837f8c496178e70e065758a27945df208805f8cf6fdd56893?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e8a44ae8f1b7592837f8c496178e70e065758a27945df208805f8cf6fdd56893?s=96&d=mm&r=g","caption":"Redacci\u00f3n Grupo Hoy"},"url":"https:\/\/grupohoymexico.com\/hidalgo\/author\/redaccion\/"}]}},"_links":{"self":[{"href":"https:\/\/grupohoymexico.com\/hidalgo\/wp-json\/wp\/v2\/posts\/582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grupohoymexico.com\/hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grupohoymexico.com\/hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/hidalgo\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/hidalgo\/wp-json\/wp\/v2\/comments?post=582"}],"version-history":[{"count":1,"href":"https:\/\/grupohoymexico.com\/hidalgo\/wp-json\/wp\/v2\/posts\/582\/revisions"}],"predecessor-version":[{"id":584,"href":"https:\/\/grupohoymexico.com\/hidalgo\/wp-json\/wp\/v2\/posts\/582\/revisions\/584"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/hidalgo\/wp-json\/wp\/v2\/media\/583"}],"wp:attachment":[{"href":"https:\/\/grupohoymexico.com\/hidalgo\/wp-json\/wp\/v2\/media?parent=582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grupohoymexico.com\/hidalgo\/wp-json\/wp\/v2\/categories?post=582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grupohoymexico.com\/hidalgo\/wp-json\/wp\/v2\/tags?post=582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}