{"id":15448,"date":"2026-05-13T14:31:13","date_gmt":"2026-05-13T20:31:13","guid":{"rendered":"https:\/\/grupohoymexico.com\/hidalgo\/uncategorized\/feminicidio-de-edith-guadalupe-no-estuvo-ligado-a-una-oferta-de-trabajo-falsa-fgj-cdmx\/"},"modified":"2026-05-13T14:31:14","modified_gmt":"2026-05-13T20:31:14","slug":"feminicidio-de-edith-guadalupe-no-estuvo-ligado-a-una-oferta-de-trabajo-falsa-fgj-cdmx","status":"publish","type":"post","link":"https:\/\/grupohoymexico.com\/hidalgo\/nacional\/feminicidio-de-edith-guadalupe-no-estuvo-ligado-a-una-oferta-de-trabajo-falsa-fgj-cdmx\/","title":{"rendered":"Feminicidio de Edith Guadalupe no estuvo ligado a una oferta de trabajo falsa: FGJ-CDMX"},"content":{"rendered":"\n<p>La <strong><a href=\"https:\/\/www.fgjcdmx.gob.mx\/\">Fiscal\u00eda General de Justicia de la Ciudad de M\u00e9xico<\/a><\/strong> revel\u00f3 nuevos avances en la <strong>investigaci\u00f3n del feminicidio de Edith Guadalupe<\/strong>, joven de 21 a\u00f1os que fue hallada sin vida el pasado <strong>15 de abril<\/strong> al interior de un edificio ubicado sobre <strong>Avenida Revoluci\u00f3n<\/strong>, en la <strong>alcald\u00eda Benito Ju\u00e1rez de la CDMX<\/strong>.<\/p>\n\n\n\n<p>La principal novedad del caso es que las <strong>autoridades descartaron que la v\u00edctima acudiera al inmueble por una supuesta oferta laboral o por un caso relacionado con trata de personas<\/strong>, como se manej\u00f3 inicialmente en diversas versiones difundidas en redes sociales y algunos medios de comunicaci\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-sigue-nuestras-cuentas-en-facebook-e-instagram-para-mantenerte-informado-con-las-noticias-mas-relevantes\"><strong>Sigue nuestras cuentas en Facebook e Instagram para mantenerte informado con las noticias m\u00e1s relevantes.<\/strong><\/h3>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-edith-guadalupe-acudio-al-edificio-por-motivos-personales\"><strong>Edith Guadalupe acudi\u00f3 al edificio por motivos personales<\/strong><\/h2>\n\n\n\n<p>Durante el Informe de Seguridad encabezado por la<strong> jefa de Gobierno de la CDMX<\/strong>, <strong>Clara Brugada<\/strong>, la <strong>fiscal capitalina Bertha Alcalde Luj\u00e1n<\/strong> inform\u00f3 que las investigaciones permitieron establecer que <strong>Edith Guadalupe hab\u00eda acordado reunirse con Juan Jes\u00fas \u201cN\u201d<\/strong>, <strong>vigilante del inmueble y principal sospechoso del feminicidio<\/strong>, por motivos estrictamente personales.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><strong><em>\u201cSabemos que hubo un contacto previo, que se quedaron de ver en el edificio por motivos personales, que no est\u00e1 relacionado esto con una entrevista de trabajo ni con un esquema de trata como se manej\u00f3 en distintos medios\u201d<\/em><\/strong>, explic\u00f3 Bertha Alcalde Luj\u00e1n.<\/p>\n<\/blockquote>\n\n\n\n<p>La <strong>fiscal detall\u00f3 que existe evidencia adicional que fortalece la imputaci\u00f3n contra Juan Jes\u00fas \u201cN\u201d<\/strong>, a quien detuvieron el mismo d\u00eda en que se localiz\u00f3 el cuerpo de la joven en la <strong>alcald\u00eda Benito Ju\u00e1rez<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-que-paso-en-el-caso-de-edith-guadalupe\"><strong>\u00bfQu\u00e9 pas\u00f3 en el caso de Edith Guadalupe?<\/strong><\/h2>\n\n\n\n<p>El <strong>feminicidio de Edith Guadalupe<\/strong> caus\u00f3 indignaci\u00f3n en redes sociales y entre colectivos feministas debido a las circunstancias en las que ocurri\u00f3 el crimen.<\/p>\n\n\n\n<p>La <strong>joven fue encontrada sin vida dentro de un inmueble de Avenida Revoluci\u00f3n<\/strong>, una de las vialidades m\u00e1s transitadas de la <strong>Ciudad de M\u00e9xico<\/strong>. Desde entonces, las autoridades iniciaron una carpeta de <strong>investigaci\u00f3n bajo el protocolo de feminicidio<\/strong>.<\/p>\n\n\n\n<p>En los primeros d\u00edas del caso surgieron versiones que apuntaban a que <strong>Edith f<\/strong>ue<strong> al lugar tras recibir una oferta de empleo<\/strong>, e incluso se habl\u00f3 de una posible red de trata; sin embargo, la <strong>Fiscal\u00eda capitalina asegur\u00f3 que dichas l\u00edneas ya se descartaron<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-leer-mas-brote-de-norovirus-en-crucero-en-francia-deja-un-muerto-y-mas-de-1-700-personas-confinadas\"><strong><em>Leer m\u00e1s: <a href=\"https:\/\/grupohoymexico.com\/2026\/05\/13\/brote-de-norovirus-en-crucero-en-francia-deja-un-muerto-y-mas-de-1700-personas-confinadas\/\">Brote de norovirus en crucero en Francia deja un muerto y m\u00e1s de 1,700 personas confinadas<\/a><\/em><\/strong><\/h3>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-familia-pidio-discrecion-en-la-investigacion\"><strong>Familia pidi\u00f3 discreci\u00f3n en la investigaci\u00f3n<\/strong><\/h2>\n\n\n\n<p>Durante su intervenci\u00f3n, la <strong>fiscal de la CDMX<\/strong> tambi\u00e9n se\u00f1al\u00f3 que la familia de <strong>Edith Guadalupe<\/strong> ha solicitado discreci\u00f3n respecto al caso, motivo por el cual las autoridades han limitado algunos detalles p\u00fablicos de la investigaci\u00f3n.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em><strong>\u201cLa familia nos ha pedido mucha discreci\u00f3n en este caso y ellos mismos han hecho p\u00fablica esta petici\u00f3n\u201d<\/strong><\/em>, indic\u00f3 Bertha Alcalde Luj\u00e1n.<\/p>\n<\/blockquote>\n\n\n\n<p>A pesar de ello, las autoridades confirmaron que contin\u00faan reuniendo pruebas para fortalecer el proceso judicial contra el presunto responsable.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Juan Jes\u00fas \u201cN\u201d permanece detenido por el feminicidio<\/strong><\/h2>\n\n\n\n<p>La <strong>Fiscal\u00eda General de Justicia de la Ciudad de M\u00e9xico reiter\u00f3 que Juan Jes\u00fas \u201cN\u201d<\/strong>, identificado como vigilante del edificio donde ocurri\u00f3 el crimen, <strong>permanece detenido y enfrenta cargos por feminicidio<\/strong>.<\/p>\n\n\n\n<p>Las investigaciones contin\u00faan para esclarecer completamente los hechos ocurridos el pasado 15 de abril y determinar las circunstancias exactas en las que ocurri\u00f3 el asesinato de <strong>Edith Guadalupe<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-unete-a-nuestro-canal-de-whatsapp\"><strong><a href=\"https:\/\/whatsapp.com\/channel\/0029Vaylt1XG3R3gm4Nsgp2m\">\u00danete a nuestro canal de WhatsApp<\/a><\/strong><\/h2>\n","protected":false},"excerpt":{"rendered":"La Fiscal\u00eda General de Justicia de la Ciudad de M\u00e9xico revel\u00f3 nuevos avances en la investigaci\u00f3n del feminicidio&hellip;","protected":false},"author":5,"featured_media":15449,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[175,5591],"tags":[1208,5404,623,5596,1842,201],"class_list":{"0":"post-15448","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nacional","8":"category-seguridad","9":"tag-cdmx","10":"tag-edith-guadalupe","11":"tag-feminicidio","12":"tag-fgj-cdmx","13":"tag-justicia","14":"tag-seguridad","15":"cs-entry","16":"cs-video-wrap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.7 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Feminicidio de Edith Guadalupe no estuvo ligado a una oferta de trabajo falsa: FGJ-CDMX - Hidalgo Hoy<\/title>\n<meta name=\"description\" content=\"La Fiscal\u00eda de la Ciudad de M\u00e9xico afirm\u00f3 que el feminicidio de Edith Guadalupe no estuvo ligado a una oferta de trabajo falsa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/grupohoymexico.com\/hidalgo\/nacional\/feminicidio-de-edith-guadalupe-no-estuvo-ligado-a-una-oferta-de-trabajo-falsa-fgj-cdmx\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Feminicidio de Edith Guadalupe no estuvo ligado a una oferta de trabajo falsa: FGJ-CDMX\" \/>\n<meta property=\"og:description\" content=\"La Fiscal\u00eda de la Ciudad de M\u00e9xico afirm\u00f3 que el feminicidio de Edith Guadalupe no estuvo ligado a una oferta de trabajo falsa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/grupohoymexico.com\/hidalgo\/nacional\/feminicidio-de-edith-guadalupe-no-estuvo-ligado-a-una-oferta-de-trabajo-falsa-fgj-cdmx\/\" \/>\n<meta property=\"og:site_name\" content=\"Hidalgo Hoy\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T20:31:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T20:31:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/grupohoymexico.com\/hidalgo\/wp-content\/uploads\/sites\/5\/2026\/05\/feminicidio-de-Edith-Guadalupe.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"638\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jair\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"jair\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/nacional\\\/feminicidio-de-edith-guadalupe-no-estuvo-ligado-a-una-oferta-de-trabajo-falsa-fgj-cdmx\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/nacional\\\/feminicidio-de-edith-guadalupe-no-estuvo-ligado-a-una-oferta-de-trabajo-falsa-fgj-cdmx\\\/\"},\"author\":{\"name\":\"jair\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/#\\\/schema\\\/person\\\/98e2425fe99fbbdf486895b69dab3c3d\"},\"headline\":\"Feminicidio de Edith Guadalupe no estuvo ligado a una oferta de trabajo falsa: FGJ-CDMX\",\"datePublished\":\"2026-05-13T20:31:13+00:00\",\"dateModified\":\"2026-05-13T20:31:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/nacional\\\/feminicidio-de-edith-guadalupe-no-estuvo-ligado-a-una-oferta-de-trabajo-falsa-fgj-cdmx\\\/\"},\"wordCount\":595,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/nacional\\\/feminicidio-de-edith-guadalupe-no-estuvo-ligado-a-una-oferta-de-trabajo-falsa-fgj-cdmx\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/05\\\/feminicidio-de-Edith-Guadalupe.jpg\",\"keywords\":[\"CDMX\",\"Edith Guadalupe\",\"feminicidio\",\"FGJ CDMX\",\"Justicia\",\"Seguridad\"],\"articleSection\":[\"Nacional\",\"Seguridad\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/nacional\\\/feminicidio-de-edith-guadalupe-no-estuvo-ligado-a-una-oferta-de-trabajo-falsa-fgj-cdmx\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/nacional\\\/feminicidio-de-edith-guadalupe-no-estuvo-ligado-a-una-oferta-de-trabajo-falsa-fgj-cdmx\\\/\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/nacional\\\/feminicidio-de-edith-guadalupe-no-estuvo-ligado-a-una-oferta-de-trabajo-falsa-fgj-cdmx\\\/\",\"name\":\"Feminicidio de Edith Guadalupe no estuvo ligado a una oferta de trabajo falsa: FGJ-CDMX - Hidalgo Hoy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/nacional\\\/feminicidio-de-edith-guadalupe-no-estuvo-ligado-a-una-oferta-de-trabajo-falsa-fgj-cdmx\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/nacional\\\/feminicidio-de-edith-guadalupe-no-estuvo-ligado-a-una-oferta-de-trabajo-falsa-fgj-cdmx\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/05\\\/feminicidio-de-Edith-Guadalupe.jpg\",\"datePublished\":\"2026-05-13T20:31:13+00:00\",\"dateModified\":\"2026-05-13T20:31:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/#\\\/schema\\\/person\\\/98e2425fe99fbbdf486895b69dab3c3d\"},\"description\":\"La Fiscal\u00eda de la Ciudad de M\u00e9xico afirm\u00f3 que el feminicidio de Edith Guadalupe no estuvo ligado a una oferta de trabajo falsa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/nacional\\\/feminicidio-de-edith-guadalupe-no-estuvo-ligado-a-una-oferta-de-trabajo-falsa-fgj-cdmx\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/nacional\\\/feminicidio-de-edith-guadalupe-no-estuvo-ligado-a-una-oferta-de-trabajo-falsa-fgj-cdmx\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/nacional\\\/feminicidio-de-edith-guadalupe-no-estuvo-ligado-a-una-oferta-de-trabajo-falsa-fgj-cdmx\\\/#primaryimage\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/05\\\/feminicidio-de-Edith-Guadalupe.jpg\",\"contentUrl\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/05\\\/feminicidio-de-Edith-Guadalupe.jpg\",\"width\":1200,\"height\":638,\"caption\":\"Foto: Grupo Hoy\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/nacional\\\/feminicidio-de-edith-guadalupe-no-estuvo-ligado-a-una-oferta-de-trabajo-falsa-fgj-cdmx\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Feminicidio de Edith Guadalupe no estuvo ligado a una oferta de trabajo falsa: FGJ-CDMX\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/#website\",\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/\",\"name\":\"Hidalgo Hoy\",\"description\":\"El alma de la noticia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/#\\\/schema\\\/person\\\/98e2425fe99fbbdf486895b69dab3c3d\",\"name\":\"jair\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ec205dfb8733a1ce1601942dddb04fc9294fb780c832e3c1ec58faa8e4e64e9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ec205dfb8733a1ce1601942dddb04fc9294fb780c832e3c1ec58faa8e4e64e9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ec205dfb8733a1ce1601942dddb04fc9294fb780c832e3c1ec58faa8e4e64e9b?s=96&d=mm&r=g\",\"caption\":\"jair\"},\"url\":\"https:\\\/\\\/grupohoymexico.com\\\/hidalgo\\\/author\\\/jair\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Feminicidio de Edith Guadalupe no estuvo ligado a una oferta de trabajo falsa: FGJ-CDMX - Hidalgo Hoy","description":"La Fiscal\u00eda de la Ciudad de M\u00e9xico afirm\u00f3 que el feminicidio de Edith Guadalupe no estuvo ligado a una oferta de trabajo falsa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/grupohoymexico.com\/hidalgo\/nacional\/feminicidio-de-edith-guadalupe-no-estuvo-ligado-a-una-oferta-de-trabajo-falsa-fgj-cdmx\/","og_locale":"es_MX","og_type":"article","og_title":"Feminicidio de Edith Guadalupe no estuvo ligado a una oferta de trabajo falsa: FGJ-CDMX","og_description":"La Fiscal\u00eda de la Ciudad de M\u00e9xico afirm\u00f3 que el feminicidio de Edith Guadalupe no estuvo ligado a una oferta de trabajo falsa.","og_url":"https:\/\/grupohoymexico.com\/hidalgo\/nacional\/feminicidio-de-edith-guadalupe-no-estuvo-ligado-a-una-oferta-de-trabajo-falsa-fgj-cdmx\/","og_site_name":"Hidalgo Hoy","article_published_time":"2026-05-13T20:31:13+00:00","article_modified_time":"2026-05-13T20:31:14+00:00","og_image":[{"width":1200,"height":638,"url":"https:\/\/grupohoymexico.com\/hidalgo\/wp-content\/uploads\/sites\/5\/2026\/05\/feminicidio-de-Edith-Guadalupe.jpg","type":"image\/jpeg"}],"author":"jair","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"jair","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/grupohoymexico.com\/hidalgo\/nacional\/feminicidio-de-edith-guadalupe-no-estuvo-ligado-a-una-oferta-de-trabajo-falsa-fgj-cdmx\/#article","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/hidalgo\/nacional\/feminicidio-de-edith-guadalupe-no-estuvo-ligado-a-una-oferta-de-trabajo-falsa-fgj-cdmx\/"},"author":{"name":"jair","@id":"https:\/\/grupohoymexico.com\/hidalgo\/#\/schema\/person\/98e2425fe99fbbdf486895b69dab3c3d"},"headline":"Feminicidio de Edith Guadalupe no estuvo ligado a una oferta de trabajo falsa: FGJ-CDMX","datePublished":"2026-05-13T20:31:13+00:00","dateModified":"2026-05-13T20:31:14+00:00","mainEntityOfPage":{"@id":"https:\/\/grupohoymexico.com\/hidalgo\/nacional\/feminicidio-de-edith-guadalupe-no-estuvo-ligado-a-una-oferta-de-trabajo-falsa-fgj-cdmx\/"},"wordCount":595,"commentCount":0,"image":{"@id":"https:\/\/grupohoymexico.com\/hidalgo\/nacional\/feminicidio-de-edith-guadalupe-no-estuvo-ligado-a-una-oferta-de-trabajo-falsa-fgj-cdmx\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/hidalgo\/wp-content\/uploads\/sites\/5\/2026\/05\/feminicidio-de-Edith-Guadalupe.jpg","keywords":["CDMX","Edith Guadalupe","feminicidio","FGJ CDMX","Justicia","Seguridad"],"articleSection":["Nacional","Seguridad"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/grupohoymexico.com\/hidalgo\/nacional\/feminicidio-de-edith-guadalupe-no-estuvo-ligado-a-una-oferta-de-trabajo-falsa-fgj-cdmx\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/grupohoymexico.com\/hidalgo\/nacional\/feminicidio-de-edith-guadalupe-no-estuvo-ligado-a-una-oferta-de-trabajo-falsa-fgj-cdmx\/","url":"https:\/\/grupohoymexico.com\/hidalgo\/nacional\/feminicidio-de-edith-guadalupe-no-estuvo-ligado-a-una-oferta-de-trabajo-falsa-fgj-cdmx\/","name":"Feminicidio de Edith Guadalupe no estuvo ligado a una oferta de trabajo falsa: FGJ-CDMX - Hidalgo Hoy","isPartOf":{"@id":"https:\/\/grupohoymexico.com\/hidalgo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/grupohoymexico.com\/hidalgo\/nacional\/feminicidio-de-edith-guadalupe-no-estuvo-ligado-a-una-oferta-de-trabajo-falsa-fgj-cdmx\/#primaryimage"},"image":{"@id":"https:\/\/grupohoymexico.com\/hidalgo\/nacional\/feminicidio-de-edith-guadalupe-no-estuvo-ligado-a-una-oferta-de-trabajo-falsa-fgj-cdmx\/#primaryimage"},"thumbnailUrl":"https:\/\/grupohoymexico.com\/hidalgo\/wp-content\/uploads\/sites\/5\/2026\/05\/feminicidio-de-Edith-Guadalupe.jpg","datePublished":"2026-05-13T20:31:13+00:00","dateModified":"2026-05-13T20:31:14+00:00","author":{"@id":"https:\/\/grupohoymexico.com\/hidalgo\/#\/schema\/person\/98e2425fe99fbbdf486895b69dab3c3d"},"description":"La Fiscal\u00eda de la Ciudad de M\u00e9xico afirm\u00f3 que el feminicidio de Edith Guadalupe no estuvo ligado a una oferta de trabajo falsa.","breadcrumb":{"@id":"https:\/\/grupohoymexico.com\/hidalgo\/nacional\/feminicidio-de-edith-guadalupe-no-estuvo-ligado-a-una-oferta-de-trabajo-falsa-fgj-cdmx\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/grupohoymexico.com\/hidalgo\/nacional\/feminicidio-de-edith-guadalupe-no-estuvo-ligado-a-una-oferta-de-trabajo-falsa-fgj-cdmx\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/grupohoymexico.com\/hidalgo\/nacional\/feminicidio-de-edith-guadalupe-no-estuvo-ligado-a-una-oferta-de-trabajo-falsa-fgj-cdmx\/#primaryimage","url":"https:\/\/grupohoymexico.com\/hidalgo\/wp-content\/uploads\/sites\/5\/2026\/05\/feminicidio-de-Edith-Guadalupe.jpg","contentUrl":"https:\/\/grupohoymexico.com\/hidalgo\/wp-content\/uploads\/sites\/5\/2026\/05\/feminicidio-de-Edith-Guadalupe.jpg","width":1200,"height":638,"caption":"Foto: Grupo Hoy"},{"@type":"BreadcrumbList","@id":"https:\/\/grupohoymexico.com\/hidalgo\/nacional\/feminicidio-de-edith-guadalupe-no-estuvo-ligado-a-una-oferta-de-trabajo-falsa-fgj-cdmx\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/grupohoymexico.com\/hidalgo\/"},{"@type":"ListItem","position":2,"name":"Feminicidio de Edith Guadalupe no estuvo ligado a una oferta de trabajo falsa: FGJ-CDMX"}]},{"@type":"WebSite","@id":"https:\/\/grupohoymexico.com\/hidalgo\/#website","url":"https:\/\/grupohoymexico.com\/hidalgo\/","name":"Hidalgo Hoy","description":"El alma de la noticia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/grupohoymexico.com\/hidalgo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/grupohoymexico.com\/hidalgo\/#\/schema\/person\/98e2425fe99fbbdf486895b69dab3c3d","name":"jair","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ec205dfb8733a1ce1601942dddb04fc9294fb780c832e3c1ec58faa8e4e64e9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ec205dfb8733a1ce1601942dddb04fc9294fb780c832e3c1ec58faa8e4e64e9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ec205dfb8733a1ce1601942dddb04fc9294fb780c832e3c1ec58faa8e4e64e9b?s=96&d=mm&r=g","caption":"jair"},"url":"https:\/\/grupohoymexico.com\/hidalgo\/author\/jair\/"}]}},"_links":{"self":[{"href":"https:\/\/grupohoymexico.com\/hidalgo\/wp-json\/wp\/v2\/posts\/15448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/grupohoymexico.com\/hidalgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/grupohoymexico.com\/hidalgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/hidalgo\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/hidalgo\/wp-json\/wp\/v2\/comments?post=15448"}],"version-history":[{"count":0,"href":"https:\/\/grupohoymexico.com\/hidalgo\/wp-json\/wp\/v2\/posts\/15448\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/grupohoymexico.com\/hidalgo\/wp-json\/wp\/v2\/media\/15449"}],"wp:attachment":[{"href":"https:\/\/grupohoymexico.com\/hidalgo\/wp-json\/wp\/v2\/media?parent=15448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/grupohoymexico.com\/hidalgo\/wp-json\/wp\/v2\/categories?post=15448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/grupohoymexico.com\/hidalgo\/wp-json\/wp\/v2\/tags?post=15448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}